{"id":11434,"date":"2018-04-30T16:41:03","date_gmt":"2018-04-30T14:41:03","guid":{"rendered":"https:\/\/leckerekekse.de\/wordpress\/?p=11434"},"modified":"2022-09-12T11:55:27","modified_gmt":"2022-09-12T09:55:27","slug":"literaturbarcamp-in-bonn-2018","status":"publish","type":"post","link":"https:\/\/leckerekekse.de\/wordpress\/literaturbarcamp-in-bonn-2018\/","title":{"rendered":"Literaturbarcamp in Bonn 2018"},"content":{"rendered":"<h2><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-11443\" src=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2018\/04\/Litcamp-Bonn-2018.jpg\" alt=\"Literaturbarcamp Bonn 2018 litcampBN18o\" width=\"640\" height=\"443\" srcset=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2018\/04\/Litcamp-Bonn-2018.jpg 640w, https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2018\/04\/Litcamp-Bonn-2018-300x208.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/h2>\n<h2>#LitcampBN18<\/h2>\n<p>Am 28.04.2018 fand das zweite Literaturbarcamp in Bonn statt. Wieder, wie auch im letzten Jahr, stellte die Volkshochschule Bonn ihre sch\u00f6nen R\u00e4ume daf\u00fcr zur Verf\u00fcgung. Auch das <a href=\"http:\/\/literaturcampnrw.de\/das-team\/\" target=\"_blank\" rel=\"noopener\">Organisationsteam<\/a>, bestehend aus Uschi Fuchs und \u00a0Ute Lange blieb gleich. Auch viele der Teilnehmer waren \u201eWiederholungst\u00e4ter\u201c. Doch war die Veranstaltung nat\u00fcrlich ganz anders als <a href=\"https:\/\/leckerekekse.de\/wordpress\/literatur-barcamp-nrw-in-bonn-veranstaltungsbericht\/\" target=\"_blank\" rel=\"noopener\">die im Vorjahr<\/a>. Warum das <em>nat\u00fcrlich<\/em> ist? Weil zwei Barcamps nie gleich sind.<br \/>\n<!--more--><\/p>\n<h3>Was ist ein Barcamp?<\/h3>\n<p>Aus dem Bekanntenkreis nehme ich mit, dass viele nicht wissen was das \u00fcberhaupt ist, so ein Barcamp. Nein, es ist nicht wieder \u201eso ein Blogger-Ding\u201c. \u00a0Es ist eine dynamische Art eine flexible Veranstaltung zu planen. Der ganze Tagesablauf lebt durch die Teilnehmer. Alle Teilnehmer sind aufgerufen eine eigene Aktion vorzustellen. Diese nennt man Session. Dabei kann es sich um einen Vortrag, eine Diskussionsrunde, offene Fragen oder sonst was handeln. Wenn es zu viele Sessions (in Bezug auf R\u00e4ume und Zeit) gibt, dann entscheidet das Publikum, welche Sessions Vorrang haben. Ich hatte also keine Ahnung, was genau an diesem Tag auf mich zukommt. Der Veranstaltungsname legt zwar eine N\u00e4he der Themen zu Literatur nahe, doch man darf alles anbieten.<\/p>\n<p>Hier ein paar Impressionen vom Tag<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-11442\" src=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2018\/04\/Impressionen-litcampbn18.jpg\" alt=\"Impressionen Literaturbarcamp Bonn, #litcampBN18\" width=\"640\" height=\"443\" srcset=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2018\/04\/Impressionen-litcampbn18.jpg 640w, https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2018\/04\/Impressionen-litcampbn18-300x208.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<h3>Der Beginn<\/h3>\n<p>Irgendwie begann der Tag f\u00fcr mich hektisch, wie oft war ich sp\u00e4t dran. Eigentlich wollte ich au\u00dferhalb von Bonn parken und dann mit der Bahn in die Innenstadt fahren (die VHS im Haus der Bildung liegt wirklich super zentral), doch daf\u00fcr blieb nicht gen\u00fcgend Zeit, wollte ich noch p\u00fcnktlich sein. Doch ich schaffte es. Die Teilnehmer standen noch bei Kaffee und belegten Br\u00f6tchen locker beisammen und mein Stress viel von mir ab. Die Er\u00f6ffnungsveranstaltung war kurzweilig und bestand vor allem aus der Vorstellung von Sponsoren, Teilnehmern und nat\u00fcrlich der Sessionplanung. Die Vorstellung der einzelnen Teilnehmer verlief viel rascher und disziplinierter als letztes Jahr. Name und drei Hashtags wurden benannt. Meine waren:<\/p>\n<p><strong>#B\u00fccher<\/strong><\/p>\n<p><strong>#leckere Kekse<\/strong><\/p>\n<p><strong>#zu wenig Zeit<\/strong><\/p>\n<p>Leider waren auf den vorgedruckten Teilnehmerkarten nur Platz f\u00fcr zwei vorgesehen. Doch auch die zust\u00e4ndige Druckerei geh\u00f6rt zu den Sponsoren und so will ich nicht meckern&#x1f609;. Apropos:<\/p>\n<h3>Sponsoren<\/h3>\n<p>Ohne Sponsoren kein Barcamp. Denn nur so k\u00f6nnen die Eintrittspreise niedrig gehalten werden. Deshalb hebe ich sie an dieser Stelle deutlich hervor. Folgende sind mir bekannt:<\/p>\n<ul>\n<li><a href=\"http:\/\/www.vhs-bonn.de\/\" target=\"_blank\" rel=\"noopener\">Volkshochschule Bonn<\/a><\/li>\n<li><a href=\"http:\/\/www.selfpublisher-verband.de\/\" target=\"_blank\" rel=\"noopener\">Selfpublisher-Verband<\/a><\/li>\n<li><a href=\"https:\/\/bonn.digital\/\" target=\"_blank\" rel=\"noopener\">digital<\/a><\/li>\n<li><a href=\"https:\/\/17ziele.de\/\" target=\"_blank\" rel=\"noopener\">#17Ziele<\/a><\/li>\n<li><a href=\"https:\/\/www.vfll.de\/\" target=\"_blank\" rel=\"noopener\">Verband der Freien Lektorinnen und Lektoren e. V. (VFLL)<\/a><\/li>\n<li>eindrucksvoll<\/li>\n<li>|Text. Lektorat<\/li>\n<li><a href=\"http:\/\/www.trio-medien.de\/\" target=\"_blank\" rel=\"noopener\">Trio<\/a><\/li>\n<li><a href=\"https:\/\/www.epubli.de\/\" target=\"_blank\" rel=\"noopener\">epubli<\/a><\/li>\n<li><a href=\"https:\/\/www.neobooks.com\/\" target=\"_blank\" rel=\"noopener\">neobooks<\/a><\/li>\n<li>Thalia Bonn<\/li>\n<li><a href=\"http:\/\/www.rheinwerk-verlag.de\" target=\"_blank\" rel=\"noopener\">Rheinwerk-Verlag<\/a><\/li>\n<li><a href=\"http:\/\/www.buchhandlung-finden.de\" target=\"_blank\" rel=\"noopener\">Buchmarketing-Kampagne JETZT EIN BUCH!<\/a> (B\u00f6rsenverein des deutschen Buchhandels)<\/li>\n<li><a href=\"http:\/\/www.kuuuk.com\/\" target=\"_blank\" rel=\"noopener\">KUUUK DER VERLAG mit 3 U<\/a><\/li>\n<li>Bonn Greeters<\/li>\n<\/ul>\n<p>Vielen Dank an alle, die dadurch das #LitcampBN18 m\u00f6glich gemacht haben. Sehr sch\u00f6n fand ich, dass von den meisten Sponsoren auch jemand vor Ort war und zu ihren Organisationen gerne Auskunft gaben.<\/p>\n<h3>Sessions<\/h3>\n<p>Dieses Jahr kamen ein paar weniger Sessions zustande als im letzten Jahr. Eigentlich hatte ich mir auch vorgenommen meine Furcht zu \u00fcberwinden und auch etwas anzubieten, doch siehe # Nummer drei. Es gab auch viel mehr Sessions, die sich direkt an Autorinnen und Autoren richtete. Das finde ich gut. Es gibt mir auch einen Einblick in deren Alltag und die Probleme, mit denen sie sich rumschlagen. Reine Bloggerthemen waren eher rar ges\u00e4t. So gab es viel Platz f\u00fcr Themen, die sich aus de Blogger-Veranstaltungen herausheben. Ich muss unbedingt auch mal ein anderes Barcamp besuchen, es gibt sogar welche, die ganz ohne Themenvorgabe auskommen. Das sind sicher sehr \u00fcberraschende Tage. \u00a0Es gab sieben parallele Sessions und insgesamt vier Sessions-Time-Slots. Ich besuchte insgesamt vier Einzelveranstaltungen<\/p>\n<h3>Ukulele<\/h3>\n<p>Wie oben schon gesagt, kannst du auch auf einem Literaturbarcamp eine Session zu einem Thema anbieten, das nix mit Literatur zu tun hat. Zum Beispiel einen Crashkurs im Ukulelespielen.<\/p>\n<p>Das machte Riesen-Spa\u00df. Es standen \u00fcber 20 Instrumente zur Verf\u00fcgung, wir lernten ein paar wenige Griffe und los ging es. Singen geh\u00f6rt nat\u00fcrlich auch dazu.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-11438\" src=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2018\/04\/ukulele-worskhop-litcampbn18.jpg\" alt=\"Ukulele Workshop LitCampBN18\" width=\"640\" height=\"429\" srcset=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2018\/04\/ukulele-worskhop-litcampbn18.jpg 640w, https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2018\/04\/ukulele-worskhop-litcampbn18-300x201.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<p>Hast du auch Lust diese viersaitige- und vielseitige Minigitarre zu spielen? Es gibt in ganz Deutschland <a href=\"http:\/\/bonn.ukulelentreff.de\/\" target=\"_blank\" rel=\"noopener\">Stammtische<\/a> dazu, ein Instrument ist schon ab 30 \u20ac zu haben.<\/p>\n<h3>Haus der Bildung<\/h3>\n<p>Ein Mitarbeiter (den Namen habe ich vergessen, sorry)\u00a0 von der Bonner VHS bot eine Hausf\u00fchrung an. Das wollte ich letztes Jahr schon machen, aber eine parallele Session lockte st\u00e4rker. Das konnte ich dieses Jahr nachholen. Wir bekamen interessante Fakts zum Haus, der Geschichte und \u00fcber Bonn zu h\u00f6ren. Die Architektur, vor allem der Stadtb\u00fccherei gef\u00e4llt mir sehr gut.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-11439\" src=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2018\/04\/bibliothek-bonn-litcampbn-2018.jpg\" alt=\"Bibliothek Bonn im Haus der Bildung\" width=\"480\" height=\"640\" srcset=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2018\/04\/bibliothek-bonn-litcampbn-2018.jpg 480w, https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2018\/04\/bibliothek-bonn-litcampbn-2018-225x300.jpg 225w\" sizes=\"auto, (max-width: 480px) 100vw, 480px\" \/><\/p>\n<p>Die VHS selbst hat auch gut ausgestattete Sportr\u00e4ume und sogar eine super K\u00fcche zu bieten. Vielleicht sollte ich dort mal einen Kurs zum Pl\u00e4tzchen backen anbieten?<\/p>\n<h3>Gutenberg<\/h3>\n<p><a href=\"https:\/\/www.britta-kretschmer.de\/\" target=\"_blank\" rel=\"noopener\">Britta<\/a> von <a href=\"https:\/\/www.internetkurse-koeln.de\/\" target=\"_blank\" rel=\"noopener\">Internet-Kurse-koeln.de<\/a> stellte den neuen WordPress-Editor \u201eGutenberg\u201c vor. Er wird mit der neuen Version 5 wahrscheinlich in der zweiten Jahresh\u00e4lfte kommen. Es gibt ein ganz neues Look and Feel. Wer sich daf\u00fcr interessiert kann Brittas <a href=\"https:\/\/www.internetkurse-koeln.de\/seiten-gestalten-mit-dem-neuen-gutenberg-spaltenblock\/\" target=\"_blank\" rel=\"noopener\">Blog-Beitrag<\/a> dazu nachlesen.<\/p>\n<p>Leider habe ich Depp vergessen ein Foto zu machen\u2026<\/p>\n<h3>Instagram<\/h3>\n<p>Wie ihr vielleicht wei\u00dft, werden die unterschiedlichen Social-Media-Kan\u00e4le von leckere Kekse unter uns aufgeteilt. Astrid macht Instagram und Pinterest, ich Facebook und Twitter. \u00a0Doch auch ich m\u00f6chte hinter das Geheimnis der Faszination von Instagram kommen. Mich\u00e8le von <a href=\"http:\/\/lichtemomente.eu\/start\/\" target=\"_blank\" rel=\"noopener\">lichtemomente<\/a> gab keine Schulung, sondern zeigte uns ein paar Beispiele und wir diskutierten \u00fcber die Vorteile von Instagram f\u00fcr Autoren. Es war ein lebhafter, spannender Austausch.<\/p>\n<h3>Abgang<\/h3>\n<p>Danach bin ich nach Hause gefahren. Ich hatte nur 4,5 Stunden geschlafen und war total m\u00fcde und ersch\u00f6pft. Au\u00dferdem versuche ich mich noch an meine neuen Einlagen zu gew\u00f6hnen (Fersensporn gepaart mit Hohl-Spreizfu\u00df und konnte nicht mehr stehen, sitzen, gehen. Ich war vielleicht unh\u00f6flich, doch ich bin einfach abgehauen ohne mich zu verabschieden. Deshalb kann ich \u00fcber die Abschlussveranstaltung nichts schreiben.<\/p>\n<h3>Fazit<\/h3>\n<p>Ein wunderbarer, ereignisreicher Tag. Ich habe viele Menschen wiedergetroffen, viele neu kennengelernt. Viel Neues erfahren. Kurz: ich freue mich auf n\u00e4chstes Jahr. Hoffentlich mit einer eigenen Session\u2026<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-5977\" src=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2016\/04\/Signatur-002-300x219.jpg\" alt=\"\" width=\"300\" height=\"219\" srcset=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2016\/04\/Signatur-002-300x219.jpg 300w, https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2016\/04\/Signatur-002.jpg 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>#LitcampBN18 Am 28.04.2018 fand das zweite Literaturbarcamp in Bonn statt. Wieder, wie auch im letzten Jahr, stellte die Volkshochschule Bonn ihre sch\u00f6nen R\u00e4ume daf\u00fcr zur Verf\u00fcgung. Auch das Organisationsteam, bestehend aus Uschi Fuchs und \u00a0Ute Lange blieb gleich. Auch viele der Teilnehmer waren \u201eWiederholungst\u00e4ter\u201c. Doch war die Veranstaltung nat\u00fcrlich ganz anders als die im Vorjahr. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":11443,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,682,19],"tags":[430,1094,457,445],"class_list":["post-11434","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-social-reading","category-veranstaltungen","tag-barcamp","tag-bonn","tag-literatur","tag-veranstaltung"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Literaturbarcamp in Bonn 2018 | Leckere Kekse &amp; mehr<\/title>\n<meta name=\"description\" content=\"Das zweite Literaturbarcamp fand im April 2018 in Bonn statt. Unter dem #LitCampBN18 wurde die Veranstaltung schon auf Twitter sehr popul\u00e4r. Hier mein pers\u00f6nlicher R\u00fcckblick.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/leckerekekse.de\/wordpress\/literaturbarcamp-in-bonn-2018\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Literaturbarcamp in Bonn 2018 | Leckere Kekse &amp; mehr\" \/>\n<meta property=\"og:description\" content=\"Das zweite Literaturbarcamp fand im April 2018 in Bonn statt. Unter dem #LitCampBN18 wurde die Veranstaltung schon auf Twitter sehr popul\u00e4r. Hier mein pers\u00f6nlicher R\u00fcckblick.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/leckerekekse.de\/wordpress\/literaturbarcamp-in-bonn-2018\/\" \/>\n<meta property=\"og:site_name\" content=\"Leckere Kekse &amp; mehr\" \/>\n<meta property=\"article:published_time\" content=\"2018-04-30T14:41:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-12T09:55:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2018\/04\/Litcamp-Bonn-2018.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"443\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Buchlieberin\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Buchlieberin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/literaturbarcamp-in-bonn-2018\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/literaturbarcamp-in-bonn-2018\\\/\"},\"author\":{\"name\":\"Buchlieberin\",\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/a3d9f5bd2acd12494d0064ab7ec8a1e4\"},\"headline\":\"Literaturbarcamp in Bonn 2018\",\"datePublished\":\"2018-04-30T14:41:03+00:00\",\"dateModified\":\"2022-09-12T09:55:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/literaturbarcamp-in-bonn-2018\\\/\"},\"wordCount\":983,\"commentCount\":12,\"publisher\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/332b4b8a8caf8c9a7642233a15eb5606\"},\"image\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/literaturbarcamp-in-bonn-2018\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/Litcamp-Bonn-2018.jpg\",\"keywords\":[\"Barcamp\",\"Bonn\",\"Literatur\",\"veranstaltung\"],\"articleSection\":{\"1\":\"Social Reading\",\"2\":\"Veranstaltungen\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/literaturbarcamp-in-bonn-2018\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/literaturbarcamp-in-bonn-2018\\\/\",\"url\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/literaturbarcamp-in-bonn-2018\\\/\",\"name\":\"Literaturbarcamp in Bonn 2018 | Leckere Kekse &amp; mehr\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/literaturbarcamp-in-bonn-2018\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/literaturbarcamp-in-bonn-2018\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/Litcamp-Bonn-2018.jpg\",\"datePublished\":\"2018-04-30T14:41:03+00:00\",\"dateModified\":\"2022-09-12T09:55:27+00:00\",\"description\":\"Das zweite Literaturbarcamp fand im April 2018 in Bonn statt. Unter dem #LitCampBN18 wurde die Veranstaltung schon auf Twitter sehr popul\u00e4r. Hier mein pers\u00f6nlicher R\u00fcckblick.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/literaturbarcamp-in-bonn-2018\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/literaturbarcamp-in-bonn-2018\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/literaturbarcamp-in-bonn-2018\\\/#primaryimage\",\"url\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/Litcamp-Bonn-2018.jpg\",\"contentUrl\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/Litcamp-Bonn-2018.jpg\",\"width\":640,\"height\":443,\"caption\":\"Literaturbarcamp Bonn 2018 litcampBN18o\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/literaturbarcamp-in-bonn-2018\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Literaturbarcamp in Bonn 2018\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#website\",\"url\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/\",\"name\":\"Leckere Kekse &amp; mehr\",\"description\":\"Kekse backen, B\u00fccher lesen und mehr\",\"publisher\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/332b4b8a8caf8c9a7642233a15eb5606\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/332b4b8a8caf8c9a7642233a15eb5606\",\"name\":\"Astrid\",\"logo\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/leckerekekse.de\\\/wordpress\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/a3d9f5bd2acd12494d0064ab7ec8a1e4\",\"name\":\"Buchlieberin\",\"sameAs\":[\"https:\\\/\\\/leckerekekse.de\\\/wordpress\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Literaturbarcamp in Bonn 2018 | Leckere Kekse &amp; mehr","description":"Das zweite Literaturbarcamp fand im April 2018 in Bonn statt. Unter dem #LitCampBN18 wurde die Veranstaltung schon auf Twitter sehr popul\u00e4r. Hier mein pers\u00f6nlicher R\u00fcckblick.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/leckerekekse.de\/wordpress\/literaturbarcamp-in-bonn-2018\/","og_locale":"de_DE","og_type":"article","og_title":"Literaturbarcamp in Bonn 2018 | Leckere Kekse &amp; mehr","og_description":"Das zweite Literaturbarcamp fand im April 2018 in Bonn statt. Unter dem #LitCampBN18 wurde die Veranstaltung schon auf Twitter sehr popul\u00e4r. Hier mein pers\u00f6nlicher R\u00fcckblick.","og_url":"https:\/\/leckerekekse.de\/wordpress\/literaturbarcamp-in-bonn-2018\/","og_site_name":"Leckere Kekse &amp; mehr","article_published_time":"2018-04-30T14:41:03+00:00","article_modified_time":"2022-09-12T09:55:27+00:00","og_image":[{"width":640,"height":443,"url":"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2018\/04\/Litcamp-Bonn-2018.jpg","type":"image\/jpeg"}],"author":"Buchlieberin","twitter_misc":{"Verfasst von":"Buchlieberin","Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/leckerekekse.de\/wordpress\/literaturbarcamp-in-bonn-2018\/#article","isPartOf":{"@id":"https:\/\/leckerekekse.de\/wordpress\/literaturbarcamp-in-bonn-2018\/"},"author":{"name":"Buchlieberin","@id":"https:\/\/leckerekekse.de\/wordpress\/#\/schema\/person\/a3d9f5bd2acd12494d0064ab7ec8a1e4"},"headline":"Literaturbarcamp in Bonn 2018","datePublished":"2018-04-30T14:41:03+00:00","dateModified":"2022-09-12T09:55:27+00:00","mainEntityOfPage":{"@id":"https:\/\/leckerekekse.de\/wordpress\/literaturbarcamp-in-bonn-2018\/"},"wordCount":983,"commentCount":12,"publisher":{"@id":"https:\/\/leckerekekse.de\/wordpress\/#\/schema\/person\/332b4b8a8caf8c9a7642233a15eb5606"},"image":{"@id":"https:\/\/leckerekekse.de\/wordpress\/literaturbarcamp-in-bonn-2018\/#primaryimage"},"thumbnailUrl":"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2018\/04\/Litcamp-Bonn-2018.jpg","keywords":["Barcamp","Bonn","Literatur","veranstaltung"],"articleSection":{"1":"Social Reading","2":"Veranstaltungen"},"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/leckerekekse.de\/wordpress\/literaturbarcamp-in-bonn-2018\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/leckerekekse.de\/wordpress\/literaturbarcamp-in-bonn-2018\/","url":"https:\/\/leckerekekse.de\/wordpress\/literaturbarcamp-in-bonn-2018\/","name":"Literaturbarcamp in Bonn 2018 | Leckere Kekse &amp; mehr","isPartOf":{"@id":"https:\/\/leckerekekse.de\/wordpress\/#website"},"primaryImageOfPage":{"@id":"https:\/\/leckerekekse.de\/wordpress\/literaturbarcamp-in-bonn-2018\/#primaryimage"},"image":{"@id":"https:\/\/leckerekekse.de\/wordpress\/literaturbarcamp-in-bonn-2018\/#primaryimage"},"thumbnailUrl":"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2018\/04\/Litcamp-Bonn-2018.jpg","datePublished":"2018-04-30T14:41:03+00:00","dateModified":"2022-09-12T09:55:27+00:00","description":"Das zweite Literaturbarcamp fand im April 2018 in Bonn statt. Unter dem #LitCampBN18 wurde die Veranstaltung schon auf Twitter sehr popul\u00e4r. Hier mein pers\u00f6nlicher R\u00fcckblick.","breadcrumb":{"@id":"https:\/\/leckerekekse.de\/wordpress\/literaturbarcamp-in-bonn-2018\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/leckerekekse.de\/wordpress\/literaturbarcamp-in-bonn-2018\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/leckerekekse.de\/wordpress\/literaturbarcamp-in-bonn-2018\/#primaryimage","url":"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2018\/04\/Litcamp-Bonn-2018.jpg","contentUrl":"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2018\/04\/Litcamp-Bonn-2018.jpg","width":640,"height":443,"caption":"Literaturbarcamp Bonn 2018 litcampBN18o"},{"@type":"BreadcrumbList","@id":"https:\/\/leckerekekse.de\/wordpress\/literaturbarcamp-in-bonn-2018\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/leckerekekse.de\/wordpress\/"},{"@type":"ListItem","position":2,"name":"Literaturbarcamp in Bonn 2018"}]},{"@type":"WebSite","@id":"https:\/\/leckerekekse.de\/wordpress\/#website","url":"https:\/\/leckerekekse.de\/wordpress\/","name":"Leckere Kekse &amp; mehr","description":"Kekse backen, B\u00fccher lesen und mehr","publisher":{"@id":"https:\/\/leckerekekse.de\/wordpress\/#\/schema\/person\/332b4b8a8caf8c9a7642233a15eb5606"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/leckerekekse.de\/wordpress\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/leckerekekse.de\/wordpress\/#\/schema\/person\/332b4b8a8caf8c9a7642233a15eb5606","name":"Astrid","logo":{"@id":"https:\/\/leckerekekse.de\/wordpress\/#\/schema\/person\/image\/"},"sameAs":["https:\/\/leckerekekse.de\/wordpress"]},{"@type":"Person","@id":"https:\/\/leckerekekse.de\/wordpress\/#\/schema\/person\/a3d9f5bd2acd12494d0064ab7ec8a1e4","name":"Buchlieberin","sameAs":["https:\/\/leckerekekse.de\/wordpress"]}]}},"_links":{"self":[{"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/posts\/11434","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/comments?post=11434"}],"version-history":[{"count":3,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/posts\/11434\/revisions"}],"predecessor-version":[{"id":17453,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/posts\/11434\/revisions\/17453"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/media\/11443"}],"wp:attachment":[{"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/media?parent=11434"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/categories?post=11434"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/tags?post=11434"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}