{"id":11862,"date":"2018-07-11T15:58:14","date_gmt":"2018-07-11T13:58:14","guid":{"rendered":"https:\/\/leckerekekse.de\/wordpress\/?p=11862"},"modified":"2022-09-12T11:55:27","modified_gmt":"2022-09-12T09:55:27","slug":"blogtour-sommerbuecher-lissabon","status":"publish","type":"post","link":"https:\/\/leckerekekse.de\/wordpress\/blogtour-sommerbuecher-lissabon\/","title":{"rendered":"Blogtour: Sommerb\u00fccher &#8211; Lissabon"},"content":{"rendered":"<h2><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-11870\" src=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2018\/07\/literarischer-spaziergang-durch-lissabon.jpg\" alt=\"Literarischer Spaziergang durch Lissabon\" width=\"640\" height=\"462\" srcset=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2018\/07\/literarischer-spaziergang-durch-lissabon.jpg 640w, https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2018\/07\/literarischer-spaziergang-durch-lissabon-300x217.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/h2>\n<h2>Ein literarischer Spaziergang durch Lissabon<\/h2>\n<p>Mein Mann erf\u00fcllte mir einen langgehegten Wunsch und schenkte mir einen Trip nach Lissabon. Als Zusatz gab es noch eine private F\u00fchrung mit dem Schwerpunkt Literatur.<\/p>\n<p>Das ergibt ein paar Buchtipps, die ich in die Blogparade <a href=\"https:\/\/tintenhain.de\/2018\/06\/01\/buechersommer-blogparade-buchtipps\/\">Sommerb\u00fccher<\/a> von Mona Tintenhain einreihen m\u00f6chte. Denn ich verbinde Portugal mit Sommer und Urlaub und lese gerne vor Ort passende B\u00fccher. Vielleicht m\u00f6chte einer von euch ja bald nach Lissabon fahren und sucht noch eine passende Lekt\u00fcre? Eine Reise in diese Stadt lohnt sich auf jeden Fall! Au\u00dferdem gibt es Infos \u00fcber ein paar Buchhandlungen und Autoren in Lissabon.<br \/>\n<!--more--><\/p>\n<h3>Buchhandlungen in Lissabon<\/h3>\n<p>Bei unseren Spazierg\u00e4ngen durch die Stadt war Literatur allgegenw\u00e4rtig. Es gibt zum Beispiel eine Buchhandlung, die viele B\u00fccher portugiesischer Titel auch in anderen Sprachen bereith\u00e4lt. Bei <a href=\"http:\/\/www.fabula-urbis.pt\/\" target=\"_blank\" rel=\"noopener\">Fabula Urbis<\/a> kann man also bequem passende Lekt\u00fcre f\u00fcr den Aufenthalt dort erwerben.<\/p>\n<p>Ganz in der N\u00e4he unseres Hotels sahen wir noch eine sch\u00f6ne, moderne Buchhandlung, in der man auf Deutsch beraten werden kann. Livraria Buchholz wurde von einer Deutschen gegr\u00fcndet und sp\u00e4ter von einer weiteren deutschen Frau \u00fcbernommen.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-11872\" src=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2018\/07\/buchhandlungen-lissabon.jpg\" alt=\"Buchhandlungen in Lissabon\" width=\"640\" height=\"427\" srcset=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2018\/07\/buchhandlungen-lissabon.jpg 640w, https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2018\/07\/buchhandlungen-lissabon-300x200.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<p>Ein weiterer Besuch sollte der \u00e4ltesten Buchhandlung Lissabons gelten. Pardon, sie ist die \u00e4lteste der Welt!!! Seit 1732 wird sie durchgehend betrieben. Die <a href=\"https:\/\/de.wikipedia.org\/wiki\/Livraria_Bertrand\" target=\"_blank\" rel=\"noopener\">Livraria Bertrand<\/a> gliedert sich in mehrere hintereinanderliegende R\u00e4ume, alle mit einem sch\u00f6nen Deckengew\u00f6lbe. Dieses ist an einer Stelle bis auf den Stein freigelegt, damit man die typische Bauweise bestaunen kann. Ansonsten sind W\u00e4nde und Decken in Wei\u00df gehalten, was die R\u00e4ume freundlich und sehr hell erscheinen l\u00e4sst. B\u00fccher auf Deutsch habe ich hier nicht entdeckt, aber es gibt ein gro\u00dfes Regal mit englischsprachigen Ausgaben. Ansonsten gab es dort sehr viel aktuelle Literatur. Witzig fand ich, dass einige B\u00fccher das gleiche Cover hatten wie in Deutschland. So zum Beispiel die sch\u00f6nen <a href=\"https:\/\/leckerekekse.de\/wordpress\/rezension-commendatore-murakami\/\" target=\"_blank\" rel=\"noopener\">Murakami<\/a>-Ausgaben.<\/p>\n<p>Die spektakul\u00e4rste Buchhandlung ist aber <a href=\"http:\/\/www.lerdevagar.com\/\" target=\"_blank\" rel=\"noopener\">Ler Devagar<\/a><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-11867\" src=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2018\/07\/ler-devagar-buchhnadlung-lissabon.jpg\" alt=\"Buchhandlung Ler Devagar Lissabon\" width=\"640\" height=\"480\" srcset=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2018\/07\/ler-devagar-buchhnadlung-lissabon.jpg 640w, https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2018\/07\/ler-devagar-buchhnadlung-lissabon-300x225.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<p>Sie befindet sich in der LX-Factory. Dieses Gel\u00e4nde ist ein ehemaliges Industriegebiet, in dem sich jetzt viele junge, moderne L\u00e4den angesiedelt haben.\u00a0 Individuelle Bekleidungs- und Schmuckl\u00e4den, viele Restaurants, Bars und Kunstgalerien findet man hier. Ein Besuch dort lohnt sich auf jeden Fall!\u00a0 Hier trifft man nicht nur auf Touristen, sondern auch auf viele junge Lissabonner.<\/p>\n<h3>Autoren<\/h3>\n<p>Es gibt in dem recht kleinen Land viele Autoren. Die Spuren einige Lissabonner Autoren sind \u00fcber die ganze Stadt verteilt.<\/p>\n<h3>Saramago<\/h3>\n<p>Jos\u00e9 Saramago ist auch acht Jahre nach seinem Tod in Lissabon sehr pr\u00e4sent. Es gibt ein Museum einer Stiftung mit seinem Namen in einem historischen Geb\u00e4ude, der Casa dos Bicos, davor einen Olivenbaum aus seinem Geburtsort und einen im Boden eingelassenen Gedenkstein.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-11868\" src=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2018\/07\/Lissabon.jpg\" alt=\"gedenken-an-saramago-lissabon\" width=\"640\" height=\"427\" srcset=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2018\/07\/Lissabon.jpg 640w, https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2018\/07\/Lissabon-300x200.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<p>Au\u00dferdem h\u00e4lt das Caffe Chiado immer noch einen Tisch f\u00fcr ihn frei. Mein Tipp: dort einen Espresso trinken und die Fotos betrachten.<\/p>\n<p>Was seine B\u00fccher betrifft, ist Stadt der Blinden sicher sein bekanntester Roman. Es ist wegen fehlender Abs\u00e4tze nicht so einfach zu lesen, da das Auge keine Struktur findet. Aber meiner Meinung nach ein must-read. Auf deutsch gibt es seine B\u00fccher bei Hoffmann und Campe.<\/p>\n<h3>Pessoa<\/h3>\n<p>Ein weiterer, wichtiger portugiesischer Autor ist Fernando Pessoa. An seinem Werk <a href=\"https:\/\/www.fischerverlage.de\/buch\/das_buch_der_unruhe_des_hilfsbuchhalters_bernardo_soares\/9783596903092\" target=\"_blank\" rel=\"noopener\">Buch der Unruhe<\/a>\u00a0 kommt man nicht vorbei, wenn man sich mit der dortigen Literatur besch\u00e4ftigt. Es geh\u00f6rt laut Perlentaucher zum Kanon der Weltliteratur. Heute. Denn zu Lebzeiten hatte er keinen gro\u00dfen Erfolg.\u00a0 Jetzt gibt es eine Bronzeskulptur von Pessoa vor dem Caf\u00e9 Brasileira und l\u00e4dt Passanten ein, sich dazu zu gesellen.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-11865\" src=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2018\/07\/pessoa-lissabon.jpg\" alt=\"Skulptur-fernando-pessoa-lissabon\" width=\"480\" height=\"640\" srcset=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2018\/07\/pessoa-lissabon.jpg 480w, https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2018\/07\/pessoa-lissabon-225x300.jpg 225w\" sizes=\"auto, (max-width: 480px) 100vw, 480px\" \/><\/p>\n<p>Von dort kann man das Standbild eines weiteren Autoren aus Lissabon sehen, n\u00e4mlich von Lu\u00eds de Cam\u00f5es.<\/p>\n<h3>Nationaldichter<\/h3>\n<p>In der Innenstadt gibt es den Pra\u00e7a Lu\u00eds de Cam\u00f5es mit einem monumentalen Standbild des \u00a0\u201eportugiesischen Goethes\u201c. Er wirkte im 16. Jahrhundert, starb w\u00e4hrend einer Pestepidemie und wurde ganz piet\u00e4tlos in einem Massengrab verscharrt. Doch er bekam sp\u00e4ter einen prachtvollen Sarkophag im Hieronymus-Kloster in Belem. Auf dem Wappen darauf ist eine Feder und eine Leier zu sehen:<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-11866 size-full\" src=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2018\/07\/Luis-de-Camoes-grabmal.jpg\" alt=\"Grabmal von Luis des Camoes in Belem\" width=\"480\" height=\"640\" srcset=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2018\/07\/Luis-de-Camoes-grabmal.jpg 480w, https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2018\/07\/Luis-de-Camoes-grabmal-225x300.jpg 225w\" sizes=\"auto, (max-width: 480px) 100vw, 480px\" \/><\/p>\n<p>Der Sarg ist leer, doch steht er direkt gegen\u00fcber dem Grabmal vom Nationalheld Vasco da Gama. Einige der Werke\u00a0Cam\u00f5es gibt es auch jetzt noch in deutscher \u00dcbersetzung und erscheinen im <a href=\"http:\/\/www.elfenbein-verlag.de\/\" target=\"_blank\" rel=\"noopener\">Elfenbein-Verlag<\/a> .<\/p>\n<h3>Meine Urlaubslekt\u00fcre<\/h3>\n<p>Begonnen habe ich auf dem K\u00f6lner Flughafen mit <a href=\"https:\/\/www.randomhouse.de\/Paperback\/Portugiesisches-Erbe\/Luis-Sellano\/Heyne\/e487744.rhd\" target=\"_blank\" rel=\"noopener\">Portugiesisches Erbe<\/a> von Luis Sellano. Hier bin ich einem Irrtum aufgesessen. Denn hinter dem portugiesisch klingenden Namen verbirgt sich ein deutscher Autor. Der Krimi ist etwas platt, hat eine leicht wirre Geschichte, kann aber auch als Reisef\u00fchrer dienen. Immer wieder sagte ich meinem Mann: &#8222;hier sind wir auch langgelaufen&#8220; oder &#8222;Wollten wir da nicht morgen hin&#8220;? Vielleicht sind auch die im Buch besuchten Restaurants und Bars gute Tipps, doch das haben wir aus zeitlichen Gr\u00fcnden nicht \u00fcberpr\u00fcft.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-11869\" src=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2018\/07\/Lissabon1.jpg\" alt=\"buecher die in Lissabon spielen\" width=\"640\" height=\"462\" srcset=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2018\/07\/Lissabon1.jpg 640w, https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2018\/07\/Lissabon1-300x217.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<h3>Antunes<\/h3>\n<p>Dann fing ich noch in Lissabon <a href=\"https:\/\/www.randomhouse.de\/Buch\/Ich-gehe-wie-ein-Haus-in-Flammen\/Antonio-Lobo-Antunes\/Luchterhand-Literaturverlag\/e483316.rhd\" target=\"_blank\" rel=\"noopener\">Ich gehe wie ein Haus in Flammen<\/a> von <a href=\"https:\/\/www.randomhouse.de\/Autor\/Antonio-Lobo-Antunes\/p74160.rhd\">Ant\u00f3nio Lobo Antunes<\/a> an. Ein ganz anderes Kaliber. Kein einfaches Buch, recht anspruchsvoll, aber irgendwie auch genial. Es geht um ein Mietshaus in Lissabon, vielmehr um dessen Bewohner. Alle kommen mehrmals zu Wort, sie erz\u00e4hlen von ihrem Leben, ihren Problemen, ihren Freuden. Es machte mir Spa\u00df die Zusammenh\u00e4nge nach und nach aufzudecken. Es spielt nach der Diktatur durch Salazar. Doch der Diktator durch R\u00fcckblicke und die Nachwirkungen auf die Gegenwart der Protagonisten ist immer pr\u00e4sent. Insofern auch ein politisches Buch. Der Roman verr\u00e4t viel \u00fcber die Kultur und die aktuellen Probleme der Gesellschaft. So zum Beispiel die nachtr\u00e4gliche Verarbeitung der bis in die 1970iger dauernden Kolonialzeit. Altersarmut, ein Thema, \u00fcber das ebenfalls unserer Stadtf\u00fchrerin gesprochen hat, ist auch ein Aspekt des Buches.\u00a0 <a href=\"https:\/\/de.wikipedia.org\/wiki\/Ant%C3%B3nio_Lobo_Antunes\" target=\"_blank\" rel=\"noopener\">Antunes<\/a> lebt und schreibt noch, ich werde sicher noch weitere B\u00fccher von ihm lesen.<\/p>\n<h3>Fazit<\/h3>\n<p>Mein Aufenthalt in Lissabon war wundersch\u00f6n. Die gezielte Besch\u00e4ftigung mit der passenden Literatur hat mir viel Spass gemacht. Auf die Idee nach Buchhandlungen in fremden St\u00e4dten Ausschau zu halten brachte mich Torsten Woywod mit seinem Buch <a href=\"https:\/\/leckerekekse.de\/wordpress\/woywood-buchhandlungen-europas\/\" target=\"_blank\" rel=\"noopener\">In 60 Buchhandlungen durch Europa<\/a>.<\/p>\n<p>Ich hoffe ich konnte euch ein paar Anregungen f\u00fcr B\u00fccher und Autoren von dort und ein paar Tipps f\u00fcr einen Aufenthalt in dieser tollen Stadt geben. Vielleicht ist jetzt kein typischer Artikel f\u00fcr die <a href=\"https:\/\/tintenhain.de\/2018\/06\/01\/buechersommer-blogparade-buchtipps\/\" target=\"_blank\" rel=\"noopener\">Aktion Sommerb\u00fccher<\/a> daraus geworden, aber manchmal bekommt so ein Beitrag bei der Erstellung ein Eigenleben.<\/p>\n<p>Sch\u00f6nen Sommer w\u00fcnsche ich euch<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-5977 size-medium\" src=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2016\/04\/Signatur-002-300x219.jpg\" alt=\"\" width=\"300\" height=\"219\" srcset=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2016\/04\/Signatur-002-300x219.jpg 300w, https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2016\/04\/Signatur-002.jpg 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p><span style=\"border-top-left-radius: 2px; border-top-right-radius: 2px; border-bottom-right-radius: 2px; border-bottom-left-radius: 2px; text-indent: 20px; width: auto; padding: 0px 4px 0px 0px; text-align: center; font-style: normal; font-variant-caps: normal; font-weight: bold; font-stretch: normal; font-size: 11px; line-height: 20px; font-family: 'Helvetica Neue', Helvetica, sans-serif; color: #ffffff; background-image: url(data:image\/svg+xml; base64,phn2zyb4bwxucz0iahr0cdovl3d3dy53my5vcmcvmjawmc9zdmciighlawdodd0imzbwecigd2lkdgg9ijmwchgiihzpzxdcb3g9ii0xic0xidmxidmxij48zz48cgf0acbkpsjnmjkundq5lde0ljy2mibdmjkundq5ldiyljcymiaymi44njgsmjkumju2ide0ljc1ldi5lji1nibdni42mzismjkumju2idaumduxldiyljcymiawlja1mswxnc42njigqzaumduxldyunjaxidyunjmyldaumdy3ide0ljc1ldaumdy3iemymi44njgsmc4wnjcgmjkundq5ldyunjaxidi5ljq0oswxnc42njiiigzpbgw9iinmzmyiihn0cm9rzt0ii2zmziigc3ryb2tllxdpzhropsixij48l3bhdgg+phbhdgggzd0itte0ljczmywxljy4nibdny41mtysms42odygms42njusny40otugms42njusmtqunjyyiemxljy2nswymc4xntkgns4xmdksmjquodu0idkuotcsmjyunzq0iem5ljg1niwyns43mtggos43ntmsmjqumtqzidewljaxniwymy4wmjigqzewlji1mywymi4wmsaxms41ndgsmtyuntcyidexlju0ocwxni41nzigqzexlju0ocwxni41nzigmteumtu3lde1ljc5nsaxms4xntcsmtqunjq2iemxms4xntcsmtiuodqyideyljixmswxms40otugmtmuntiyldexljq5nsbdmtqunjm3ldexljq5nsaxns4xnzusmtiumzi2ide1lje3nswxmy4zmjmgqze1lje3nswxnc40mzygmtqundyylde2ljegmtqumdkzlde3ljy0mybdmtmunzg1lde4ljkznsaxnc43ndusmtkuotg4ide2ljayocwxos45odggqze4ljm1mswxos45odggmjaumtm2lde3lju1niaymc4xmzysmtqumdq2iemymc4xmzysmtauotm5ide3ljg4ocw4ljc2nyaxnc42nzgsoc43njcgqzewljk1osw4ljc2nya4ljc3nywxms41mzygoc43nzcsmtqumzk4iem4ljc3nywxns41mtmgos4ymswxni43mdkgos43ndksmtcumzu5iem5ljg1niwxny40odggos44nzismtcunia5ljg0lde3ljczmsbdos43ndesmtgumtqxidkuntismtkumdizidkundc3lde5ljiwmybdos40miwxos40nca5lji4ocwxos40otegos4wncwxos4znzygqzcunda4lde4ljyymia2ljm4nywxni4yntigni4zodcsmtqumzq5iem2ljm4nywxmc4yntygos4zodmsni40otcgmtuumdiyldyundk3iemxos41ntusni40otcgmjmumdc4ldkunza1idizlja3ocwxmy45otegqzizlja3ocwxoc40njmgmjaumjm5ldiylja2miaxni4yotcsmjiumdyyiemxnc45nzmsmjiumdyyidezljcyocwyms4znzkgmtmumzayldiwlju3mibdmtmumzayldiwlju3miaxmi42ndcsmjmumdugmtiundg4ldizljy1nybdmtiumtkzldi0ljc4ncaxms4zotysmjyumtk2idewljg2mywyny4wntggqzeylja4niwyny40mzqgmtmumzg2ldi3ljyznyaxnc43mzmsmjcunjm3iemyms45nswyny42mzcgmjcuodaxldixljgyocayny44mdesmtqunjyyiemyny44mdesny40otugmjeuotusms42odygmtqunzmzldeunjg2iibmawxspsijymqwodfjij48l3bhdgg+pc9npjwvc3znpg==); background-size: 14px 14px; background-color: #bd081c; position: absolute; opacity: 1; z-index: 8675309; display: none; cursor: pointer; border: none; -webkit-font-smoothing: antialiased; top: 25px; left: 158px; background-position: 3px 50%; background-repeat: no-repeat no-repeat;\">Merken<\/span><span style=\"border-top-left-radius: 2px; border-top-right-radius: 2px; border-bottom-right-radius: 2px; border-bottom-left-radius: 2px; text-indent: 20px; width: auto; padding: 0px 4px 0px 0px; text-align: center; font-style: normal; font-variant-caps: normal; font-weight: bold; font-stretch: normal; font-size: 11px; line-height: 20px; font-family: 'Helvetica Neue', Helvetica, sans-serif; color: #ffffff; background-image: url(data:image\/svg+xml; base64,phn2zyb4bwxucz0iahr0cdovl3d3dy53my5vcmcvmjawmc9zdmciighlawdodd0imzbwecigd2lkdgg9ijmwchgiihzpzxdcb3g9ii0xic0xidmxidmxij48zz48cgf0acbkpsjnmjkundq5lde0ljy2mibdmjkundq5ldiyljcymiaymi44njgsmjkumju2ide0ljc1ldi5lji1nibdni42mzismjkumju2idaumduxldiyljcymiawlja1mswxnc42njigqzaumduxldyunjaxidyunjmyldaumdy3ide0ljc1ldaumdy3iemymi44njgsmc4wnjcgmjkundq5ldyunjaxidi5ljq0oswxnc42njiiigzpbgw9iinmzmyiihn0cm9rzt0ii2zmziigc3ryb2tllxdpzhropsixij48l3bhdgg+phbhdgggzd0itte0ljczmywxljy4nibdny41mtysms42odygms42njusny40otugms42njusmtqunjyyiemxljy2nswymc4xntkgns4xmdksmjquodu0idkuotcsmjyunzq0iem5ljg1niwyns43mtggos43ntmsmjqumtqzidewljaxniwymy4wmjigqzewlji1mywymi4wmsaxms41ndgsmtyuntcyidexlju0ocwxni41nzigqzexlju0ocwxni41nzigmteumtu3lde1ljc5nsaxms4xntcsmtqunjq2iemxms4xntcsmtiuodqyideyljixmswxms40otugmtmuntiyldexljq5nsbdmtqunjm3ldexljq5nsaxns4xnzusmtiumzi2ide1lje3nswxmy4zmjmgqze1lje3nswxnc40mzygmtqundyylde2ljegmtqumdkzlde3ljy0mybdmtmunzg1lde4ljkznsaxnc43ndusmtkuotg4ide2ljayocwxos45odggqze4ljm1mswxos45odggmjaumtm2lde3lju1niaymc4xmzysmtqumdq2iemymc4xmzysmtauotm5ide3ljg4ocw4ljc2nyaxnc42nzgsoc43njcgqzewljk1osw4ljc2nya4ljc3nywxms41mzygoc43nzcsmtqumzk4iem4ljc3nywxns41mtmgos4ymswxni43mdkgos43ndksmtcumzu5iem5ljg1niwxny40odggos44nzismtcunia5ljg0lde3ljczmsbdos43ndesmtgumtqxidkuntismtkumdizidkundc3lde5ljiwmybdos40miwxos40nca5lji4ocwxos40otegos4wncwxos4znzygqzcunda4lde4ljyymia2ljm4nywxni4yntigni4zodcsmtqumzq5iem2ljm4nywxmc4yntygos4zodmsni40otcgmtuumdiyldyundk3iemxos41ntusni40otcgmjmumdc4ldkunza1idizlja3ocwxmy45otegqzizlja3ocwxoc40njmgmjaumjm5ldiylja2miaxni4yotcsmjiumdyyiemxnc45nzmsmjiumdyyidezljcyocwyms4znzkgmtmumzayldiwlju3mibdmtmumzayldiwlju3miaxmi42ndcsmjmumdugmtiundg4ldizljy1nybdmtiumtkzldi0ljc4ncaxms4zotysmjyumtk2idewljg2mywyny4wntggqzeylja4niwyny40mzqgmtmumzg2ldi3ljyznyaxnc43mzmsmjcunjm3iemyms45nswyny42mzcgmjcuodaxldixljgyocayny44mdesmtqunjyyiemyny44mdesny40otugmjeuotusms42odygmtqunzmzldeunjg2iibmawxspsijymqwodfjij48l3bhdgg+pc9npjwvc3znpg==); background-size: 14px 14px; background-color: #bd081c; position: absolute; opacity: 1; z-index: 8675309; display: none; cursor: pointer; border: none; -webkit-font-smoothing: antialiased; top: 25px; left: 158px; background-position: 3px 50%; background-repeat: no-repeat no-repeat;\">Merken<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ein literarischer Spaziergang durch Lissabon Mein Mann erf\u00fcllte mir einen langgehegten Wunsch und schenkte mir einen Trip nach Lissabon. Als Zusatz gab es noch eine private F\u00fchrung mit dem Schwerpunkt Literatur. Das ergibt ein paar Buchtipps, die ich in die Blogparade Sommerb\u00fccher von Mona Tintenhain einreihen m\u00f6chte. Denn ich verbinde Portugal mit Sommer und Urlaub [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":11870,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,3,808,682],"tags":[563,499,306,1117,265,271],"class_list":["post-11862","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-buecher","category-buchtipps","category-social-reading","tag-blogparade","tag-blogtour","tag-buchhandlung","tag-lissabon","tag-sommer","tag-urlaub"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Blogtour: Sommerb\u00fccher - Lissabon | Leckere Kekse &amp; mehr<\/title>\n<meta name=\"description\" content=\"Ich nehme euch mit auf einen literarischen Spaziergang durch Lissabon und stelle Literatur, Buchhandlungen und Autoren von dort vor.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/leckerekekse.de\/wordpress\/blogtour-sommerbuecher-lissabon\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Blogtour: Sommerb\u00fccher - Lissabon | Leckere Kekse &amp; mehr\" \/>\n<meta property=\"og:description\" content=\"Ich nehme euch mit auf einen literarischen Spaziergang durch Lissabon und stelle Literatur, Buchhandlungen und Autoren von dort vor.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/leckerekekse.de\/wordpress\/blogtour-sommerbuecher-lissabon\/\" \/>\n<meta property=\"og:site_name\" content=\"Leckere Kekse &amp; mehr\" \/>\n<meta property=\"article:published_time\" content=\"2018-07-11T13:58:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-12T09:55:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2018\/07\/literarischer-spaziergang-durch-lissabon.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"462\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Buchlieberin\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Buchlieberin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/blogtour-sommerbuecher-lissabon\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/blogtour-sommerbuecher-lissabon\\\/\"},\"author\":{\"name\":\"Buchlieberin\",\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/2374d41b5cda28a27f6924e58f3afcc2\"},\"headline\":\"Blogtour: Sommerb\u00fccher &#8211; Lissabon\",\"datePublished\":\"2018-07-11T13:58:14+00:00\",\"dateModified\":\"2022-09-12T09:55:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/blogtour-sommerbuecher-lissabon\\\/\"},\"wordCount\":1071,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/72061e7e8c1c70c8e8e542a13e5acbfe\"},\"image\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/blogtour-sommerbuecher-lissabon\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/literarischer-spaziergang-durch-lissabon.jpg\",\"keywords\":[\"Blogparade\",\"Blogtour\",\"Buchhandlung\",\"Lissabon\",\"Sommer\",\"Urlaub\"],\"articleSection\":{\"1\":\"B\u00fccher\",\"2\":\"Buchtipps\",\"3\":\"Social Reading\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/blogtour-sommerbuecher-lissabon\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/blogtour-sommerbuecher-lissabon\\\/\",\"url\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/blogtour-sommerbuecher-lissabon\\\/\",\"name\":\"Blogtour: Sommerb\u00fccher - Lissabon | Leckere Kekse &amp; mehr\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/blogtour-sommerbuecher-lissabon\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/blogtour-sommerbuecher-lissabon\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/literarischer-spaziergang-durch-lissabon.jpg\",\"datePublished\":\"2018-07-11T13:58:14+00:00\",\"dateModified\":\"2022-09-12T09:55:27+00:00\",\"description\":\"Ich nehme euch mit auf einen literarischen Spaziergang durch Lissabon und stelle Literatur, Buchhandlungen und Autoren von dort vor.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/blogtour-sommerbuecher-lissabon\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/blogtour-sommerbuecher-lissabon\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/blogtour-sommerbuecher-lissabon\\\/#primaryimage\",\"url\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/literarischer-spaziergang-durch-lissabon.jpg\",\"contentUrl\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/literarischer-spaziergang-durch-lissabon.jpg\",\"width\":640,\"height\":462,\"caption\":\"Literarischer Spaziergang durch Lissabon\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/blogtour-sommerbuecher-lissabon\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Blogtour: Sommerb\u00fccher &#8211; Lissabon\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#website\",\"url\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/\",\"name\":\"Leckere Kekse &amp; mehr\",\"description\":\"Kekse backen, B\u00fccher lesen und mehr\",\"publisher\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/72061e7e8c1c70c8e8e542a13e5acbfe\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/72061e7e8c1c70c8e8e542a13e5acbfe\",\"name\":\"Astrid\",\"logo\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/leckerekekse.de\\\/wordpress\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/2374d41b5cda28a27f6924e58f3afcc2\",\"name\":\"Buchlieberin\",\"sameAs\":[\"https:\\\/\\\/leckerekekse.de\\\/wordpress\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Blogtour: Sommerb\u00fccher - Lissabon | Leckere Kekse &amp; mehr","description":"Ich nehme euch mit auf einen literarischen Spaziergang durch Lissabon und stelle Literatur, Buchhandlungen und Autoren von dort vor.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/leckerekekse.de\/wordpress\/blogtour-sommerbuecher-lissabon\/","og_locale":"de_DE","og_type":"article","og_title":"Blogtour: Sommerb\u00fccher - Lissabon | Leckere Kekse &amp; mehr","og_description":"Ich nehme euch mit auf einen literarischen Spaziergang durch Lissabon und stelle Literatur, Buchhandlungen und Autoren von dort vor.","og_url":"https:\/\/leckerekekse.de\/wordpress\/blogtour-sommerbuecher-lissabon\/","og_site_name":"Leckere Kekse &amp; mehr","article_published_time":"2018-07-11T13:58:14+00:00","article_modified_time":"2022-09-12T09:55:27+00:00","og_image":[{"width":640,"height":462,"url":"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2018\/07\/literarischer-spaziergang-durch-lissabon.jpg","type":"image\/jpeg"}],"author":"Buchlieberin","twitter_misc":{"Verfasst von":"Buchlieberin","Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/leckerekekse.de\/wordpress\/blogtour-sommerbuecher-lissabon\/#article","isPartOf":{"@id":"https:\/\/leckerekekse.de\/wordpress\/blogtour-sommerbuecher-lissabon\/"},"author":{"name":"Buchlieberin","@id":"https:\/\/leckerekekse.de\/wordpress\/#\/schema\/person\/2374d41b5cda28a27f6924e58f3afcc2"},"headline":"Blogtour: Sommerb\u00fccher &#8211; Lissabon","datePublished":"2018-07-11T13:58:14+00:00","dateModified":"2022-09-12T09:55:27+00:00","mainEntityOfPage":{"@id":"https:\/\/leckerekekse.de\/wordpress\/blogtour-sommerbuecher-lissabon\/"},"wordCount":1071,"commentCount":1,"publisher":{"@id":"https:\/\/leckerekekse.de\/wordpress\/#\/schema\/person\/72061e7e8c1c70c8e8e542a13e5acbfe"},"image":{"@id":"https:\/\/leckerekekse.de\/wordpress\/blogtour-sommerbuecher-lissabon\/#primaryimage"},"thumbnailUrl":"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2018\/07\/literarischer-spaziergang-durch-lissabon.jpg","keywords":["Blogparade","Blogtour","Buchhandlung","Lissabon","Sommer","Urlaub"],"articleSection":{"1":"B\u00fccher","2":"Buchtipps","3":"Social Reading"},"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/leckerekekse.de\/wordpress\/blogtour-sommerbuecher-lissabon\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/leckerekekse.de\/wordpress\/blogtour-sommerbuecher-lissabon\/","url":"https:\/\/leckerekekse.de\/wordpress\/blogtour-sommerbuecher-lissabon\/","name":"Blogtour: Sommerb\u00fccher - Lissabon | Leckere Kekse &amp; mehr","isPartOf":{"@id":"https:\/\/leckerekekse.de\/wordpress\/#website"},"primaryImageOfPage":{"@id":"https:\/\/leckerekekse.de\/wordpress\/blogtour-sommerbuecher-lissabon\/#primaryimage"},"image":{"@id":"https:\/\/leckerekekse.de\/wordpress\/blogtour-sommerbuecher-lissabon\/#primaryimage"},"thumbnailUrl":"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2018\/07\/literarischer-spaziergang-durch-lissabon.jpg","datePublished":"2018-07-11T13:58:14+00:00","dateModified":"2022-09-12T09:55:27+00:00","description":"Ich nehme euch mit auf einen literarischen Spaziergang durch Lissabon und stelle Literatur, Buchhandlungen und Autoren von dort vor.","breadcrumb":{"@id":"https:\/\/leckerekekse.de\/wordpress\/blogtour-sommerbuecher-lissabon\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/leckerekekse.de\/wordpress\/blogtour-sommerbuecher-lissabon\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/leckerekekse.de\/wordpress\/blogtour-sommerbuecher-lissabon\/#primaryimage","url":"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2018\/07\/literarischer-spaziergang-durch-lissabon.jpg","contentUrl":"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2018\/07\/literarischer-spaziergang-durch-lissabon.jpg","width":640,"height":462,"caption":"Literarischer Spaziergang durch Lissabon"},{"@type":"BreadcrumbList","@id":"https:\/\/leckerekekse.de\/wordpress\/blogtour-sommerbuecher-lissabon\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/leckerekekse.de\/wordpress\/"},{"@type":"ListItem","position":2,"name":"Blogtour: Sommerb\u00fccher &#8211; Lissabon"}]},{"@type":"WebSite","@id":"https:\/\/leckerekekse.de\/wordpress\/#website","url":"https:\/\/leckerekekse.de\/wordpress\/","name":"Leckere Kekse &amp; mehr","description":"Kekse backen, B\u00fccher lesen und mehr","publisher":{"@id":"https:\/\/leckerekekse.de\/wordpress\/#\/schema\/person\/72061e7e8c1c70c8e8e542a13e5acbfe"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/leckerekekse.de\/wordpress\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/leckerekekse.de\/wordpress\/#\/schema\/person\/72061e7e8c1c70c8e8e542a13e5acbfe","name":"Astrid","logo":{"@id":"https:\/\/leckerekekse.de\/wordpress\/#\/schema\/person\/image\/"},"sameAs":["https:\/\/leckerekekse.de\/wordpress"]},{"@type":"Person","@id":"https:\/\/leckerekekse.de\/wordpress\/#\/schema\/person\/2374d41b5cda28a27f6924e58f3afcc2","name":"Buchlieberin","sameAs":["https:\/\/leckerekekse.de\/wordpress"]}]}},"_links":{"self":[{"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/posts\/11862","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/comments?post=11862"}],"version-history":[{"count":4,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/posts\/11862\/revisions"}],"predecessor-version":[{"id":17456,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/posts\/11862\/revisions\/17456"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/media\/11870"}],"wp:attachment":[{"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/media?parent=11862"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/categories?post=11862"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/tags?post=11862"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}