{"id":12691,"date":"2018-12-19T14:35:31","date_gmt":"2018-12-19T13:35:31","guid":{"rendered":"https:\/\/leckerekekse.de\/wordpress\/?p=12691"},"modified":"2018-12-19T16:09:36","modified_gmt":"2018-12-19T15:09:36","slug":"10-buchsaiten-blogparade","status":"publish","type":"post","link":"https:\/\/leckerekekse.de\/wordpress\/10-buchsaiten-blogparade\/","title":{"rendered":"10. BuchSaiten-Blogparade"},"content":{"rendered":"\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"430\" src=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2018\/12\/buchsaeiten-blogparade-640x430.png\" alt=\"\" class=\"wp-image-12693\" srcset=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2018\/12\/buchsaeiten-blogparade.png 640w, https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2018\/12\/buchsaeiten-blogparade-300x202.png 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Zeit f\u00fcr die Buchsaiten-Blogparade<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Das Jahr geht zu Ende, ein Neues steht bevor. Das bedeutet: Es ist an der Zeit, bei der&nbsp;<strong>#BSBP18 (BuchSaiten BlogParade)&nbsp;<\/strong>mitzumachen<strong>.&nbsp;<\/strong>Die&nbsp;Organisation macht wie im letzten Jahr Petzi von <a href=\"https:\/\/dieliebezudenbuechern.de\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"Das Jahr geht zu Ende, ein Neues steht bevor. Das bedeutet: Es ist an der Zeit, bei der&nbsp;#BSBP18 (BuchSaiten BlogParade)&nbsp;mitzumachen.&nbsp;Die&nbsp;Organisation macht wie im letzten Jahr Petzi von DieLiebezudenB\u00fcchern. Diese Blogparade ist perfekt, um die gelesenen B\u00fccher des vergangenen Jahres Revue passieren zu lassen. Es gibt immer die gleichen Fragen und so ist es Jahr f\u00fcr Jahr eine sch\u00f6ne Tradition, an dieser Blogparade teilzunehmen. (\u00f6ffnet in neuem Tab)\">DieLiebezudenB\u00fcchern<\/a>. Diese Blogparade ist perfekt, um die gelesenen B\u00fccher des vergangenen Jahres Revue passieren zu lassen. Es gibt immer die gleichen Fragen und so ist es Jahr f\u00fcr Jahr eine sch\u00f6ne Tradition, an dieser Blogparade teilzunehmen.<\/p>\n\n\n\n<!--more-->\n\n\n\n<h3 class=\"wp-block-heading\">WELCHES WAR DAS BUCH IN DIESEM JAHR, VON DEM ICH MIR WENIG VERSPROCHEN HABE, DAS MICH DANN ABER POSITIV \u00dcBERRASCHT HAT?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">So viele waren begeistert von dem Buch. Aber ich konnte mich nicht so recht durchringen es zu lesen. Und dann hat es mich \u00fcberrascht! Dachte ich doch immer: &#8222;Was kommt da noch? Eigentlich ist das Thema doch gleich durch?&#8220; Und dann wurde alles noch ganz anders als gedacht. F\u00fcr mich ein Roman mit gro\u00dfem \u00dcberraschungseffekt.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"640\" src=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2018\/09\/Olga-480x640.jpg\" alt=\"Olga - Bernhard Schlank\" class=\"wp-image-12171\" srcset=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2018\/09\/Olga-480x640.jpg 480w, https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2018\/09\/Olga-225x300.jpg 225w, https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2018\/09\/Olga.jpg 640w\" sizes=\"auto, (max-width: 480px) 100vw, 480px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">WELCHES WAR DAS BUCH IN DIESEM JAHR, VON DEM ICH MIR VIEL VERSPROCHEN HABE, DAS MICH DANN ABER NEGATIV \u00dcBERRASCHT HAT?<\/h3>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"853\" src=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2018\/09\/die-katze-und-der-general.jpg\" alt=\"Die Katze und der General\" class=\"wp-image-12168\" srcset=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2018\/09\/die-katze-und-der-general.jpg 640w, https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2018\/09\/die-katze-und-der-general-225x300.jpg 225w, https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2018\/09\/die-katze-und-der-general-480x640.jpg 480w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">&#8222;Die Katze und der General&#8220; war meine gr\u00f6\u00dfte Entt\u00e4uschung dieses Jahr. 2018 hatte ich in der Blogsaitenblogparade &#8222;Das achte Leben&#8220; von Nino Haratischwilli genannt, dass ich unbedingt lesen wollte. Das habe ich auch geschafft! Und ich war begeistert! So ein tolles Buch! Das Nachfolgebuch stand sogar auf der Shortlist f\u00fcr den deutschen Buchpreis. Also konnte es doch nur noch besser sein! Aber dieses Buch war nicht stimmig. Ob die Autorin zu viel Druck beim Schreiben hatte? Das Lektorat nicht passte? Ich wei\u00df es nicht!&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">WELCHES WAR Deine&nbsp;PERS\u00d6NLICHE AUTOREN-NEUENTDECKUNG IN DIESEM JAHR UND WARUM?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Franziska Seyboldt. &#8222;<a href=\"https:\/\/leckerekekse.de\/wordpress\/franziska-seyboldt-rattatatam-mein-herz\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"Franziska Seyboldt. &quot;Rattatatam, mein Herz&quot;. Das Thema interessierte mich bisher ehrlich gesagt nicht sehr. Es war das erste Buch in diesem Jahr, das ich gelesen hatte und es sprach mich total an. Zum ersten Mal konnte mir jemand erkl\u00e4ren, was Angstst\u00f6rungen sind. Ich f\u00fchlte mich extrem gut informiert, aber auch sehr gut unterhalten. Ein Highlight meines Lesejahres. Und es hat mich ein wenig auf das vorbereitet, was das Jahr f\u00fcr mich bringen sollte. Ich bin einfach nur dankbar f\u00fcr dieses tolle Buch.&nbsp; (\u00f6ffnet in neuem Tab)\">Rattatatam, mein Herz<\/a>&#8222;. Das Thema interessierte mich bisher ehrlich gesagt nicht sehr. Es war das erste Buch in diesem Jahr, das ich gelesen hatte und es sprach mich total an. Zum ersten Mal konnte mir jemand erkl\u00e4ren, was Angstst\u00f6rungen sind. Ich f\u00fchlte mich extrem gut informiert, aber auch sehr gut unterhalten. Ein Highlight meines Lesejahres. Und es hat mich ein wenig auf das vorbereitet, was das Jahr f\u00fcr mich bringen sollte. Ich bin einfach nur dankbar f\u00fcr dieses tolle Buch.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"640\" src=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2018\/01\/rattatatam-franziska-seyboldt.jpg\" alt=\"Buch \u00fcber Angstst\u00f6rung\" class=\"wp-image-10798\" srcset=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2018\/01\/rattatatam-franziska-seyboldt.jpg 640w, https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2018\/01\/rattatatam-franziska-seyboldt-150x150.jpg 150w, https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2018\/01\/rattatatam-franziska-seyboldt-300x300.jpg 300w, https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2018\/01\/rattatatam-franziska-seyboldt-144x144.jpg 144w, https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2018\/01\/rattatatam-franziska-seyboldt-120x120.jpg 120w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">WELCHES WAR Dein&nbsp;LIEBLINGS-COVER IN DIESEM JAHR UND WARUM?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Das ist das Cover von &#8222;Dunkelgr\u00fcn fast schwarz&#8220;. Wie h\u00e4ufig habe ich mir das angesehen? Ich habe mir das Buch direkt nach der Buchmesse gekauft und es lag hier sehr lange in Sichtweite, weil ich das Cover mit dem Gr\u00fcn einfach klasse fand. Vielleicht lag es an dem Fr\u00fchling, der einfach nicht kommen wollte! Ich sehnte mich wahrscheinlich endlich nach sattem sommerlichen Gr\u00fcn. Inhaltlich konnte mich das Buch leider nicht 100% \u00fcberzeugen.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"633\" height=\"640\" src=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2018\/12\/dunkelgruenfastschwarz-633x640.jpg\" alt=\"\" class=\"wp-image-12695\" srcset=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2018\/12\/dunkelgruenfastschwarz-633x640.jpg 633w, https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2018\/12\/dunkelgruenfastschwarz-297x300.jpg 297w, https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2018\/12\/dunkelgruenfastschwarz-120x120.jpg 120w, https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2018\/12\/dunkelgruenfastschwarz.jpg 639w\" sizes=\"auto, (max-width: 633px) 100vw, 633px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">WELCHES BUCH WILLST du UNBEDINGT IN 2019 LESEN UND WARUM?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Ich habe es schon auf meinem Reader! Es ist &#8222;<strong>Der sanfte Zwilling<\/strong>&#8222;<strong>&nbsp;<\/strong>von Nino Haratischwili. Ich m\u00f6chte noch einmal ein weiteres gutes Buch der Autorin lesen. Und bei diesem Buch scheinen sich alle einig zu sein, dass es gut ist.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vielen Dank an Petzi von <a href=\"http:\/\/www.dieliebezudenbuechern.de\" target=\"_blank\" rel=\"noreferrer noopener\">Die Liebe zu den B\u00fcchern<\/a> f\u00fcr die Organisation der Blogparade.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">So, und nun w\u00fcnsche ich Euch besinnliche Weihnachten, einen guten Rutsch und ein wundervolles Jahr 2019<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"206\" height=\"97\" src=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2016\/04\/Scan-11.jpeg\" alt=\"\" class=\"wp-image-5966\"\/><\/figure><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Zeit f\u00fcr die Buchsaiten-Blogparade Das Jahr geht zu Ende, ein Neues steht bevor. Das bedeutet: Es ist an der Zeit, bei der&nbsp;#BSBP18 (BuchSaiten BlogParade)&nbsp;mitzumachen.&nbsp;Die&nbsp;Organisation macht wie im letzten Jahr Petzi von DieLiebezudenB\u00fcchern. Diese Blogparade ist perfekt, um die gelesenen B\u00fccher des vergangenen Jahres Revue passieren zu lassen. Es gibt immer die gleichen Fragen und so [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":12693,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,3],"tags":[563,1180,459],"class_list":["post-12691","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-buecher","tag-blogparade","tag-buchsaiten","tag-roman"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>10. BuchSaiten-Blogparade | Leckere Kekse &amp; mehr<\/title>\n<meta name=\"description\" content=\"Es ist mal wieder Zeit, um das Jahr Revue passieren zu lassen. Bei dieser Blogparade geht es um die B\u00fccher des Jahres 2018.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/leckerekekse.de\/wordpress\/10-buchsaiten-blogparade\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"10. BuchSaiten-Blogparade | Leckere Kekse &amp; mehr\" \/>\n<meta property=\"og:description\" content=\"Es ist mal wieder Zeit, um das Jahr Revue passieren zu lassen. Bei dieser Blogparade geht es um die B\u00fccher des Jahres 2018.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/leckerekekse.de\/wordpress\/10-buchsaiten-blogparade\/\" \/>\n<meta property=\"og:site_name\" content=\"Leckere Kekse &amp; mehr\" \/>\n<meta property=\"article:published_time\" content=\"2018-12-19T13:35:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-12-19T15:09:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2018\/12\/buchsaeiten-blogparade.png\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"430\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Astrid\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Astrid\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/10-buchsaiten-blogparade\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/10-buchsaiten-blogparade\\\/\"},\"author\":{\"name\":\"Astrid\",\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/72061e7e8c1c70c8e8e542a13e5acbfe\"},\"headline\":\"10. BuchSaiten-Blogparade\",\"datePublished\":\"2018-12-19T13:35:31+00:00\",\"dateModified\":\"2018-12-19T15:09:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/10-buchsaiten-blogparade\\\/\"},\"wordCount\":538,\"commentCount\":5,\"publisher\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/72061e7e8c1c70c8e8e542a13e5acbfe\"},\"image\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/10-buchsaiten-blogparade\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/buchsaeiten-blogparade.png\",\"keywords\":[\"Blogparade\",\"Buchsaiten\",\"Roman\"],\"articleSection\":{\"1\":\"B\u00fccher\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/10-buchsaiten-blogparade\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/10-buchsaiten-blogparade\\\/\",\"url\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/10-buchsaiten-blogparade\\\/\",\"name\":\"10. BuchSaiten-Blogparade | Leckere Kekse &amp; mehr\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/10-buchsaiten-blogparade\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/10-buchsaiten-blogparade\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/buchsaeiten-blogparade.png\",\"datePublished\":\"2018-12-19T13:35:31+00:00\",\"dateModified\":\"2018-12-19T15:09:36+00:00\",\"description\":\"Es ist mal wieder Zeit, um das Jahr Revue passieren zu lassen. Bei dieser Blogparade geht es um die B\u00fccher des Jahres 2018.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/10-buchsaiten-blogparade\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/10-buchsaiten-blogparade\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/10-buchsaiten-blogparade\\\/#primaryimage\",\"url\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/buchsaeiten-blogparade.png\",\"contentUrl\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/buchsaeiten-blogparade.png\",\"width\":640,\"height\":430},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/10-buchsaiten-blogparade\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"10. BuchSaiten-Blogparade\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#website\",\"url\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/\",\"name\":\"Leckere Kekse &amp; mehr\",\"description\":\"Kekse backen, B\u00fccher lesen und mehr\",\"publisher\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/72061e7e8c1c70c8e8e542a13e5acbfe\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/72061e7e8c1c70c8e8e542a13e5acbfe\",\"name\":\"Astrid\",\"logo\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/leckerekekse.de\\\/wordpress\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"10. BuchSaiten-Blogparade | Leckere Kekse &amp; mehr","description":"Es ist mal wieder Zeit, um das Jahr Revue passieren zu lassen. Bei dieser Blogparade geht es um die B\u00fccher des Jahres 2018.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/leckerekekse.de\/wordpress\/10-buchsaiten-blogparade\/","og_locale":"de_DE","og_type":"article","og_title":"10. BuchSaiten-Blogparade | Leckere Kekse &amp; mehr","og_description":"Es ist mal wieder Zeit, um das Jahr Revue passieren zu lassen. Bei dieser Blogparade geht es um die B\u00fccher des Jahres 2018.","og_url":"https:\/\/leckerekekse.de\/wordpress\/10-buchsaiten-blogparade\/","og_site_name":"Leckere Kekse &amp; mehr","article_published_time":"2018-12-19T13:35:31+00:00","article_modified_time":"2018-12-19T15:09:36+00:00","og_image":[{"width":640,"height":430,"url":"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2018\/12\/buchsaeiten-blogparade.png","type":"image\/png"}],"author":"Astrid","twitter_misc":{"Verfasst von":"Astrid","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/leckerekekse.de\/wordpress\/10-buchsaiten-blogparade\/#article","isPartOf":{"@id":"https:\/\/leckerekekse.de\/wordpress\/10-buchsaiten-blogparade\/"},"author":{"name":"Astrid","@id":"https:\/\/leckerekekse.de\/wordpress\/#\/schema\/person\/72061e7e8c1c70c8e8e542a13e5acbfe"},"headline":"10. BuchSaiten-Blogparade","datePublished":"2018-12-19T13:35:31+00:00","dateModified":"2018-12-19T15:09:36+00:00","mainEntityOfPage":{"@id":"https:\/\/leckerekekse.de\/wordpress\/10-buchsaiten-blogparade\/"},"wordCount":538,"commentCount":5,"publisher":{"@id":"https:\/\/leckerekekse.de\/wordpress\/#\/schema\/person\/72061e7e8c1c70c8e8e542a13e5acbfe"},"image":{"@id":"https:\/\/leckerekekse.de\/wordpress\/10-buchsaiten-blogparade\/#primaryimage"},"thumbnailUrl":"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2018\/12\/buchsaeiten-blogparade.png","keywords":["Blogparade","Buchsaiten","Roman"],"articleSection":{"1":"B\u00fccher"},"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/leckerekekse.de\/wordpress\/10-buchsaiten-blogparade\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/leckerekekse.de\/wordpress\/10-buchsaiten-blogparade\/","url":"https:\/\/leckerekekse.de\/wordpress\/10-buchsaiten-blogparade\/","name":"10. BuchSaiten-Blogparade | Leckere Kekse &amp; mehr","isPartOf":{"@id":"https:\/\/leckerekekse.de\/wordpress\/#website"},"primaryImageOfPage":{"@id":"https:\/\/leckerekekse.de\/wordpress\/10-buchsaiten-blogparade\/#primaryimage"},"image":{"@id":"https:\/\/leckerekekse.de\/wordpress\/10-buchsaiten-blogparade\/#primaryimage"},"thumbnailUrl":"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2018\/12\/buchsaeiten-blogparade.png","datePublished":"2018-12-19T13:35:31+00:00","dateModified":"2018-12-19T15:09:36+00:00","description":"Es ist mal wieder Zeit, um das Jahr Revue passieren zu lassen. Bei dieser Blogparade geht es um die B\u00fccher des Jahres 2018.","breadcrumb":{"@id":"https:\/\/leckerekekse.de\/wordpress\/10-buchsaiten-blogparade\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/leckerekekse.de\/wordpress\/10-buchsaiten-blogparade\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/leckerekekse.de\/wordpress\/10-buchsaiten-blogparade\/#primaryimage","url":"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2018\/12\/buchsaeiten-blogparade.png","contentUrl":"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2018\/12\/buchsaeiten-blogparade.png","width":640,"height":430},{"@type":"BreadcrumbList","@id":"https:\/\/leckerekekse.de\/wordpress\/10-buchsaiten-blogparade\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/leckerekekse.de\/wordpress\/"},{"@type":"ListItem","position":2,"name":"10. BuchSaiten-Blogparade"}]},{"@type":"WebSite","@id":"https:\/\/leckerekekse.de\/wordpress\/#website","url":"https:\/\/leckerekekse.de\/wordpress\/","name":"Leckere Kekse &amp; mehr","description":"Kekse backen, B\u00fccher lesen und mehr","publisher":{"@id":"https:\/\/leckerekekse.de\/wordpress\/#\/schema\/person\/72061e7e8c1c70c8e8e542a13e5acbfe"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/leckerekekse.de\/wordpress\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/leckerekekse.de\/wordpress\/#\/schema\/person\/72061e7e8c1c70c8e8e542a13e5acbfe","name":"Astrid","logo":{"@id":"https:\/\/leckerekekse.de\/wordpress\/#\/schema\/person\/image\/"},"sameAs":["https:\/\/leckerekekse.de\/wordpress"]}]}},"_links":{"self":[{"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/posts\/12691","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/comments?post=12691"}],"version-history":[{"count":3,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/posts\/12691\/revisions"}],"predecessor-version":[{"id":12786,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/posts\/12691\/revisions\/12786"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/media\/12693"}],"wp:attachment":[{"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/media?parent=12691"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/categories?post=12691"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/tags?post=12691"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}