{"id":14768,"date":"2019-12-18T16:16:00","date_gmt":"2019-12-18T15:16:00","guid":{"rendered":"https:\/\/leckerekekse.de\/wordpress\/?p=14768"},"modified":"2020-01-02T18:30:06","modified_gmt":"2020-01-02T17:30:06","slug":"nadine-schneider-drei-kilometer","status":"publish","type":"post","link":"https:\/\/leckerekekse.de\/wordpress\/nadine-schneider-drei-kilometer\/","title":{"rendered":"Nadine Schneider: Drei Kilometer"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"427\" src=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2019\/12\/nadine-schneider-drei-kilometer-rezension-640x427.jpg\" alt=\"Nadine Schneider: Drei Kilometer, Jung und Jung, Bloggerpreis, Deb\u00fctroman\" class=\"wp-image-14770\" srcset=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2019\/12\/nadine-schneider-drei-kilometer-rezension.jpg 640w, https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2019\/12\/nadine-schneider-drei-kilometer-rezension-300x200.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Rezension Deb\u00fctroman<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Nur drei Kilometer ist die Grenze entfernt von dem kleinen Dorf, in dem Anna mit ihrer Familie lebt. Im Sommer 1989 denken viele Rum\u00e4nen an Flucht aus ihrem Land. Denn das Leben unter dem Diktator Ceau\u0219escu ist kein Zuckerschlecken. Die Wirtschaft liegt am Boden, der Bev\u00f6lkerung fehlt es an allem, viele hungern, vor allem die Menschen in der Stadt. Nadine Schneider beschreibt in ihrem Deb\u00fctroman die letzten Monate in Rum\u00e4nien unter Ceau\u0219escu<\/p>\n\n\n\n<!--more-->\n\n\n\n<h3 class=\"wp-block-heading\">Gehen oder bleiben?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Alle denken an Flucht in diesen Zeiten in Rum\u00e4nien. Bis zur Grenze erstrecken sich im Herbst hohe Maisfelder, \u00fcber zwei Meter hoch stehen die Pflanzen und w\u00fcrden dadurch Deckung bieten. Doch soll Anna es wirklich wagen? Was erwartet sie in der Fremde? Was ist mit ihren Freunden? Ihren Eltern? Ihrer greisen Gro\u00dfmutter?<br>Eigentlich m\u00f6chte sie gar nicht weg. Wenn die Zeiten nicht so hart w\u00e4ren, w\u00fcrde sie lieber bleiben wollen. Der Hof, die Tiere, die Familie und Nachbarschaft. Die Sonne im Sommer und die K\u00e4lte im Winter. Sie liebt die Landschaft und das kleine Dorf. Doch das Leben in Rum\u00e4nien ist, gerade als junger Mensch mit Tr\u00e4umen, kaum auszuhalten. <br>Doch was sind Annas Tr\u00e4ume? Sie will mit den Menschen zusammen sein, die ihr wichtig sind. So auch ihr Freund Hans und Misch, ein gemeinsamer Freund des Paares. Die jungen M\u00e4nner sprechen viel von Flucht. Anna will nicht weg. <\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Ich frage mich, warum uns das nicht reichte. Warum es uns nicht reichte, dass wir alle hier waren und an manchen Abenden eine gute Suppe a\u00dfen. <\/p><cite> S. 23 <\/cite><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Anna ist so bodenst\u00e4ndig, so bescheiden, doch auch ohne Visionen.<br>Zur Flucht braucht es Mut, zum Bleiben aber auch.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Dreierbeziehung<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Auf der ersten Seite dachte ich direkt: Anna ist mit Misch zusammen, sie liebt ihn. Doch Hans ist ihr Partner. Hans und Misch sind beste Freunde. Anna liebt auch Hans. Vor allem liebt sie die Best\u00e4ndigkeit. Eigentlich will sie keine drastischen Ver\u00e4nderungen.<br>Hans und Misch: sie sch\u00e4tzen einander sehr, fangen aber irgendwann an einander zu misstrauen. Vielleicht wegen Anna? <br>Hans und Misch: beide lieben Anna. Beide wollen mit ihr fliehen, aber nur zu zweit. Ist einer von ihnen ein Milizspitzel? Wem kann man noch trauen? <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Mais<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Das Maisfeld steht f\u00fcr die Verhei\u00dfung von Freiheit. Doch was genau wartet dahinter, hinter der Grenze? Nicht nur die Gefahr erwischt zu werden, sondern auch die Ungewissheiten die nach einer gegl\u00fcckten Flucht lauern. Anna ist klar, dass Deutschland nicht gerade auf sie wartet. Auch dort wird sie kein Abitur machen k\u00f6nnen, wird Hans nicht studieren k\u00f6nnen. Auch dort m\u00fcssen sie um ihren Lebensunterhalt k\u00e4mpfen. Was kommt, wenn sie alles Gewohnte hinter sich l\u00e4sst? Die Familie, das Dorf, die Feste, die Landschaft?<br>Doch viel Zeit bleibt nicht. Nach der Maisernte wird die Flucht nahezu unm\u00f6glich. Der Tag der Maisernte hei\u00dft dort Kukruzbrechen:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Fr\u00fcher hie\u00df das einen ganzen Tag Arbeit, und am Abend sch\u00e4lte man Maiskolben und erz\u00e4hlte dabei Geschichten. Heute klang das Wort wie eine zufallende T\u00fcr. <\/p><cite> S. 68 <\/cite><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Mit der Maisernte geht die T\u00fcr zur m\u00f6glichen Flucht zu. Also\nm\u00fcssen sie sich entscheiden: Misch, Hans und auch Anna.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"427\" height=\"640\" src=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2019\/12\/Deb\u00fctpreis4.jpg\" alt=\"Nadine Schneider: Drei Kilometer, Jung und Jung, Bloggerpreis, Deb\u00fctroman\" class=\"wp-image-14773\" srcset=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2019\/12\/Deb\u00fctpreis4.jpg 427w, https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2019\/12\/Deb\u00fctpreis4-200x300.jpg 200w\" sizes=\"auto, (max-width: 427px) 100vw, 427px\" \/><\/figure><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Mut zur L\u00fccke<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Dieser kleine Roman k\u00f6nnte auch viermal so dick sein. So sehr ist er reduziert. Von den eigentlich sehr dramatischen, historischen Ereignissen wird eigentlich keines wirklich beschrieben, weder die Demonstrationen, noch der Prozess der sp\u00e4ter Ceau\u0219escu und seiner Frau gemacht wird. Nicht die erzwungenen Besuche bei der Miliz, keine Fluchtgeschichten, nicht die Reise des Vater nach Deutschland. <br>Die St\u00e4rke dieses Romans liegt f\u00fcr mich in den Dingen, die nicht erz\u00e4hlt werden. Nadine Schneider konzentriert sich ganz auf die kleine Welt von Anna, die eigentlich nur zufrieden leben will. Der Tot einer Verwandten ist f\u00fcr sie wichtiger als Demos, Gewalt und Revolution in den Stra\u00dfen der Stadt. Denn das Dorf bleibt davon fast unber\u00fchrt. Wie eine kleine Insel.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Solche Tage erinnerten mich daran, dass noch eine Leichtigkeit in den Dingen steckte. Dass die Schwere sich nicht an alles geh\u00e4ngt hat. S. 25<\/p><cite> S. 68 <\/cite><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Anna ist nicht naiv. Nur bescheiden. Sie will nur an sch\u00f6nen\nDingen und Br\u00e4uchen festhalten. Alles soll bleiben wie es ist. Bitte nicht\nschlimmer. Aber viel besser muss es auch nicht sein, damit sie Gl\u00fcck erleben\nkann.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Stil<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Schneider benutzt eine unheimlich bildhafte Sprache. Ich sah alles vor mir: Ihr Zimmer, die Gro\u00dfmutter, die Fabrik und nat\u00fcrlich das Maisfeld. Ich konnte die K\u00e4lte des Winters sp\u00fcren, ebenso wie die W\u00e4rme des Sommers. <br>Es gibt immer wieder so sch\u00f6ne, aber auch einfache Formulierungen wie zum Beispiel diese \u00fcber Annas Vater<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>&#8230;er wirkte m\u00fcde. Nicht m\u00fcde von der Arbeit und wenig Schlaf, sondern m\u00fcde von der Zeit. <\/p><cite> S. 100 <\/cite><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">So sch\u00f6n: M\u00fcde von der Zeit. Eine wunderbare Formulierung.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Geschichte<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">1989 war auch in Deutschland ein Jahr der gro\u00dfen Ver\u00e4nderungen. Im November fiel die Mauer. &#8222;Drei Kilometer&#8220; spielt zur gleichen Zeit. An vielen Deutschen sind die Ver\u00e4nderungen in Rum\u00e4nien vielleicht vorbeigegangen, weil sie selbst mit einem neuen Leben konfrontiert waren. Ich erinnere mich dunkel an den Prozess und die Hinrichtung Ceau\u0219escus. Es erinnerte mich stark an den Tod der Zarenfamilie 1918. Es lohnt, da mal nachzuforschen. So kann man die Ereignisse besser in einen historischen Kontext setzen.<br>Ich habe mich im Buch auch sehr \u00fcber die deutschen Namen gewundert. Als n\u00e4chstes werde ich mich noch \u00fcber Banat und die Rum\u00e4niendeutschen informieren. Auch ein Thema, \u00fcber das ich fast nichts wei\u00df.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"426\" src=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2019\/12\/Schneider6218\u00a9Laurin-Gutwin-640x426.jpg\" alt=\"Nadine Schneider: Drei Kilometer, Jung und Jung, Bloggerpreis, Deb\u00fctroman\" class=\"wp-image-14771\" srcset=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2019\/12\/Schneider6218\u00a9Laurin-Gutwin.jpg 640w, https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2019\/12\/Schneider6218\u00a9Laurin-Gutwin-300x200.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><figcaption>Copyright: Laurin Gutwin<\/figcaption><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Autorin<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/nadine-schneider-autorin.com\/\">Nadine Schneider<\/a> ist knapp 30 Jahre alt und lebt in Berlin. Sie studierte Musikwissenschaft und Germanistik. Bisher sind von ihr bereits Kurzgeschichten in Anthologien erschienen. &#8222;Drei Kilometer&#8220; ist ihr erster Roman und bekam f\u00fcr Ausz\u00fcge daraus bereits einen Literaturpreis. Ihre Eltern sind rum\u00e4nische Auswanderer, dadurch wurde sie wohl auch zu diesem Buch inspiriert. Bei <a href=\"https:\/\/www.zehnseiten.de\/de\/buecher\/detail\/nadine-schneider-drei-kilometer-733.html\">Zehn Seiten<\/a> liest sie ein St\u00fcck aus ihrem Buch vor.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Bloggerpeis<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Dieser Roman steht auf der Shortlist des Bloggerpreises f\u00fcr das beste Deb\u00fct des Jahres 2019, der vom Blog &#8222;Das Deb\u00fct&#8220; ausgelobt wird. Die Jury, zu der auch ich geh\u00f6re, besteht aus freiwilligen Literaturbloggern. Folgende Romane stehen ebenfalls auf der Shortlist:<br><a href=\"https:\/\/leckerekekse.de\/wordpress\/angela-lehner-vater-unser\/\">Angela Lehner: Vater unser<\/a><br><a href=\"https:\/\/leckerekekse.de\/wordpress\/martin-peichl-wie-man-dinge-repariert\/\">Martin Peichl: Wie man Dinge repariert<\/a><br><a rel=\"noreferrer noopener\" aria-label=\"Katharina Mevissen \u2013 Ich kann dich h\u00f6ren (\u00f6ffnet in neuem Tab)\" href=\"https:\/\/leckerekekse.de\/wordpress\/katharina-mevissen-ich-kann-dich-hoeren\/\" target=\"_blank\">Katharina Mevissen \u2013 Ich kann dich h\u00f6ren<\/a><br><a href=\"https:\/\/leckerekekse.de\/wordpress\/ana-marwan-der-kreis-des-weberknechts\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"Ana Marwan \u2013 Der Kreis des Weberknechts (\u00f6ffnet in neuem Tab)\">Ana Marwan \u2013 Der Kreis des Weberknechts<\/a><\/p>\n\n\n\n<figure class=\"wp-block-image size-medium\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"219\" src=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2016\/04\/Signatur-002-300x219.jpg\" alt=\"\" class=\"wp-image-5977\" srcset=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2016\/04\/Signatur-002-300x219.jpg 300w, https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2016\/04\/Signatur-002.jpg 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Rezension Deb\u00fctroman Nur drei Kilometer ist die Grenze entfernt von dem kleinen Dorf, in dem Anna mit ihrer Familie lebt. Im Sommer 1989 denken viele Rum\u00e4nen an Flucht aus ihrem Land. Denn das Leben unter dem Diktator Ceau\u0219escu ist kein Zuckerschlecken. Die Wirtschaft liegt am Boden, der Bev\u00f6lkerung fehlt es an allem, viele hungern, vor [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":14770,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,3,788],"tags":[57,1072,1269],"class_list":["post-14768","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-buecher","category-rezension","tag-debuet","tag-debuetroman","tag-rumaenien"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nadine Schneider: Drei Kilometer | Leckere Kekse &amp; mehr<\/title>\n<meta name=\"description\" content=\"Der Deb\u00fctroman von nadine Schnedier &quot;Drei Kilometer&quot; handelt vom Dilemma einer jungen Frau in Rum\u00e4nien 1986. Flucht oder Bleiben?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/leckerekekse.de\/wordpress\/nadine-schneider-drei-kilometer\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nadine Schneider: Drei Kilometer | Leckere Kekse &amp; mehr\" \/>\n<meta property=\"og:description\" content=\"Der Deb\u00fctroman von nadine Schnedier &quot;Drei Kilometer&quot; handelt vom Dilemma einer jungen Frau in Rum\u00e4nien 1986. Flucht oder Bleiben?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/leckerekekse.de\/wordpress\/nadine-schneider-drei-kilometer\/\" \/>\n<meta property=\"og:site_name\" content=\"Leckere Kekse &amp; mehr\" \/>\n<meta property=\"article:published_time\" content=\"2019-12-18T15:16:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-01-02T17:30:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2019\/12\/nadine-schneider-drei-kilometer-rezension.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"427\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Buchlieberin\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Buchlieberin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/nadine-schneider-drei-kilometer\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/nadine-schneider-drei-kilometer\\\/\"},\"author\":{\"name\":\"Buchlieberin\",\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/2374d41b5cda28a27f6924e58f3afcc2\"},\"headline\":\"Nadine Schneider: Drei Kilometer\",\"datePublished\":\"2019-12-18T15:16:00+00:00\",\"dateModified\":\"2020-01-02T17:30:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/nadine-schneider-drei-kilometer\\\/\"},\"wordCount\":1085,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/72061e7e8c1c70c8e8e542a13e5acbfe\"},\"image\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/nadine-schneider-drei-kilometer\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/nadine-schneider-drei-kilometer-rezension.jpg\",\"keywords\":[\"Deb\u00fct\",\"Deb\u00fctroman\",\"Rum\u00e4nien\"],\"articleSection\":{\"1\":\"B\u00fccher\",\"2\":\"Rezension\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/nadine-schneider-drei-kilometer\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/nadine-schneider-drei-kilometer\\\/\",\"url\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/nadine-schneider-drei-kilometer\\\/\",\"name\":\"Nadine Schneider: Drei Kilometer | Leckere Kekse &amp; mehr\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/nadine-schneider-drei-kilometer\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/nadine-schneider-drei-kilometer\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/nadine-schneider-drei-kilometer-rezension.jpg\",\"datePublished\":\"2019-12-18T15:16:00+00:00\",\"dateModified\":\"2020-01-02T17:30:06+00:00\",\"description\":\"Der Deb\u00fctroman von nadine Schnedier \\\"Drei Kilometer\\\" handelt vom Dilemma einer jungen Frau in Rum\u00e4nien 1986. Flucht oder Bleiben?\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/nadine-schneider-drei-kilometer\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/nadine-schneider-drei-kilometer\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/nadine-schneider-drei-kilometer\\\/#primaryimage\",\"url\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/nadine-schneider-drei-kilometer-rezension.jpg\",\"contentUrl\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/nadine-schneider-drei-kilometer-rezension.jpg\",\"width\":640,\"height\":427},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/nadine-schneider-drei-kilometer\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nadine Schneider: Drei Kilometer\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#website\",\"url\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/\",\"name\":\"Leckere Kekse &amp; mehr\",\"description\":\"Kekse backen, B\u00fccher lesen und mehr\",\"publisher\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/72061e7e8c1c70c8e8e542a13e5acbfe\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/72061e7e8c1c70c8e8e542a13e5acbfe\",\"name\":\"Astrid\",\"logo\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/leckerekekse.de\\\/wordpress\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/2374d41b5cda28a27f6924e58f3afcc2\",\"name\":\"Buchlieberin\",\"sameAs\":[\"https:\\\/\\\/leckerekekse.de\\\/wordpress\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nadine Schneider: Drei Kilometer | Leckere Kekse &amp; mehr","description":"Der Deb\u00fctroman von nadine Schnedier \"Drei Kilometer\" handelt vom Dilemma einer jungen Frau in Rum\u00e4nien 1986. Flucht oder Bleiben?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/leckerekekse.de\/wordpress\/nadine-schneider-drei-kilometer\/","og_locale":"de_DE","og_type":"article","og_title":"Nadine Schneider: Drei Kilometer | Leckere Kekse &amp; mehr","og_description":"Der Deb\u00fctroman von nadine Schnedier \"Drei Kilometer\" handelt vom Dilemma einer jungen Frau in Rum\u00e4nien 1986. Flucht oder Bleiben?","og_url":"https:\/\/leckerekekse.de\/wordpress\/nadine-schneider-drei-kilometer\/","og_site_name":"Leckere Kekse &amp; mehr","article_published_time":"2019-12-18T15:16:00+00:00","article_modified_time":"2020-01-02T17:30:06+00:00","og_image":[{"width":640,"height":427,"url":"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2019\/12\/nadine-schneider-drei-kilometer-rezension.jpg","type":"image\/jpeg"}],"author":"Buchlieberin","twitter_misc":{"Verfasst von":"Buchlieberin","Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/leckerekekse.de\/wordpress\/nadine-schneider-drei-kilometer\/#article","isPartOf":{"@id":"https:\/\/leckerekekse.de\/wordpress\/nadine-schneider-drei-kilometer\/"},"author":{"name":"Buchlieberin","@id":"https:\/\/leckerekekse.de\/wordpress\/#\/schema\/person\/2374d41b5cda28a27f6924e58f3afcc2"},"headline":"Nadine Schneider: Drei Kilometer","datePublished":"2019-12-18T15:16:00+00:00","dateModified":"2020-01-02T17:30:06+00:00","mainEntityOfPage":{"@id":"https:\/\/leckerekekse.de\/wordpress\/nadine-schneider-drei-kilometer\/"},"wordCount":1085,"commentCount":1,"publisher":{"@id":"https:\/\/leckerekekse.de\/wordpress\/#\/schema\/person\/72061e7e8c1c70c8e8e542a13e5acbfe"},"image":{"@id":"https:\/\/leckerekekse.de\/wordpress\/nadine-schneider-drei-kilometer\/#primaryimage"},"thumbnailUrl":"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2019\/12\/nadine-schneider-drei-kilometer-rezension.jpg","keywords":["Deb\u00fct","Deb\u00fctroman","Rum\u00e4nien"],"articleSection":{"1":"B\u00fccher","2":"Rezension"},"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/leckerekekse.de\/wordpress\/nadine-schneider-drei-kilometer\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/leckerekekse.de\/wordpress\/nadine-schneider-drei-kilometer\/","url":"https:\/\/leckerekekse.de\/wordpress\/nadine-schneider-drei-kilometer\/","name":"Nadine Schneider: Drei Kilometer | Leckere Kekse &amp; mehr","isPartOf":{"@id":"https:\/\/leckerekekse.de\/wordpress\/#website"},"primaryImageOfPage":{"@id":"https:\/\/leckerekekse.de\/wordpress\/nadine-schneider-drei-kilometer\/#primaryimage"},"image":{"@id":"https:\/\/leckerekekse.de\/wordpress\/nadine-schneider-drei-kilometer\/#primaryimage"},"thumbnailUrl":"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2019\/12\/nadine-schneider-drei-kilometer-rezension.jpg","datePublished":"2019-12-18T15:16:00+00:00","dateModified":"2020-01-02T17:30:06+00:00","description":"Der Deb\u00fctroman von nadine Schnedier \"Drei Kilometer\" handelt vom Dilemma einer jungen Frau in Rum\u00e4nien 1986. Flucht oder Bleiben?","breadcrumb":{"@id":"https:\/\/leckerekekse.de\/wordpress\/nadine-schneider-drei-kilometer\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/leckerekekse.de\/wordpress\/nadine-schneider-drei-kilometer\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/leckerekekse.de\/wordpress\/nadine-schneider-drei-kilometer\/#primaryimage","url":"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2019\/12\/nadine-schneider-drei-kilometer-rezension.jpg","contentUrl":"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2019\/12\/nadine-schneider-drei-kilometer-rezension.jpg","width":640,"height":427},{"@type":"BreadcrumbList","@id":"https:\/\/leckerekekse.de\/wordpress\/nadine-schneider-drei-kilometer\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/leckerekekse.de\/wordpress\/"},{"@type":"ListItem","position":2,"name":"Nadine Schneider: Drei Kilometer"}]},{"@type":"WebSite","@id":"https:\/\/leckerekekse.de\/wordpress\/#website","url":"https:\/\/leckerekekse.de\/wordpress\/","name":"Leckere Kekse &amp; mehr","description":"Kekse backen, B\u00fccher lesen und mehr","publisher":{"@id":"https:\/\/leckerekekse.de\/wordpress\/#\/schema\/person\/72061e7e8c1c70c8e8e542a13e5acbfe"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/leckerekekse.de\/wordpress\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/leckerekekse.de\/wordpress\/#\/schema\/person\/72061e7e8c1c70c8e8e542a13e5acbfe","name":"Astrid","logo":{"@id":"https:\/\/leckerekekse.de\/wordpress\/#\/schema\/person\/image\/"},"sameAs":["https:\/\/leckerekekse.de\/wordpress"]},{"@type":"Person","@id":"https:\/\/leckerekekse.de\/wordpress\/#\/schema\/person\/2374d41b5cda28a27f6924e58f3afcc2","name":"Buchlieberin","sameAs":["https:\/\/leckerekekse.de\/wordpress"]}]}},"_links":{"self":[{"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/posts\/14768","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/comments?post=14768"}],"version-history":[{"count":3,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/posts\/14768\/revisions"}],"predecessor-version":[{"id":14836,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/posts\/14768\/revisions\/14836"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/media\/14770"}],"wp:attachment":[{"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/media?parent=14768"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/categories?post=14768"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/tags?post=14768"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}