{"id":15463,"date":"2020-07-19T08:38:00","date_gmt":"2020-07-19T06:38:00","guid":{"rendered":"https:\/\/leckerekekse.de\/wordpress\/?p=15463"},"modified":"2020-07-18T15:38:28","modified_gmt":"2020-07-18T13:38:28","slug":"ian-mcewan-maschinen-wie-ich","status":"publish","type":"post","link":"https:\/\/leckerekekse.de\/wordpress\/ian-mcewan-maschinen-wie-ich\/","title":{"rendered":"Ian McEwan: Maschinen wie ich"},"content":{"rendered":"\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"480\" src=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2020\/07\/rezension-maschinen-mcewan.jpg\" alt=\"Rezension Maschinen wie ich, Menschen wie ihr von Ian McEwan\" class=\"wp-image-15464\" srcset=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2020\/07\/rezension-maschinen-mcewan.jpg 640w, https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2020\/07\/rezension-maschinen-mcewan-300x225.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Wer ist \u00fcberlegen, Mensch oder Maschine?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Wir befinden uns im Jahr 1982 in Gro\u00dfbritannien. Margaret Thatcher ist an der Macht, der Falklandkrieg bahnt sich an. Soweit, so bekannt. Doch im Roman &#8222;Maschinen wie ich&#8220; von Ian McEwan ist vieles anders, als ich es aus meiner Teenagerzeit in Erinnerung habe. Das Buch ist eine Art r\u00fcckw\u00e4rtsgerichteter Si-Fi-Roman. Denn die Technologie, insbesondere alles rund um Computer, Soft- und Hardware ist sehr weit fortgeschritten. Das Setting des Romans hat uns schon einiges voraus. So gibt es jetzt die ersten Androiden zu kaufen, die vom Menschen kaum noch zu unterscheiden sind.<\/p>\n\n\n\n<!--more-->\n\n\n\n<h3 class=\"wp-block-heading\">Story<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Charlie ist so etwas drei\u00dfig Jahre alt und steckt sein ganzes restliches Geld in den Erwerb von Adam, einer der ersten Androiden, die wirklich technisch sehr ausgereift sind. Insgesamt gibt es weltweit nur 25 davon, 12 Adams und 13 Eves. Genaue Pl\u00e4ne hat er damit nicht. So im Hinterkopf hofft er aber durch Adam, \u00e4hnlich wie bei einem gemeinsamen Kind, seine geliebte Nachbarin Miranda zu beeindrucken und an ihn zu binden. Adam bietet viel Chancen, aber auch Risiken. So kann er alle Datenbaken der Welt sekundenschnell durchforsten, h\u00e4lt mit Informationen auch nicht hinter dem Berg. Auch nicht mit Dingen, die Charlie lieber nicht wissen m\u00f6chte.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Maschinen wie ihr<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">So geht es also nicht um Technik, sondern um Beziehungen und Vergangenheitsaufarbeitung, denn Miranda hat da so ihre Geheimnisse.<br>Und es geht um Moral. Wie kann man eine Maschine, die Adam ja ist, von einem richtigen Menschen unterscheiden? Was macht den Unterschied wirklich aus? Und ist der Mensch nicht der Unterlegene? Adam ist schlauer, schneller, kr\u00e4ftiger. Auch sonst hat er erstaunliche F\u00e4higkeiten und lernt, als k\u00fcnstliche Intelligenz (KI) immer mehr dazu. So denkt er lange \u00fcber Literatur nach (er kann ja blitzschnell mal alles nachlesen) und kommt zu dem Schluss, dass die einzige Literaturform die das Zeug hat weiterhin Bestand zu haben, der Haiku ist. Fortan dichtet er fr\u00f6hlich vor sich hin.<br>Ein Merkmal von k\u00fcnstlicher Intelligenz ist ja, dass sie sich selbstst\u00e4ndig macht, indem sie immer mehr lernt und sich selbst dadurch verbessert. Daran arbeitet auch Adam.<br>Aber wie sieht es mit seiner Moral aus? Ist er da auch \u00fcberlegen?\u00a0 Vielleicht das zentrale Thema des Buches. Doch daf\u00fcr m\u00fcsste ich vielmehr vom Inhalt erz\u00e4hlen als ich das jetzt m\u00f6chte.<br>Und k\u00f6nnen die Maschinen Gef\u00fchle haben? Zumindest behauptet Adam, dass er sich verliebt hat.<br>Au\u00dferdem begehen einige der anderen ausgelieferten Androiden eine Art Selbstmord, weil sie ihre Existenz so nicht ertragen k\u00f6nnen.<br>Ich f\u00fchlte mich oft sehr an die Serie \u201eReal Humans\u201c erinnert.<br>Irritiert hat mich allerdings, dass der Roman aus der Sicht von Charlie, nicht aus der Adams geschrieben ist. Diese Erwartung hat der Titel bei mir geweckt.<br>Vielleicht hatte ich deshalb Probleme mir diesen zu merken? Ich dachte statt \u201eMaschinen wie ich, Menschen wie ihr\u201c immer an &#8222;Maschinen wie ihr, Menschen wie wir\u201c.<br>Allerdings w\u00e4re ein Roman aus Adams Sicht f\u00fcr uns Menschen nicht lesbar, aufgrund seiner starken intellektuellen \u00dcberlegenheit.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"480\" src=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2020\/07\/ian-mcewan-maschinen-wie-ich-rezension.jpg\" alt=\"Rezension Maschinen wie ich, Menschen wie ihr von Ian McEwan\" class=\"wp-image-15465\" srcset=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2020\/07\/ian-mcewan-maschinen-wie-ich-rezension.jpg 640w, https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2020\/07\/ian-mcewan-maschinen-wie-ich-rezension-300x225.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Erfundene Vergangenheit<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Ich habe bis zur H\u00e4lfte des Buches herumger\u00e4tselt, warum McEwan das Buch in einer ver\u00e4nderten Vergangenheit spielen l\u00e4sst. Und mir dann doch noch einen Reim darauf gemacht, der f\u00fcr mich Sinn macht und die Konstruktion des Romans dadurch ganz wunderbar wird.<br>Denn es ist auch Roman \u00fcber <a href=\"https:\/\/de.wikipedia.org\/wiki\/Alan_Turing\">Alan Turing<\/a>. Der Mathematiker hatte schon in der ersten H\u00e4lfte des 20. Jahrhunderts viele, zum Teil noch sehr theoretische, \u00dcberlegungen im Bereich der Informatik ver\u00f6ffentlicht. In unserer Realit\u00e4t ist Turing nach einer chemischen Kastration (er war homosexuell, das war 1950 strafbar und galt als eine Art Geisteskrankheit) bereits 1952 gestorben. In der Welt dieses Romans hat er diese Medikamente abgelehnt, einige Zeit im Gef\u00e4ngnis verbracht und weiter geforscht. Allein druch sein \u00dcberleben und durch die Zusammenarbeit mit weiteren Genies hat sich die Informatik viel schneller entwickelt. So verlor zum Beispiel in diesem Roman Gro\u00dfbritannien den Falklandkrieg, weil die Gegner computergesteuerte Fernlenkraketen mit ungeheurer Treffgenauigkeit hatten. Und so hat sie die Technologie der KI viel schneller entwickelt.<br>Deshalb spielt der Roman in den 1980iger Jahren, weil Turing da noch leben k\u00f6nnte und es im Buch auch so ist. Es gibt sogar zwei Begegnungen zwischen Charlie und ihm.<br>Besonders die letzte, ganz am Ende des Buches, stellt die Moralfrage nochmal ganz auf den Kopf. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Alter Bekannter<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Ian McEwan ist ein sehr bekannter Autor, und auch ich habe schon einiges von ihm gelesen. Allerdings stehe ich seinem Werk sehr ambivalent gegen\u00fcber. Sein vielleicht erfolgreichstes Werk ist <em>Abbitte<\/em>. Die Mitglieder meines Lesekreises waren hingerissen von Abbitte. Ich nicht. Diesen Roman habe ich drei Mal begonnen und drei Mal abgebrochen. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"428\" src=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2020\/07\/ian-mcean-romane.jpg\" alt=\"Romane von Ian McEwan: Saturday, am Strand, Kindeswohl, Honig\" class=\"wp-image-15466\" srcset=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2020\/07\/ian-mcean-romane.jpg 640w, https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2020\/07\/ian-mcean-romane-300x201.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Dagegen fand ich Saturday einfach gro\u00dfartig. Ebenso <a href=\"https:\/\/leckerekekse.de\/wordpress\/rezension-am-strand-von-ian-mcewan\/\">Am Strand<\/a> (On Chesil Beach), dass ich sogar im Original gelesen habe. <a href=\"https:\/\/leckerekekse.de\/wordpress\/winternachlese\/\">Kindeswohl<\/a> und <em>Honig<\/em> habe ich gerne gelesen, mich aber nicht vom Hocker gerissen. <a href=\"https:\/\/leckerekekse.de\/wordpress\/nussschale\/\">Nussschale<\/a> habe ich erst begonnen zu lesen, abgebrochen und als H\u00f6rbuch neu begonnen, das war vorgelesen in meinen Ohren dann wieder gro\u00dfartig.<br>Deshalb habe ich auch bei &#8222;Maschinen wie ich etwas&#8220; gez\u00f6gert bis ich es begonnen habe. Astrid hat es abgebrochen, sie fand diese erfundene Historie zu seltsam. Den Eindruck hatte ich Anfangs auch, bis ich es mir halt durch meine Turing-Theorie erkl\u00e4ren konnte.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Fazit<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.diogenes.ch\/leser\/titel\/ian-mcewan\/maschinen-wie-ich-9783257070682.html\">Maschinen wie ich<\/a> ist f\u00fcr mich ein gro\u00dfartiger Roman, der mit Realit\u00e4t, Vergangenheit und Gegenwart spielt. Er wirft gro\u00dfe Fragen auf, wie nach der Moral und der \u00dcberlegenheit der Menschheit. Werden wir uns selbst durch unsere Technologie \u00fcberfl\u00fcssig machen? Ich hatte viel Stoff zum Nachdenken, so wie ich es liebe an einem guten Buch.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Weitere B\u00fccher \u00fcber KI<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Besprochen habe ich zu diesem Thema:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/leckerekekse.de\/wordpress\/hoertagebuch-tyrannei-des-schmetterlings\/\">Tyrannei des Schmetterlings<\/a> von Frank Sch\u00e4tzing. Hier gibt es ein mehrteiliges H\u00f6rtagebuch auf dem Blog.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/leckerekekse.de\/wordpress\/rezension-hologrammatica\/\">Hologrammatica<\/a> von Tom Hillenbrand. Vielleicht eher ein Buch \u00fcber eine Zeit nach k\u00fcnstlicher Intelligenz. Supercomputer sind hier n\u00e4mlich verboten, nachdem einer Menschheit durch einen von ihm freigesetzten Virus halbiert hat. Also gibt es einen tollen Bezug zu unserer jetzigen Realit\u00e4t.<\/p>\n\n\n\n<figure class=\"wp-block-image size-medium\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"219\" src=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2016\/04\/Signatur-002-300x219.jpg\" alt=\"\" class=\"wp-image-5977\" srcset=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2016\/04\/Signatur-002-300x219.jpg 300w, https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2016\/04\/Signatur-002.jpg 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Wer ist \u00fcberlegen, Mensch oder Maschine? Wir befinden uns im Jahr 1982 in Gro\u00dfbritannien. Margaret Thatcher ist an der Macht, der Falklandkrieg bahnt sich an. Soweit, so bekannt. Doch im Roman &#8222;Maschinen wie ich&#8220; von Ian McEwan ist vieles anders, als ich es aus meiner Teenagerzeit in Erinnerung habe. Das Buch ist eine Art r\u00fcckw\u00e4rtsgerichteter [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":15465,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,3,788],"tags":[1325,1326,1101],"class_list":["post-15463","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-buecher","category-rezension","tag-androide","tag-grossbritannien","tag-kuenstliche-intelligenz"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ian McEwan: Maschinen wie ich | Leckere Kekse &amp; mehr<\/title>\n<meta name=\"description\" content=\"Der neueste Roman von Ian McEwan befasst sich mit Androiden und ihrem Verh\u00e4ltnis zum Menschen. In Maschinen wie ich geht es auch im Moral. Rezension.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/leckerekekse.de\/wordpress\/ian-mcewan-maschinen-wie-ich\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ian McEwan: Maschinen wie ich | Leckere Kekse &amp; mehr\" \/>\n<meta property=\"og:description\" content=\"Der neueste Roman von Ian McEwan befasst sich mit Androiden und ihrem Verh\u00e4ltnis zum Menschen. In Maschinen wie ich geht es auch im Moral. Rezension.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/leckerekekse.de\/wordpress\/ian-mcewan-maschinen-wie-ich\/\" \/>\n<meta property=\"og:site_name\" content=\"Leckere Kekse &amp; mehr\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-19T06:38:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2020\/07\/ian-mcewan-maschinen-wie-ich-rezension.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Buchlieberin\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Buchlieberin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/ian-mcewan-maschinen-wie-ich\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/ian-mcewan-maschinen-wie-ich\\\/\"},\"author\":{\"name\":\"Buchlieberin\",\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/5bb66ddc2b49052f1ebd057189be9f35\"},\"headline\":\"Ian McEwan: Maschinen wie ich\",\"datePublished\":\"2020-07-19T06:38:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/ian-mcewan-maschinen-wie-ich\\\/\"},\"wordCount\":1018,\"commentCount\":5,\"publisher\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/2cf295e7c997b7e06628864ef88c1b3c\"},\"image\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/ian-mcewan-maschinen-wie-ich\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/ian-mcewan-maschinen-wie-ich-rezension.jpg\",\"keywords\":[\"Androide\",\"Gro\u00dfbritannien\",\"K\u00fcnstliche Intelligenz\"],\"articleSection\":{\"1\":\"B\u00fccher\",\"2\":\"Rezension\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/ian-mcewan-maschinen-wie-ich\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/ian-mcewan-maschinen-wie-ich\\\/\",\"url\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/ian-mcewan-maschinen-wie-ich\\\/\",\"name\":\"Ian McEwan: Maschinen wie ich | Leckere Kekse &amp; mehr\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/ian-mcewan-maschinen-wie-ich\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/ian-mcewan-maschinen-wie-ich\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/ian-mcewan-maschinen-wie-ich-rezension.jpg\",\"datePublished\":\"2020-07-19T06:38:00+00:00\",\"description\":\"Der neueste Roman von Ian McEwan befasst sich mit Androiden und ihrem Verh\u00e4ltnis zum Menschen. In Maschinen wie ich geht es auch im Moral. Rezension.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/ian-mcewan-maschinen-wie-ich\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/ian-mcewan-maschinen-wie-ich\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/ian-mcewan-maschinen-wie-ich\\\/#primaryimage\",\"url\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/ian-mcewan-maschinen-wie-ich-rezension.jpg\",\"contentUrl\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/ian-mcewan-maschinen-wie-ich-rezension.jpg\",\"width\":640,\"height\":480},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/ian-mcewan-maschinen-wie-ich\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ian McEwan: Maschinen wie ich\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#website\",\"url\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/\",\"name\":\"Leckere Kekse &amp; mehr\",\"description\":\"Kekse backen, B\u00fccher lesen und mehr\",\"publisher\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/2cf295e7c997b7e06628864ef88c1b3c\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/2cf295e7c997b7e06628864ef88c1b3c\",\"name\":\"Astrid\",\"logo\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/leckerekekse.de\\\/wordpress\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/5bb66ddc2b49052f1ebd057189be9f35\",\"name\":\"Buchlieberin\",\"sameAs\":[\"https:\\\/\\\/leckerekekse.de\\\/wordpress\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ian McEwan: Maschinen wie ich | Leckere Kekse &amp; mehr","description":"Der neueste Roman von Ian McEwan befasst sich mit Androiden und ihrem Verh\u00e4ltnis zum Menschen. In Maschinen wie ich geht es auch im Moral. Rezension.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/leckerekekse.de\/wordpress\/ian-mcewan-maschinen-wie-ich\/","og_locale":"de_DE","og_type":"article","og_title":"Ian McEwan: Maschinen wie ich | Leckere Kekse &amp; mehr","og_description":"Der neueste Roman von Ian McEwan befasst sich mit Androiden und ihrem Verh\u00e4ltnis zum Menschen. In Maschinen wie ich geht es auch im Moral. Rezension.","og_url":"https:\/\/leckerekekse.de\/wordpress\/ian-mcewan-maschinen-wie-ich\/","og_site_name":"Leckere Kekse &amp; mehr","article_published_time":"2020-07-19T06:38:00+00:00","og_image":[{"width":640,"height":480,"url":"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2020\/07\/ian-mcewan-maschinen-wie-ich-rezension.jpg","type":"image\/jpeg"}],"author":"Buchlieberin","twitter_misc":{"Verfasst von":"Buchlieberin","Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/leckerekekse.de\/wordpress\/ian-mcewan-maschinen-wie-ich\/#article","isPartOf":{"@id":"https:\/\/leckerekekse.de\/wordpress\/ian-mcewan-maschinen-wie-ich\/"},"author":{"name":"Buchlieberin","@id":"https:\/\/leckerekekse.de\/wordpress\/#\/schema\/person\/5bb66ddc2b49052f1ebd057189be9f35"},"headline":"Ian McEwan: Maschinen wie ich","datePublished":"2020-07-19T06:38:00+00:00","mainEntityOfPage":{"@id":"https:\/\/leckerekekse.de\/wordpress\/ian-mcewan-maschinen-wie-ich\/"},"wordCount":1018,"commentCount":5,"publisher":{"@id":"https:\/\/leckerekekse.de\/wordpress\/#\/schema\/person\/2cf295e7c997b7e06628864ef88c1b3c"},"image":{"@id":"https:\/\/leckerekekse.de\/wordpress\/ian-mcewan-maschinen-wie-ich\/#primaryimage"},"thumbnailUrl":"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2020\/07\/ian-mcewan-maschinen-wie-ich-rezension.jpg","keywords":["Androide","Gro\u00dfbritannien","K\u00fcnstliche Intelligenz"],"articleSection":{"1":"B\u00fccher","2":"Rezension"},"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/leckerekekse.de\/wordpress\/ian-mcewan-maschinen-wie-ich\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/leckerekekse.de\/wordpress\/ian-mcewan-maschinen-wie-ich\/","url":"https:\/\/leckerekekse.de\/wordpress\/ian-mcewan-maschinen-wie-ich\/","name":"Ian McEwan: Maschinen wie ich | Leckere Kekse &amp; mehr","isPartOf":{"@id":"https:\/\/leckerekekse.de\/wordpress\/#website"},"primaryImageOfPage":{"@id":"https:\/\/leckerekekse.de\/wordpress\/ian-mcewan-maschinen-wie-ich\/#primaryimage"},"image":{"@id":"https:\/\/leckerekekse.de\/wordpress\/ian-mcewan-maschinen-wie-ich\/#primaryimage"},"thumbnailUrl":"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2020\/07\/ian-mcewan-maschinen-wie-ich-rezension.jpg","datePublished":"2020-07-19T06:38:00+00:00","description":"Der neueste Roman von Ian McEwan befasst sich mit Androiden und ihrem Verh\u00e4ltnis zum Menschen. In Maschinen wie ich geht es auch im Moral. Rezension.","breadcrumb":{"@id":"https:\/\/leckerekekse.de\/wordpress\/ian-mcewan-maschinen-wie-ich\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/leckerekekse.de\/wordpress\/ian-mcewan-maschinen-wie-ich\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/leckerekekse.de\/wordpress\/ian-mcewan-maschinen-wie-ich\/#primaryimage","url":"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2020\/07\/ian-mcewan-maschinen-wie-ich-rezension.jpg","contentUrl":"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2020\/07\/ian-mcewan-maschinen-wie-ich-rezension.jpg","width":640,"height":480},{"@type":"BreadcrumbList","@id":"https:\/\/leckerekekse.de\/wordpress\/ian-mcewan-maschinen-wie-ich\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/leckerekekse.de\/wordpress\/"},{"@type":"ListItem","position":2,"name":"Ian McEwan: Maschinen wie ich"}]},{"@type":"WebSite","@id":"https:\/\/leckerekekse.de\/wordpress\/#website","url":"https:\/\/leckerekekse.de\/wordpress\/","name":"Leckere Kekse &amp; mehr","description":"Kekse backen, B\u00fccher lesen und mehr","publisher":{"@id":"https:\/\/leckerekekse.de\/wordpress\/#\/schema\/person\/2cf295e7c997b7e06628864ef88c1b3c"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/leckerekekse.de\/wordpress\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/leckerekekse.de\/wordpress\/#\/schema\/person\/2cf295e7c997b7e06628864ef88c1b3c","name":"Astrid","logo":{"@id":"https:\/\/leckerekekse.de\/wordpress\/#\/schema\/person\/image\/"},"sameAs":["https:\/\/leckerekekse.de\/wordpress"]},{"@type":"Person","@id":"https:\/\/leckerekekse.de\/wordpress\/#\/schema\/person\/5bb66ddc2b49052f1ebd057189be9f35","name":"Buchlieberin","sameAs":["https:\/\/leckerekekse.de\/wordpress"]}]}},"_links":{"self":[{"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/posts\/15463","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/comments?post=15463"}],"version-history":[{"count":3,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/posts\/15463\/revisions"}],"predecessor-version":[{"id":15472,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/posts\/15463\/revisions\/15472"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/media\/15465"}],"wp:attachment":[{"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/media?parent=15463"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/categories?post=15463"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/tags?post=15463"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}