{"id":15552,"date":"2020-09-06T08:13:00","date_gmt":"2020-09-06T06:13:00","guid":{"rendered":"https:\/\/leckerekekse.de\/wordpress\/?p=15552"},"modified":"2020-08-31T08:48:45","modified_gmt":"2020-08-31T06:48:45","slug":"buecher-ueber-fotografinnen","status":"publish","type":"post","link":"https:\/\/leckerekekse.de\/wordpress\/buecher-ueber-fotografinnen\/","title":{"rendered":"B\u00fccher \u00fcber Fotografinnen"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"853\" src=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2020\/08\/Buecher-Fotografinnen.jpg\" alt=\"Fotografinnen\" class=\"wp-image-15556\" srcset=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2020\/08\/Buecher-Fotografinnen.jpg 640w, https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2020\/08\/Buecher-Fotografinnen-225x300.jpg 225w, https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2020\/08\/Buecher-Fotografinnen-480x640.jpg 480w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Kommt es mir nur so vor oder h\u00f6rt ihr auch st\u00e4ndig davon? Von Koffern voller Fotos, die irgendwo auftauchen. Gerade war ich im Altonaer Museum in einer Fotoausstellung. Ein Hamburger hat in den 1930er Jahren viele Arbeiter im Hafen, in der B\u00f6rse, beim Fischhandel fotografiert. Bei jedem Umzug kam der Koffer mit den Fotos mit bis er vor kurzem von seinen Erben entdeckt wurde. Sch\u00f6ne Ausstellung!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aufgefallen sind mir in den letzten Monaten folgende B\u00fccher \u00fcber Fotografinnen. Warum eigentlich keins \u00fcber Fotografen? <\/p>\n\n\n\n<!--more-->\n\n\n\n<h2 class=\"wp-block-heading\">Christina Hesselholdt: Vivian<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Ein Roman \u00fcber die Stra\u00dfenfotografin Vivian Maier.<span class=\"Apple-converted-space\">&nbsp;<\/span><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"480\" src=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2020\/08\/Fotografin-vivian.jpg\" alt=\"Vivian\" class=\"wp-image-15557\" srcset=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2020\/08\/Fotografin-vivian.jpg 640w, https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2020\/08\/Fotografin-vivian-300x225.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Kennt die jemand? Ich hatte noch nie von ihr geh\u00f6rt.<span class=\"Apple-converted-space\">&nbsp;<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vivian (1926 &#8211; 2009) ist eine unscheinbare Frau, die die Fotografie liebt. St\u00e4ndig fotografiert sie, entwickelt werden ihre Filme aber selten. Sie ist viel zu sch\u00fcchtern, um nach Ruhm zu streben. Erst nach ihrem Tod werden ihre vielen Aufnahmen gefunden (in einem Koffer) und anerkannt. Und nun dieses Buch.<span class=\"Apple-converted-space\">&nbsp;<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Autorin Christina Hesselholdt versucht, die Fotografin n\u00e4her zu beschreiben. Es kommen ehemalige Arbeitgeber von Vivian zu Wort und auch ein Kind, dass sie betreut hat. Vivian kam aus einer armen Immigrantenfamilie, f\u00fcr eine teure Ausbildung war kein Geld da. Also arbeitete sie ihr ganzes Leben als Kinderm\u00e4dchen. Den Job nahm sie anscheinend nicht sehr ernst, denn auch w\u00e4hrend ihrer Arbeitszeit fotografierte sie. Manchmal versuchte sie, Bilder der betreuten Kinder an die Eltern zu verkaufen.<span class=\"Apple-converted-space\">&nbsp;<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Das Buch hat Interviewcharakter. St\u00e4ndig wechseln die Erz\u00e4hler, so dass kein richtiger Lesefluss aufkommen will bei mir. Vivian ist sch\u00fcchtern und erz\u00e4hlt nie von sich selbst. Ihre Arbeitgeber, bei denen sie teilweise jahrelang wohnt, wissen nichts von ihr. Da frage ich mich ehrlich gesagt mehr als einmal, wie man auf die Idee kommt, \u00fcber diese Fotografin ein Buch zu schreiben. Sie selbst h\u00e4tte sich sicher nicht daf\u00fcr begeistern k\u00f6nnen. Wenn sie selbst nichts \u00fcber ihre Familie erz\u00e4hlt, will sie es sicher auch in keinem Buch lesen. Ich bin hin und her gerissen. Ich lese gerne \u00fcber Fotografie und in diesem Roman gibt es zwar keine Fotos zu sehen, aber ein paar Fotohighlights werden beschrieben. Das gef\u00e4llt mir. Auch das Cover ist der Knaller. Genau mein Geschmack. Aber ganz ehrlich, die Familiengeschichte dieser eher unsympathischen Frau ist mir ziemlich egal!<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Helena Janeczek: Das M\u00e4dchen mit der Leica<\/h2>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"480\" src=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2020\/08\/das-maedchen-mit-der-leica-1.jpg\" alt=\"Das M\u00e4dchen mit der Leica\" class=\"wp-image-15559\" srcset=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2020\/08\/das-maedchen-mit-der-leica-1.jpg 640w, https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2020\/08\/das-maedchen-mit-der-leica-1-300x225.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Und auch f\u00fcr dieses Buch ist ein Koffer verantwortlich. Gefunden 2007 in New York. Die Fotografin Gerda Taro war in den 1940er Jahren bekannt. Zusammen mit ihrem Lebensgef\u00e4hrten Robert Capa (dieser Name sagt uns eher was) hat sie im Spanischen B\u00fcrgerkrieg fotografiert. Und dort ist sie auch t\u00f6dlich verungl\u00fcckt. Beerdigt ist sie in Paris.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Helena Janecek will uns in ihrem Buch diese engagierte und mutige Frau vorstellen. Auch sie l\u00e4sst ehemalige Freunde und Bekannte der Fotografin zu Wort kommen, allerdings nicht in Interviewform, sondern in ausf\u00fchrlichen, sehr ausschweifenden Texten.<span class=\"Apple-converted-space\">&nbsp;<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ich bin in keinen Lesefluss gekommen, habe zwar die H\u00e4lfte des Buches geschafft, aber mich dann gefragt, was ich bisher von dieser tollen Frau erfahren habe. Und ich hatte tats\u00e4chlich so gut wie keine Erinnerung an das bisher Gelesene. Also Abbruch! Echt schade, denn ich habe eine kurze Zusammenfassung von Taros Lebensgeschichte als Film gesehen und das war echt spannend.<span class=\"Apple-converted-space\">&nbsp;<\/span><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Sofia Lundberg: Ein halbes Herz<\/h2>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"480\" src=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2020\/08\/ein-halbes-herz.jpg\" alt=\"Ein halbes Herz\" class=\"wp-image-15560\" srcset=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2020\/08\/ein-halbes-herz.jpg 640w, https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2020\/08\/ein-halbes-herz-300x225.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">So ganz passt dieser Roman nicht zu den oberen beiden. Dieser ist n\u00e4mlich ein echter Roman, ohne Bezug zu einer realen Person. Aber ich m\u00f6chte ihn euch trotzdem vorstellen. Auch hier geht es um eine Fotografin. Eine erfolgreiche in New York. Elin lebt mit Mann und Tochter zusammen und arbeitet rund um die Uhr. Ihr Arbeitspensum belastet die Familie und es sieht nicht gut aus f\u00fcr ihre Ehe.<span class=\"Apple-converted-space\">&nbsp;<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Au\u00dferdem gibt es ein Geheimnis. Elin ist in Schweden aufgewachsen und davon ahnt ihre Familie nicht das geringste.<span class=\"Apple-converted-space\">&nbsp;<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Alles gute Zutaten f\u00fcr einen gelungenen Roman. Ich genie\u00dfe dieses Buch, bin in einem guten Lesefluss und freue mich immer, wenn ich Zeit habe zum Weiterlesen. Das war bei den oberen B\u00fcchern definitiv nicht der Fall. Erinnert ihr euch an \u201eDas rote Adressbuch\u201c? Wenn euch das gefallen hat, m\u00f6gt ihr \u201eEin halbes Herz\u201c auch.<span class=\"Apple-converted-space\">&nbsp;<\/span><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Mal was anderes?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Vielleicht brauche ich lesetechnisch gerade ein etwas anderes Genre als ich normalerweise lese? Einfach mal wieder eine gute Familiengeschichte, die in England in einem verwunschenen Cottage spielt und mit einem Geheimnis aufwarten kann? Ich glaube, das versuche ich mal.<span class=\"Apple-converted-space\">&nbsp;<\/span>Aber sicher werde ich weiterhin B\u00fccher \u00fcber Fotografinnen und auch Fotografen lesen. K\u00f6nnt ihr mir vielleicht welche empfehlen?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Und: Kennt ihr eins von diesen B\u00fcchern?<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"206\" height=\"97\" src=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2016\/04\/Scan-11.jpeg\" alt=\"\" class=\"wp-image-5966\"\/><\/figure><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Kommt es mir nur so vor oder h\u00f6rt ihr auch st\u00e4ndig davon? Von Koffern voller Fotos, die irgendwo auftauchen. Gerade war ich im Altonaer Museum in einer Fotoausstellung. Ein Hamburger hat in den 1930er Jahren viele Arbeiter im Hafen, in der B\u00f6rse, beim Fischhandel fotografiert. Bei jedem Umzug kam der Koffer mit den Fotos mit [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":15556,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,3,788],"tags":[1335,1334,1336,459],"class_list":["post-15552","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-buecher","category-rezension","tag-fotografien","tag-fotografin","tag-koffer","tag-roman"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>B\u00fccher \u00fcber Fotografinnen | Leckere Kekse &amp; mehr<\/title>\n<meta name=\"description\" content=\"Heute stelle ich euch drei B\u00fccher \u00fcber Fotografinnen vor. Zwei von den Frauen gab es wirklich, eine ist fiktiv. F\u00fcr mich ein spannendes Thema.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/leckerekekse.de\/wordpress\/buecher-ueber-fotografinnen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"B\u00fccher \u00fcber Fotografinnen | Leckere Kekse &amp; mehr\" \/>\n<meta property=\"og:description\" content=\"Heute stelle ich euch drei B\u00fccher \u00fcber Fotografinnen vor. Zwei von den Frauen gab es wirklich, eine ist fiktiv. F\u00fcr mich ein spannendes Thema.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/leckerekekse.de\/wordpress\/buecher-ueber-fotografinnen\/\" \/>\n<meta property=\"og:site_name\" content=\"Leckere Kekse &amp; mehr\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-06T06:13:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2020\/08\/Buecher-Fotografinnen.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"853\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Astrid\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Astrid\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/buecher-ueber-fotografinnen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/buecher-ueber-fotografinnen\\\/\"},\"author\":{\"name\":\"Astrid\",\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/2cf295e7c997b7e06628864ef88c1b3c\"},\"headline\":\"B\u00fccher \u00fcber Fotografinnen\",\"datePublished\":\"2020-09-06T06:13:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/buecher-ueber-fotografinnen\\\/\"},\"wordCount\":787,\"commentCount\":5,\"publisher\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/2cf295e7c997b7e06628864ef88c1b3c\"},\"image\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/buecher-ueber-fotografinnen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/Buecher-Fotografinnen.jpg\",\"keywords\":[\"Fotografien\",\"Fotografin\",\"Koffer\",\"Roman\"],\"articleSection\":{\"1\":\"B\u00fccher\",\"2\":\"Rezension\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/buecher-ueber-fotografinnen\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/buecher-ueber-fotografinnen\\\/\",\"url\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/buecher-ueber-fotografinnen\\\/\",\"name\":\"B\u00fccher \u00fcber Fotografinnen | Leckere Kekse &amp; mehr\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/buecher-ueber-fotografinnen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/buecher-ueber-fotografinnen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/Buecher-Fotografinnen.jpg\",\"datePublished\":\"2020-09-06T06:13:00+00:00\",\"description\":\"Heute stelle ich euch drei B\u00fccher \u00fcber Fotografinnen vor. Zwei von den Frauen gab es wirklich, eine ist fiktiv. F\u00fcr mich ein spannendes Thema.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/buecher-ueber-fotografinnen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/buecher-ueber-fotografinnen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/buecher-ueber-fotografinnen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/Buecher-Fotografinnen.jpg\",\"contentUrl\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/Buecher-Fotografinnen.jpg\",\"width\":640,\"height\":853,\"caption\":\"B\u00fccher \u00fcber Fotografinnen\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/buecher-ueber-fotografinnen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"B\u00fccher \u00fcber Fotografinnen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#website\",\"url\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/\",\"name\":\"Leckere Kekse &amp; mehr\",\"description\":\"Kekse backen, B\u00fccher lesen und mehr\",\"publisher\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/2cf295e7c997b7e06628864ef88c1b3c\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/2cf295e7c997b7e06628864ef88c1b3c\",\"name\":\"Astrid\",\"logo\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/leckerekekse.de\\\/wordpress\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"B\u00fccher \u00fcber Fotografinnen | Leckere Kekse &amp; mehr","description":"Heute stelle ich euch drei B\u00fccher \u00fcber Fotografinnen vor. Zwei von den Frauen gab es wirklich, eine ist fiktiv. F\u00fcr mich ein spannendes Thema.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/leckerekekse.de\/wordpress\/buecher-ueber-fotografinnen\/","og_locale":"de_DE","og_type":"article","og_title":"B\u00fccher \u00fcber Fotografinnen | Leckere Kekse &amp; mehr","og_description":"Heute stelle ich euch drei B\u00fccher \u00fcber Fotografinnen vor. Zwei von den Frauen gab es wirklich, eine ist fiktiv. F\u00fcr mich ein spannendes Thema.","og_url":"https:\/\/leckerekekse.de\/wordpress\/buecher-ueber-fotografinnen\/","og_site_name":"Leckere Kekse &amp; mehr","article_published_time":"2020-09-06T06:13:00+00:00","og_image":[{"width":640,"height":853,"url":"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2020\/08\/Buecher-Fotografinnen.jpg","type":"image\/jpeg"}],"author":"Astrid","twitter_misc":{"Verfasst von":"Astrid","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/leckerekekse.de\/wordpress\/buecher-ueber-fotografinnen\/#article","isPartOf":{"@id":"https:\/\/leckerekekse.de\/wordpress\/buecher-ueber-fotografinnen\/"},"author":{"name":"Astrid","@id":"https:\/\/leckerekekse.de\/wordpress\/#\/schema\/person\/2cf295e7c997b7e06628864ef88c1b3c"},"headline":"B\u00fccher \u00fcber Fotografinnen","datePublished":"2020-09-06T06:13:00+00:00","mainEntityOfPage":{"@id":"https:\/\/leckerekekse.de\/wordpress\/buecher-ueber-fotografinnen\/"},"wordCount":787,"commentCount":5,"publisher":{"@id":"https:\/\/leckerekekse.de\/wordpress\/#\/schema\/person\/2cf295e7c997b7e06628864ef88c1b3c"},"image":{"@id":"https:\/\/leckerekekse.de\/wordpress\/buecher-ueber-fotografinnen\/#primaryimage"},"thumbnailUrl":"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2020\/08\/Buecher-Fotografinnen.jpg","keywords":["Fotografien","Fotografin","Koffer","Roman"],"articleSection":{"1":"B\u00fccher","2":"Rezension"},"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/leckerekekse.de\/wordpress\/buecher-ueber-fotografinnen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/leckerekekse.de\/wordpress\/buecher-ueber-fotografinnen\/","url":"https:\/\/leckerekekse.de\/wordpress\/buecher-ueber-fotografinnen\/","name":"B\u00fccher \u00fcber Fotografinnen | Leckere Kekse &amp; mehr","isPartOf":{"@id":"https:\/\/leckerekekse.de\/wordpress\/#website"},"primaryImageOfPage":{"@id":"https:\/\/leckerekekse.de\/wordpress\/buecher-ueber-fotografinnen\/#primaryimage"},"image":{"@id":"https:\/\/leckerekekse.de\/wordpress\/buecher-ueber-fotografinnen\/#primaryimage"},"thumbnailUrl":"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2020\/08\/Buecher-Fotografinnen.jpg","datePublished":"2020-09-06T06:13:00+00:00","description":"Heute stelle ich euch drei B\u00fccher \u00fcber Fotografinnen vor. Zwei von den Frauen gab es wirklich, eine ist fiktiv. F\u00fcr mich ein spannendes Thema.","breadcrumb":{"@id":"https:\/\/leckerekekse.de\/wordpress\/buecher-ueber-fotografinnen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/leckerekekse.de\/wordpress\/buecher-ueber-fotografinnen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/leckerekekse.de\/wordpress\/buecher-ueber-fotografinnen\/#primaryimage","url":"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2020\/08\/Buecher-Fotografinnen.jpg","contentUrl":"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2020\/08\/Buecher-Fotografinnen.jpg","width":640,"height":853,"caption":"B\u00fccher \u00fcber Fotografinnen"},{"@type":"BreadcrumbList","@id":"https:\/\/leckerekekse.de\/wordpress\/buecher-ueber-fotografinnen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/leckerekekse.de\/wordpress\/"},{"@type":"ListItem","position":2,"name":"B\u00fccher \u00fcber Fotografinnen"}]},{"@type":"WebSite","@id":"https:\/\/leckerekekse.de\/wordpress\/#website","url":"https:\/\/leckerekekse.de\/wordpress\/","name":"Leckere Kekse &amp; mehr","description":"Kekse backen, B\u00fccher lesen und mehr","publisher":{"@id":"https:\/\/leckerekekse.de\/wordpress\/#\/schema\/person\/2cf295e7c997b7e06628864ef88c1b3c"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/leckerekekse.de\/wordpress\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/leckerekekse.de\/wordpress\/#\/schema\/person\/2cf295e7c997b7e06628864ef88c1b3c","name":"Astrid","logo":{"@id":"https:\/\/leckerekekse.de\/wordpress\/#\/schema\/person\/image\/"},"sameAs":["https:\/\/leckerekekse.de\/wordpress"]}]}},"_links":{"self":[{"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/posts\/15552","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/comments?post=15552"}],"version-history":[{"count":3,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/posts\/15552\/revisions"}],"predecessor-version":[{"id":15568,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/posts\/15552\/revisions\/15568"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/media\/15556"}],"wp:attachment":[{"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/media?parent=15552"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/categories?post=15552"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/tags?post=15552"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}