{"id":16150,"date":"2021-01-08T16:27:00","date_gmt":"2021-01-08T15:27:00","guid":{"rendered":"https:\/\/leckerekekse.de\/wordpress\/?p=16150"},"modified":"2021-03-27T16:39:51","modified_gmt":"2021-03-27T15:39:51","slug":"interview-lucia-leidenfrost","status":"publish","type":"post","link":"https:\/\/leckerekekse.de\/wordpress\/interview-lucia-leidenfrost\/","title":{"rendered":"Interview: Lucia Leidenfrost"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"360\" src=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2021\/01\/Interview-Lucia-Leidenfrost.jpg\" alt=\"Lucia Leidenfrost: Wir verlassenen Kinder, Deb\u00fctroman, Interview\" class=\"wp-image-16152\" srcset=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2021\/01\/Interview-Lucia-Leidenfrost.jpg 640w, https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2021\/01\/Interview-Lucia-Leidenfrost-300x169.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Lucia Leidenfrost geh\u00f6rt zu den f\u00fcnf Autoren\/Autorinnen, die auf der Shortlist f\u00fcr den Bloggerpreis f\u00fcr das beste Deb\u00fct 2020 vom <a href=\"https:\/\/dasdebuet.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">Blog Das Deb\u00fct<\/a> stehen. Eine Rezension ihres Romans <a href=\"https:\/\/leckerekekse.de\/wordpress\/lucia-leidenfrost-wir-verlassenen-kinder\/\">Wir verlassenen Kinder<\/a> habe ich bereits ver\u00f6ffentlicht. Es ist ein eindringlicher Deb\u00fctroman, der vom Schicksal eines Dorfes erz\u00e4hlt. Die Eltern gehen alle weg um zu arbeiten, die Kinder bleiben zur\u00fcck und bilden eine verschworene Gemeinschaft.<br>Lucia war so nett mir f\u00fcnf Fragen zu beantworten. Doch zuerst ein paar Dinge \u00fcber die Autorin.<\/p>\n\n\n\n<!--more-->\n\n\n\n<h3 class=\"wp-block-heading\">Lucia Leidenfrost<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">1990 wurde Lucia in Ober\u00f6sterreich geboren. In T\u00fcbingen studierte sie Skandinavistik, Germanistische Linguistik und Germanistik. Danach engagierte sie sich am Institut f\u00fcr Deutsche Sprache, unterrichtete und bildete sich selbst weiter. Jetzt lebt sie als freie Autorin in Mannheim und war dort ma\u00dfgeblich an der Gr\u00fcndung des dortigen Kollektivs f\u00fcr Junge Literatur beteiligt. Sie ver\u00f6ffentlichte 2017 bereits den Erz\u00e4hlband <a href=\"https:\/\/www.kremayr-scheriau.at\/bucher-e-books\/titel\/mir-ist-die-zunge-so-schwer\/\" target=\"_blank\" rel=\"noreferrer noopener\">Mir ist die Zunge so schwer<\/a>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Der Weg<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Wie bist du ans Schreiben gekommen?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Lucia Leidenfrost:<\/strong> Ich habe bald viel gelesen, habe Sprache als Material verstanden, mit dem ich spielen konnte. Meine Familie ist in den Urlaub an den W\u00f6rthersee gefahren. Ich habe mich sehr auf diesen Urlaub gefreut, weil ich die Vorstellung hatte, dass in diesem See W\u00f6rter schwimmen. Als wir dort ankamen, war meine Entt\u00e4uschung nat\u00fcrlich sehr gro\u00df. Dann sind erste Geschichten f\u00fcr ein Publikum entstanden (mit Kasperltheaterfiguren, aber auch geschriebenen Texten, die ich illustriert habe etc). Das Schreiben, der Umgang mit W\u00f6rtern geh\u00f6rt zu mir, ich kann es mir nicht mehr wegdenken.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Dauer<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Wie lange hast du an deinem Deb\u00fctroman gearbeitet?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Lucia Leidenfrost:<\/strong> Insgesamt habe ich drei Jahre an meinem Deb\u00fctroman geschrieben. Angefangen habe ich, als sich meine Erz\u00e4hlungen (Mir ist die Zunge so schwer) im Lektorat befunden haben. Dann kam die Lesereise mit dem ersten Buch und wenig Zeit zum Weiterschreiben. Ein Roman \u2013 oder Texte \u00fcberhaupt \u2013 brauchen ja auch Recherche, Lekt\u00fcreinput, Lebenseindr\u00fccke, um mit dem Text weiterzukommen. Sehr intensiv an \u201eWir verlassene Kinder\u201c geschrieben habe ich insgesamt ein, eineinhalb Jahre.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"427\" src=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2021\/01\/Wir-verlassenen-Kinder.jpg\" alt=\"Lucia Leidenfrost: Wir verlassenen Kinder, Deb\u00fctroman, Interview\" class=\"wp-image-16153\" srcset=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2021\/01\/Wir-verlassenen-Kinder.jpg 640w, https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2021\/01\/Wir-verlassenen-Kinder-300x200.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><figcaption>Copyright des Autorenfotos liegt bei punktachtneun<\/figcaption><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Verlagssuche<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Wie hast du deinen Verlag gefunden?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Lucia Leidenfrost:<\/strong> Der Verlag hat mich gefunden. Ich habe in einer Literaturzeitschrift eine Erz\u00e4hlung ver\u00f6ffentlich und daraufhin habe ich Anfragen von Verlagen bekommen. Ein Verlag wollte einen mir wichtigen Text rausschmei\u00dfen, ein anderer wollte nur einen Roman machen. Beim ersten Telefonat mit meinem jetzigen Verlag hat die Lektorin Tanja Reich diesen einen Text als zentral bezeichnet und gemeint, sie w\u00fcrden auch Erz\u00e4hlb\u00e4nde machen. Da habe ich mich aufgehoben und verstanden gef\u00fchlt und die Zusammenarbeit ist auch beim zweiten Buch wunderbar gelaufen.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Tipps<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Hast du einen Tipp f\u00fcr andere Jungautor*innen?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Lucia Leidenfrost:<\/strong> Schreibt, schreibt, lest, schreibt, lest, tauscht euch aus, findet Leute, die mit euch \u00fcber eure Texte sprechen (wie z.B. im Kollektiv f\u00fcr junge Literatur in Mannheim, in der Schule f\u00fcr Dichtung in Wien etc!) Und jede gute Einsendung, auch wenn es keinen Preis, keine Ver\u00f6ffentlichung o.\u00c4. gibt, z\u00e4hlt. Denn die Leute in den Redaktionen, in der Jury und in den Verlagen merken sich eure Namen, wenn die Texte gut sind und irgendwann tr\u00e4gt das Fr\u00fcchte.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Zukunft<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Wie sehen deine literarischen Pl\u00e4ne f\u00fcr 2021 aus?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Lucia Leidenfrost:<\/strong> Ich habe zwei Prosa-Projekte, an denen ich abwechselnd schreibe, au\u00dferdem schreibe ich an Essays und ein weiteres Projekt sind Texte mit befreundeten Schriftsteller*innen. Ich hoffe, dass ich die vielen aus dem letzten Jahr verschobenen Lesungen 2021 wirklich nachholen kann. Mal sehen, was davon schon bald klappt; so aufgeschrieben sieht es doch recht viel aus \ud83d\ude00<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"427\" src=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2020\/12\/rezension-leidenfrost-verlassenen-kinder-001.jpg\" alt=\"Lucia Leidenfrost: Wir verlassenen Kinder, Deb\u00fctroman, Interview\" class=\"wp-image-15969\" srcset=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2020\/12\/rezension-leidenfrost-verlassenen-kinder-001.jpg 640w, https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2020\/12\/rezension-leidenfrost-verlassenen-kinder-001-300x200.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Danke<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Ich danke Lucia Leidenfrost f\u00fcr diese Tipps und Einblicke. Ich w\u00fcnsche ihr viel Inspiration f\u00fcr die neuen Projekte und hoffe sehr, dass auch ich sie mal bei einer Lesung erleben kann. Hoffentlich haben wir dieses Jahr wieder Offline-Lesungen.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Deb\u00fctpreis<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Der Roman\u00a0<a href=\"https:\/\/leckerekekse.de\/wordpress\/lucia-leidenfrost-wir-verlassenen-kinder\/\">Wir verlassenen Kinder<\/a> von <a href=\"https:\/\/www.lucialeidenfrost.at\/\">Lucia Leidenfrost<\/a> steht auf der Shortlist f\u00fcr den Bloggerpreis f\u00fcr das beste Deb\u00fct des Jahres 2020, ausgelobt vom\u00a0<a href=\"https:\/\/dasdebuet.com\/\">Blog Das Deb\u00fct<\/a>.<br>Ich darf in der\u00a0<a href=\"https:\/\/dasdebuet.com\/2020\/11\/16\/das-debut-2020-die-jury-steht-fest\/\">Jury<\/a>\u00a0mitwirken.<br>Die anderen B\u00fccher der Shortlist:<br><a href=\"https:\/\/leckerekekse.de\/wordpress\/david-misch-schatten-ueber-den-brettern\/\">Schatten \u00fcber den Brettern<\/a> von <a href=\"https:\/\/leckerekekse.de\/wordpress\/interview-mit-david-misch\/\">David Misch<\/a><br><a href=\"https:\/\/leckerekekse.de\/wordpress\/cihan-acar-hawaii\/\">Hawaii<\/a> von <a href=\"https:\/\/leckerekekse.de\/wordpress\/interview-mit-cihan-acar\/\">Cihan Acar<\/a><br><a href=\"https:\/\/leckerekekse.de\/wordpress\/amanda-lasker-berlin-elijas-lied\/\">Elijas Lied<\/a> von <a href=\"https:\/\/leckerekekse.de\/wordpress\/interview-mit-amanda-lasker-berlin\/\">Amanda Lasker-Berlin<\/a><br><a href=\"https:\/\/leckerekekse.de\/wordpress\/deniz-ohde-streulicht\/\">Streulicht<\/a> von Deniz Ohde<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wenn du Lust auf mehr Deb\u00fctromane hast, empfehle ich dir in der&nbsp;<a href=\"https:\/\/dasdebuet.com\/bloggerpreis\/eingereichte-titel\/\">Liste der eingereichten Deb\u00fctromane<\/a>&nbsp;zu bl\u00e4ttern.&nbsp;Diese wird sicher im Laufe des Jahres neu aufgebaut werden.<br>2019 gewann \u00fcbrigens Nadine Schneider mit ihrem Roman&nbsp;<a href=\"https:\/\/leckerekekse.de\/wordpress\/nadine-schneider-drei-kilometer\/\">Drei Kilometer<\/a>.<\/p>\n\n\n\n<figure class=\"wp-block-image size-medium\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"219\" src=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2016\/04\/Signatur-002-300x219.jpg\" alt=\"\" class=\"wp-image-5977\" srcset=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2016\/04\/Signatur-002-300x219.jpg 300w, https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2016\/04\/Signatur-002.jpg 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Lucia Leidenfrost geh\u00f6rt zu den f\u00fcnf Autoren\/Autorinnen, die auf der Shortlist f\u00fcr den Bloggerpreis f\u00fcr das beste Deb\u00fct 2020 vom Blog Das Deb\u00fct stehen. Eine Rezension ihres Romans Wir verlassenen Kinder habe ich bereits ver\u00f6ffentlicht. Es ist ein eindringlicher Deb\u00fctroman, der vom Schicksal eines Dorfes erz\u00e4hlt. Die Eltern gehen alle weg um zu arbeiten, die [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":16152,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,3,781,788],"tags":[1079,57,1072,93],"class_list":["post-16150","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-buecher","category-interview","category-rezension","tag-autorin","tag-debuet","tag-debuetroman","tag-kinder"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Interview: Lucia Leidenfrost | Leckere Kekse &amp; mehr<\/title>\n<meta name=\"description\" content=\"Die Deb\u00fctautorin Lucia Leidenfrost beantwortet f\u00fcnf Fragen zu ihrer Karriere. Intervew im Rahmen des Bloggerpreises f\u00fcr das beste Deb\u00fct 2020.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/leckerekekse.de\/wordpress\/interview-lucia-leidenfrost\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Interview: Lucia Leidenfrost | Leckere Kekse &amp; mehr\" \/>\n<meta property=\"og:description\" content=\"Die Deb\u00fctautorin Lucia Leidenfrost beantwortet f\u00fcnf Fragen zu ihrer Karriere. Intervew im Rahmen des Bloggerpreises f\u00fcr das beste Deb\u00fct 2020.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/leckerekekse.de\/wordpress\/interview-lucia-leidenfrost\/\" \/>\n<meta property=\"og:site_name\" content=\"Leckere Kekse &amp; mehr\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-08T15:27:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-27T15:39:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2021\/01\/Interview-Lucia-Leidenfrost.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"360\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Buchlieberin\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Buchlieberin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/interview-lucia-leidenfrost\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/interview-lucia-leidenfrost\\\/\"},\"author\":{\"name\":\"Buchlieberin\",\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/2374d41b5cda28a27f6924e58f3afcc2\"},\"headline\":\"Interview: Lucia Leidenfrost\",\"datePublished\":\"2021-01-08T15:27:00+00:00\",\"dateModified\":\"2021-03-27T15:39:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/interview-lucia-leidenfrost\\\/\"},\"wordCount\":769,\"commentCount\":2,\"publisher\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/72061e7e8c1c70c8e8e542a13e5acbfe\"},\"image\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/interview-lucia-leidenfrost\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/Interview-Lucia-Leidenfrost.jpg\",\"keywords\":[\"Autorin\",\"Deb\u00fct\",\"Deb\u00fctroman\",\"Kinder\"],\"articleSection\":{\"1\":\"B\u00fccher\",\"2\":\"Interview\",\"3\":\"Rezension\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/interview-lucia-leidenfrost\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/interview-lucia-leidenfrost\\\/\",\"url\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/interview-lucia-leidenfrost\\\/\",\"name\":\"Interview: Lucia Leidenfrost | Leckere Kekse &amp; mehr\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/interview-lucia-leidenfrost\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/interview-lucia-leidenfrost\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/Interview-Lucia-Leidenfrost.jpg\",\"datePublished\":\"2021-01-08T15:27:00+00:00\",\"dateModified\":\"2021-03-27T15:39:51+00:00\",\"description\":\"Die Deb\u00fctautorin Lucia Leidenfrost beantwortet f\u00fcnf Fragen zu ihrer Karriere. Intervew im Rahmen des Bloggerpreises f\u00fcr das beste Deb\u00fct 2020.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/interview-lucia-leidenfrost\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/interview-lucia-leidenfrost\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/interview-lucia-leidenfrost\\\/#primaryimage\",\"url\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/Interview-Lucia-Leidenfrost.jpg\",\"contentUrl\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/Interview-Lucia-Leidenfrost.jpg\",\"width\":640,\"height\":360},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/interview-lucia-leidenfrost\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Interview: Lucia Leidenfrost\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#website\",\"url\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/\",\"name\":\"Leckere Kekse &amp; mehr\",\"description\":\"Kekse backen, B\u00fccher lesen und mehr\",\"publisher\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/72061e7e8c1c70c8e8e542a13e5acbfe\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/72061e7e8c1c70c8e8e542a13e5acbfe\",\"name\":\"Astrid\",\"logo\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/leckerekekse.de\\\/wordpress\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/2374d41b5cda28a27f6924e58f3afcc2\",\"name\":\"Buchlieberin\",\"sameAs\":[\"https:\\\/\\\/leckerekekse.de\\\/wordpress\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Interview: Lucia Leidenfrost | Leckere Kekse &amp; mehr","description":"Die Deb\u00fctautorin Lucia Leidenfrost beantwortet f\u00fcnf Fragen zu ihrer Karriere. Intervew im Rahmen des Bloggerpreises f\u00fcr das beste Deb\u00fct 2020.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/leckerekekse.de\/wordpress\/interview-lucia-leidenfrost\/","og_locale":"de_DE","og_type":"article","og_title":"Interview: Lucia Leidenfrost | Leckere Kekse &amp; mehr","og_description":"Die Deb\u00fctautorin Lucia Leidenfrost beantwortet f\u00fcnf Fragen zu ihrer Karriere. Intervew im Rahmen des Bloggerpreises f\u00fcr das beste Deb\u00fct 2020.","og_url":"https:\/\/leckerekekse.de\/wordpress\/interview-lucia-leidenfrost\/","og_site_name":"Leckere Kekse &amp; mehr","article_published_time":"2021-01-08T15:27:00+00:00","article_modified_time":"2021-03-27T15:39:51+00:00","og_image":[{"width":640,"height":360,"url":"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2021\/01\/Interview-Lucia-Leidenfrost.jpg","type":"image\/jpeg"}],"author":"Buchlieberin","twitter_misc":{"Verfasst von":"Buchlieberin","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/leckerekekse.de\/wordpress\/interview-lucia-leidenfrost\/#article","isPartOf":{"@id":"https:\/\/leckerekekse.de\/wordpress\/interview-lucia-leidenfrost\/"},"author":{"name":"Buchlieberin","@id":"https:\/\/leckerekekse.de\/wordpress\/#\/schema\/person\/2374d41b5cda28a27f6924e58f3afcc2"},"headline":"Interview: Lucia Leidenfrost","datePublished":"2021-01-08T15:27:00+00:00","dateModified":"2021-03-27T15:39:51+00:00","mainEntityOfPage":{"@id":"https:\/\/leckerekekse.de\/wordpress\/interview-lucia-leidenfrost\/"},"wordCount":769,"commentCount":2,"publisher":{"@id":"https:\/\/leckerekekse.de\/wordpress\/#\/schema\/person\/72061e7e8c1c70c8e8e542a13e5acbfe"},"image":{"@id":"https:\/\/leckerekekse.de\/wordpress\/interview-lucia-leidenfrost\/#primaryimage"},"thumbnailUrl":"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2021\/01\/Interview-Lucia-Leidenfrost.jpg","keywords":["Autorin","Deb\u00fct","Deb\u00fctroman","Kinder"],"articleSection":{"1":"B\u00fccher","2":"Interview","3":"Rezension"},"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/leckerekekse.de\/wordpress\/interview-lucia-leidenfrost\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/leckerekekse.de\/wordpress\/interview-lucia-leidenfrost\/","url":"https:\/\/leckerekekse.de\/wordpress\/interview-lucia-leidenfrost\/","name":"Interview: Lucia Leidenfrost | Leckere Kekse &amp; mehr","isPartOf":{"@id":"https:\/\/leckerekekse.de\/wordpress\/#website"},"primaryImageOfPage":{"@id":"https:\/\/leckerekekse.de\/wordpress\/interview-lucia-leidenfrost\/#primaryimage"},"image":{"@id":"https:\/\/leckerekekse.de\/wordpress\/interview-lucia-leidenfrost\/#primaryimage"},"thumbnailUrl":"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2021\/01\/Interview-Lucia-Leidenfrost.jpg","datePublished":"2021-01-08T15:27:00+00:00","dateModified":"2021-03-27T15:39:51+00:00","description":"Die Deb\u00fctautorin Lucia Leidenfrost beantwortet f\u00fcnf Fragen zu ihrer Karriere. Intervew im Rahmen des Bloggerpreises f\u00fcr das beste Deb\u00fct 2020.","breadcrumb":{"@id":"https:\/\/leckerekekse.de\/wordpress\/interview-lucia-leidenfrost\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/leckerekekse.de\/wordpress\/interview-lucia-leidenfrost\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/leckerekekse.de\/wordpress\/interview-lucia-leidenfrost\/#primaryimage","url":"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2021\/01\/Interview-Lucia-Leidenfrost.jpg","contentUrl":"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2021\/01\/Interview-Lucia-Leidenfrost.jpg","width":640,"height":360},{"@type":"BreadcrumbList","@id":"https:\/\/leckerekekse.de\/wordpress\/interview-lucia-leidenfrost\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/leckerekekse.de\/wordpress\/"},{"@type":"ListItem","position":2,"name":"Interview: Lucia Leidenfrost"}]},{"@type":"WebSite","@id":"https:\/\/leckerekekse.de\/wordpress\/#website","url":"https:\/\/leckerekekse.de\/wordpress\/","name":"Leckere Kekse &amp; mehr","description":"Kekse backen, B\u00fccher lesen und mehr","publisher":{"@id":"https:\/\/leckerekekse.de\/wordpress\/#\/schema\/person\/72061e7e8c1c70c8e8e542a13e5acbfe"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/leckerekekse.de\/wordpress\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/leckerekekse.de\/wordpress\/#\/schema\/person\/72061e7e8c1c70c8e8e542a13e5acbfe","name":"Astrid","logo":{"@id":"https:\/\/leckerekekse.de\/wordpress\/#\/schema\/person\/image\/"},"sameAs":["https:\/\/leckerekekse.de\/wordpress"]},{"@type":"Person","@id":"https:\/\/leckerekekse.de\/wordpress\/#\/schema\/person\/2374d41b5cda28a27f6924e58f3afcc2","name":"Buchlieberin","sameAs":["https:\/\/leckerekekse.de\/wordpress"]}]}},"_links":{"self":[{"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/posts\/16150","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/comments?post=16150"}],"version-history":[{"count":3,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/posts\/16150\/revisions"}],"predecessor-version":[{"id":16457,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/posts\/16150\/revisions\/16457"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/media\/16152"}],"wp:attachment":[{"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/media?parent=16150"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/categories?post=16150"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/tags?post=16150"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}