{"id":16167,"date":"2021-01-13T12:26:00","date_gmt":"2021-01-13T11:26:00","guid":{"rendered":"https:\/\/leckerekekse.de\/wordpress\/?p=16167"},"modified":"2021-01-08T12:26:34","modified_gmt":"2021-01-08T11:26:34","slug":"interview-mit-deniz-ohde","status":"publish","type":"post","link":"https:\/\/leckerekekse.de\/wordpress\/interview-mit-deniz-ohde\/","title":{"rendered":"Interview mit Deniz Ohde"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"360\" src=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2021\/01\/Interview-Denit-Ohde.jpg\" alt=\"Deniz Ohde: Streulicht, Interview, \" class=\"wp-image-16169\" srcset=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2021\/01\/Interview-Denit-Ohde.jpg 640w, https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2021\/01\/Interview-Denit-Ohde-300x169.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">F\u00fcnf Fragen an eine Deb\u00fctautorin<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Deniz Ohde geh\u00f6rt zu den f\u00fcnf Autoren\/Autorinnen, die auf der Shortlist f\u00fcr den Bloggerpreis f\u00fcr das beste Deb\u00fct 2020 vom <a href=\"https:\/\/dasdebuet.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">Blog Das Deb\u00fct<\/a> stehen. Eine Rezension ihres Romans Streulicht habe ich bereits ver\u00f6ffentlicht. In dem Buch beschreibt eine namenlose Erz\u00e4hlerin Kindheit und Jugend. Sie leidet unter einem schwierigen Elternhaus und hat keinerlei Selbstbewusstsein. In der Schule wird sie total untersch\u00e4tz und auch gemobbt, weil ihr Vorname kein deutscher ist und ihre Mutter aus einem anderen Land stammt.\u00a0 Deniz war so nett mir f\u00fcnf Fragen zu beantworten. Doch zuerst ein paar Dinge \u00fcber die Autorin.<\/p>\n\n\n\n<!--more-->\n\n\n\n<h3 class=\"wp-block-heading\">Deniz Ohde<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Deniz wurde 1988 in Frankfurt am Main geboren. Sp\u00e4ter zog sie zu einem Germanistik-Studium nach Leipzig. Ihr Mutter macht sie fr\u00fch mit B\u00fcchern bekannt. Deniz schrieb auch schon auf verschiedenen Plattformen wir zum Beispiel Blogs oder auch literarische Tagebucheintr\u00e4ge und Tweets. Es folgten ver\u00f6ffentlichte Erz\u00e4hlungen und dann, 2020 ihr Deb\u00fctroman Streulicht. Daf\u00fcr erhielt sie 2020 bereits den Literaturpreis der J\u00fcrgen-Ponto-Stiftung und den aspekte Literaturpreis.<br>Doch jetzt soll die Autorin selbst zu Wort kommen.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Der Weg<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Wie bist du ans Schreiben gekommen?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Deniz Ohde<\/strong>: Die Faszination f\u00fcr Literatur war f\u00fcr mich seit fr\u00fchester Kindheit da. Ich habe meine Mutter immer viel lesen sehen und sie hat mir auch all die Kinderbuchklassiker vorgelesen. Bald hab ich ihr dann meine eigenen Geschichten diktiert (nerd alert!) und sie, sobald ich schreiben konnte, selbst aufgeschrieben &#8211; also das Schreiben begleitet mich eigentlich von Anfang an!<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Dauer<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Wie lange hast du an deinem Deb\u00fctroman gearbeitet?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Deniz Ohde:<\/strong> Insgesamt waren es drei Jahre, es gab dabei aber sowohl intensive Arbeitsphasen, als auch Monate, in denen gar nichts passiert ist. Wie viel Realzeit nun letztendlich drinsteckt, kann ich gar nicht sagen, aber im Nachhinein wei\u00df ich, dass auch die Zeiten, in der ich scheinbar nicht geschrieben habe, sehr wichtig waren.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Verlagssuche<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Wie hast du deinen Verlag gefunden?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Deniz Ohde:<\/strong> \u00dcber meine Agentur &#8211; Elisabeth Ruge!<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"427\" src=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2021\/01\/Streulicht.jpg\" alt=\"Deniz Ohde: Streilicht, Interview\" class=\"wp-image-16160\" srcset=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2021\/01\/Streulicht.jpg 640w, https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2021\/01\/Streulicht-300x200.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><figcaption>Copyright f\u00fcr diese Bilder liegt beim Suhrkamp Verlag<\/figcaption><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Tipps<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Hast du einen Tipp f\u00fcr andere Jungautor*innen?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Deniz Ohde:<\/strong> Nimm deine eigenen Ideen ernst.<br>Versuch alles, was mit \u00d6ffentlichkeit und Rezeption zu tun hat, w\u00e4hrend dem Schreiben auszublenden.<br>Es ist normal, dass alles lang dauert.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Zukunft<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Wie sehen deine literarischen Pl\u00e4ne f\u00fcr 2021 aus?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Deniz Ohde:<\/strong> Ich hoffe mit meinem zweiten Roman ein gutes St\u00fcck weiter zu kommen. Und ansonsten habe ich 2021 noch viele Lesetermine mit Streulicht.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Dank<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Ich danke Deniz Ohde f\u00fcr diese Einblicke in ihren Beruf als Autorin. Ich w\u00fcnsche ihr viel Inspiration f\u00fcr den neuen Roman und hoffe sehr f\u00fcr sie, dass die Pandemie ihr keinen Strich durch ihre Lesungspl\u00e4ne macht. Vielleicht kann ich sie auch mal live erleben?<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Deb\u00fctpreis<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Der Roman&nbsp;<a href=\"https:\/\/www.suhrkamp.de\/buecher\/streulicht-deniz_ohde_42963.html\">Streulicht<\/a> von <a href=\"https:\/\/denizohde.wordpress.com\/\">Deniz Ohde<\/a> steht auf der Shortlist f\u00fcr den Bloggerpreis f\u00fcr das beste Deb\u00fct des Jahres 2020, ausgelobt vom&nbsp;<a href=\"https:\/\/dasdebuet.com\/\">Blog Das Deb\u00fct<\/a>.<br>Ich darf in der&nbsp;<a href=\"https:\/\/dasdebuet.com\/2020\/11\/16\/das-debut-2020-die-jury-steht-fest\/\">Jury<\/a>&nbsp;mitwirken.<br>Die anderen B\u00fccher der Shortlist:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/leckerekekse.de\/wordpress\/lucia-leidenfrost-wir-verlassenen-kinder\/\">Wir verlassenen Kinder<\/a>\u00a0von <a href=\"https:\/\/leckerekekse.de\/wordpress\/?p=16150\">Lucia Leidenfrost<\/a><br><a href=\"https:\/\/leckerekekse.de\/wordpress\/david-misch-schatten-ueber-den-brettern\/\">Schatten \u00fcber den Brettern<\/a> von <a href=\"https:\/\/leckerekekse.de\/wordpress\/interview-mit-david-misch\/\">David Misch<\/a><br><a href=\"https:\/\/leckerekekse.de\/wordpress\/cihan-acar-hawaii\/\">Hawaii<\/a> von <a href=\"https:\/\/leckerekekse.de\/wordpress\/interview-mit-cihan-acar\/\">Cihan Acar<\/a><br><a href=\"https:\/\/leckerekekse.de\/wordpress\/amanda-lasker-berlin-elijas-lied\/\">Elijas Lied<\/a> von <a href=\"https:\/\/leckerekekse.de\/wordpress\/interview-mit-amanda-lasker-berlin\/\">Amanda Lasker-Berlin<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wenn du Lust auf mehr Deb\u00fctromane hast, empfehle ich dir in der&nbsp;<a href=\"https:\/\/dasdebuet.com\/bloggerpreis\/eingereichte-titel\/\">Liste der eingereichten Deb\u00fctromane<\/a>&nbsp;zu bl\u00e4ttern.&nbsp;<br>2019 gewann \u00fcbrigens Nadine Schneider mit ihrem Roman&nbsp;<a href=\"https:\/\/leckerekekse.de\/wordpress\/nadine-schneider-drei-kilometer\/\">Drei Kilometer<\/a>.<\/p>\n\n\n\n<figure class=\"wp-block-image size-medium\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"219\" src=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2016\/04\/Signatur-002-300x219.jpg\" alt=\"\" class=\"wp-image-5977\" srcset=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2016\/04\/Signatur-002-300x219.jpg 300w, https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2016\/04\/Signatur-002.jpg 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>F\u00fcnf Fragen an eine Deb\u00fctautorin Deniz Ohde geh\u00f6rt zu den f\u00fcnf Autoren\/Autorinnen, die auf der Shortlist f\u00fcr den Bloggerpreis f\u00fcr das beste Deb\u00fct 2020 vom Blog Das Deb\u00fct stehen. Eine Rezension ihres Romans Streulicht habe ich bereits ver\u00f6ffentlicht. In dem Buch beschreibt eine namenlose Erz\u00e4hlerin Kindheit und Jugend. Sie leidet unter einem schwierigen Elternhaus und [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":16169,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,3,781],"tags":[1079,1046,1072,725],"class_list":["post-16167","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-buecher","category-interview","tag-autorin","tag-bloggerpreis","tag-debuetroman","tag-interview"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Interview mit Deniz Ohde | Leckere Kekse &amp; mehr<\/title>\n<meta name=\"description\" content=\"Die Deb\u00fctautorin Deniz Ohde des Romans Streulicht beantwortet f\u00fcnf Fragen in einem Interview im Rahmen des Deb\u00fctpreises.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/leckerekekse.de\/wordpress\/interview-mit-deniz-ohde\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Interview mit Deniz Ohde | Leckere Kekse &amp; mehr\" \/>\n<meta property=\"og:description\" content=\"Die Deb\u00fctautorin Deniz Ohde des Romans Streulicht beantwortet f\u00fcnf Fragen in einem Interview im Rahmen des Deb\u00fctpreises.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/leckerekekse.de\/wordpress\/interview-mit-deniz-ohde\/\" \/>\n<meta property=\"og:site_name\" content=\"Leckere Kekse &amp; mehr\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-13T11:26:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2021\/01\/Interview-Denit-Ohde.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"360\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Buchlieberin\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Buchlieberin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/interview-mit-deniz-ohde\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/interview-mit-deniz-ohde\\\/\"},\"author\":{\"name\":\"Buchlieberin\",\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/2374d41b5cda28a27f6924e58f3afcc2\"},\"headline\":\"Interview mit Deniz Ohde\",\"datePublished\":\"2021-01-13T11:26:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/interview-mit-deniz-ohde\\\/\"},\"wordCount\":578,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/72061e7e8c1c70c8e8e542a13e5acbfe\"},\"image\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/interview-mit-deniz-ohde\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/Interview-Denit-Ohde.jpg\",\"keywords\":[\"Autorin\",\"Bloggerpreis\",\"Deb\u00fctroman\",\"Interview\"],\"articleSection\":{\"1\":\"B\u00fccher\",\"2\":\"Interview\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/interview-mit-deniz-ohde\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/interview-mit-deniz-ohde\\\/\",\"url\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/interview-mit-deniz-ohde\\\/\",\"name\":\"Interview mit Deniz Ohde | Leckere Kekse &amp; mehr\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/interview-mit-deniz-ohde\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/interview-mit-deniz-ohde\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/Interview-Denit-Ohde.jpg\",\"datePublished\":\"2021-01-13T11:26:00+00:00\",\"description\":\"Die Deb\u00fctautorin Deniz Ohde des Romans Streulicht beantwortet f\u00fcnf Fragen in einem Interview im Rahmen des Deb\u00fctpreises.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/interview-mit-deniz-ohde\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/interview-mit-deniz-ohde\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/interview-mit-deniz-ohde\\\/#primaryimage\",\"url\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/Interview-Denit-Ohde.jpg\",\"contentUrl\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/Interview-Denit-Ohde.jpg\",\"width\":640,\"height\":360},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/interview-mit-deniz-ohde\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Interview mit Deniz Ohde\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#website\",\"url\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/\",\"name\":\"Leckere Kekse &amp; mehr\",\"description\":\"Kekse backen, B\u00fccher lesen und mehr\",\"publisher\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/72061e7e8c1c70c8e8e542a13e5acbfe\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/72061e7e8c1c70c8e8e542a13e5acbfe\",\"name\":\"Astrid\",\"logo\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/leckerekekse.de\\\/wordpress\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/2374d41b5cda28a27f6924e58f3afcc2\",\"name\":\"Buchlieberin\",\"sameAs\":[\"https:\\\/\\\/leckerekekse.de\\\/wordpress\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Interview mit Deniz Ohde | Leckere Kekse &amp; mehr","description":"Die Deb\u00fctautorin Deniz Ohde des Romans Streulicht beantwortet f\u00fcnf Fragen in einem Interview im Rahmen des Deb\u00fctpreises.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/leckerekekse.de\/wordpress\/interview-mit-deniz-ohde\/","og_locale":"de_DE","og_type":"article","og_title":"Interview mit Deniz Ohde | Leckere Kekse &amp; mehr","og_description":"Die Deb\u00fctautorin Deniz Ohde des Romans Streulicht beantwortet f\u00fcnf Fragen in einem Interview im Rahmen des Deb\u00fctpreises.","og_url":"https:\/\/leckerekekse.de\/wordpress\/interview-mit-deniz-ohde\/","og_site_name":"Leckere Kekse &amp; mehr","article_published_time":"2021-01-13T11:26:00+00:00","og_image":[{"width":640,"height":360,"url":"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2021\/01\/Interview-Denit-Ohde.jpg","type":"image\/jpeg"}],"author":"Buchlieberin","twitter_misc":{"Verfasst von":"Buchlieberin","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/leckerekekse.de\/wordpress\/interview-mit-deniz-ohde\/#article","isPartOf":{"@id":"https:\/\/leckerekekse.de\/wordpress\/interview-mit-deniz-ohde\/"},"author":{"name":"Buchlieberin","@id":"https:\/\/leckerekekse.de\/wordpress\/#\/schema\/person\/2374d41b5cda28a27f6924e58f3afcc2"},"headline":"Interview mit Deniz Ohde","datePublished":"2021-01-13T11:26:00+00:00","mainEntityOfPage":{"@id":"https:\/\/leckerekekse.de\/wordpress\/interview-mit-deniz-ohde\/"},"wordCount":578,"commentCount":0,"publisher":{"@id":"https:\/\/leckerekekse.de\/wordpress\/#\/schema\/person\/72061e7e8c1c70c8e8e542a13e5acbfe"},"image":{"@id":"https:\/\/leckerekekse.de\/wordpress\/interview-mit-deniz-ohde\/#primaryimage"},"thumbnailUrl":"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2021\/01\/Interview-Denit-Ohde.jpg","keywords":["Autorin","Bloggerpreis","Deb\u00fctroman","Interview"],"articleSection":{"1":"B\u00fccher","2":"Interview"},"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/leckerekekse.de\/wordpress\/interview-mit-deniz-ohde\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/leckerekekse.de\/wordpress\/interview-mit-deniz-ohde\/","url":"https:\/\/leckerekekse.de\/wordpress\/interview-mit-deniz-ohde\/","name":"Interview mit Deniz Ohde | Leckere Kekse &amp; mehr","isPartOf":{"@id":"https:\/\/leckerekekse.de\/wordpress\/#website"},"primaryImageOfPage":{"@id":"https:\/\/leckerekekse.de\/wordpress\/interview-mit-deniz-ohde\/#primaryimage"},"image":{"@id":"https:\/\/leckerekekse.de\/wordpress\/interview-mit-deniz-ohde\/#primaryimage"},"thumbnailUrl":"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2021\/01\/Interview-Denit-Ohde.jpg","datePublished":"2021-01-13T11:26:00+00:00","description":"Die Deb\u00fctautorin Deniz Ohde des Romans Streulicht beantwortet f\u00fcnf Fragen in einem Interview im Rahmen des Deb\u00fctpreises.","breadcrumb":{"@id":"https:\/\/leckerekekse.de\/wordpress\/interview-mit-deniz-ohde\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/leckerekekse.de\/wordpress\/interview-mit-deniz-ohde\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/leckerekekse.de\/wordpress\/interview-mit-deniz-ohde\/#primaryimage","url":"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2021\/01\/Interview-Denit-Ohde.jpg","contentUrl":"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2021\/01\/Interview-Denit-Ohde.jpg","width":640,"height":360},{"@type":"BreadcrumbList","@id":"https:\/\/leckerekekse.de\/wordpress\/interview-mit-deniz-ohde\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/leckerekekse.de\/wordpress\/"},{"@type":"ListItem","position":2,"name":"Interview mit Deniz Ohde"}]},{"@type":"WebSite","@id":"https:\/\/leckerekekse.de\/wordpress\/#website","url":"https:\/\/leckerekekse.de\/wordpress\/","name":"Leckere Kekse &amp; mehr","description":"Kekse backen, B\u00fccher lesen und mehr","publisher":{"@id":"https:\/\/leckerekekse.de\/wordpress\/#\/schema\/person\/72061e7e8c1c70c8e8e542a13e5acbfe"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/leckerekekse.de\/wordpress\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/leckerekekse.de\/wordpress\/#\/schema\/person\/72061e7e8c1c70c8e8e542a13e5acbfe","name":"Astrid","logo":{"@id":"https:\/\/leckerekekse.de\/wordpress\/#\/schema\/person\/image\/"},"sameAs":["https:\/\/leckerekekse.de\/wordpress"]},{"@type":"Person","@id":"https:\/\/leckerekekse.de\/wordpress\/#\/schema\/person\/2374d41b5cda28a27f6924e58f3afcc2","name":"Buchlieberin","sameAs":["https:\/\/leckerekekse.de\/wordpress"]}]}},"_links":{"self":[{"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/posts\/16167","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/comments?post=16167"}],"version-history":[{"count":3,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/posts\/16167\/revisions"}],"predecessor-version":[{"id":16172,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/posts\/16167\/revisions\/16172"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/media\/16169"}],"wp:attachment":[{"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/media?parent=16167"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/categories?post=16167"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/tags?post=16167"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}