{"id":16211,"date":"2021-01-24T08:02:00","date_gmt":"2021-01-24T07:02:00","guid":{"rendered":"https:\/\/leckerekekse.de\/wordpress\/?p=16211"},"modified":"2021-01-23T17:03:39","modified_gmt":"2021-01-23T16:03:39","slug":"john-boyne-die-geschichte-eines-luegners","status":"publish","type":"post","link":"https:\/\/leckerekekse.de\/wordpress\/john-boyne-die-geschichte-eines-luegners\/","title":{"rendered":"John Boyne: die Geschichte eines L\u00fcgners"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"428\" src=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2021\/01\/john-boyne-maurice-swift-rezension.jpg\" alt=\"Johne Boyne: Maurice Swift: Die Geschichte eines L\u00fcgners, Rezension, Piper Verlag\" class=\"wp-image-16216\" srcset=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2021\/01\/john-boyne-maurice-swift-rezension.jpg 640w, https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2021\/01\/john-boyne-maurice-swift-rezension-300x201.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Woher nehmen Autoren ihre Ideen?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Maurice Swift ist ein sehr gut aussehender junger Mann. Hoch ambitioniert. Er will unbedingt ber\u00fchmt werden und das am besten als Schriftsteller. Als er den bereits erfolgreichen Autor Erich Ackermann kennenlernt, erkennt Maurice schnell, dass dort eine gute Geschichte zu holen ist. Der Roman begleitet Maurice durch einen gro\u00dfen Teil seines Lebens, wobei die erste H\u00e4lfte des Buches aus der Sicht einiger Menschen beschrieben wird, die sich mehr oder weniger auf ihn einlassen. In der folgenden Buchbesprechung folge ich diesen verschiedenen Stimmen. Ohne Spoiler geht es dabei leider nicht.&nbsp; Ich versuche aber m\u00f6glichst wenig zu verraten.<\/p>\n\n\n\n<!--more-->\n\n\n\n<h3 class=\"wp-block-heading\">Erich<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Erich Ackermann ist um die 60 Jahre alt, Uni-Dozent und mit seinem letzten Roman sehr erfolgreich. Seine Lesereisen im Jahr 1988 f\u00fchren ihn auch nach Berlin. Dort f\u00e4llt ihm ein junger Kellner ins Auge. Dieser sieht so gut aus, dass seine Leidenschaft sofort erwacht. Sie gehen was zusammen trinken, unterhalten sich gut. Der junge Mann, Maurice Swift, m\u00f6chte auch Schriftsteller werden. Nicht nur das, er will ein ber\u00fchmter Autor werden.<br>Erich ist total verliebt, bietet Maurice einen Job an worauf dieser ihn auf verschiedenen lesereisen begleitet. Auf Erichs sch\u00fcchterne Avancen geht Maurice nicht ein. Daf\u00fcr entlockt er Erich ein dunkles Geheimnis aus dessen Vergangenheit.<br>Erich gibt und gibt und bekommt nichts zur\u00fcck. Irgendwann verliert er den Kontakt zu Maurice, der einen Bestseller ver\u00f6ffentlicht, der Erichs Leben zerst\u00f6rt.<br>Erich ist eine sehr tragische Figur, der sein Schicksal aber einfach annimmt.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Gore<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Ein paar wenige Jahre sp\u00e4ter. Gore Vidal ist eine Ikone der Literatur. Er und sein Partner Howard leben in einer Villa mit Blick aufs Meer. Dort empfangen sie h\u00e4ufig Besuch. So z.B. auch den ebenfalls homosexuellen Dash, ein eher mittelm\u00e4\u00dfiger Schriftsteller. Dieser hat einen auff\u00e4llig h\u00fcbschen jungen Mann im Schlepptau. Dieser hei\u00dft Maurice.<br>Ich liebe diesen Abschnitt, der aus Gores Sicht geschrieben ist. Sein Leben ist so dekadent. Gore ist ziemlich gewitzt und schlau. Er kennt Gott und die Welt. Gott vielleicht noch nicht pers\u00f6nlich, daf\u00fcr aber zwei P\u00e4pste. So hat er ein G\u00e4stebett in dem unter anderem Kissinger, Prinzessin Margaret, Paul Simon und Paul Newman geschlafen haben.<br>Gores leben im Jetset w\u00e4re wahrlich ein toller Stoff f\u00fcr einen Roman! Das hat sich Maurice sicher auch gedacht.<br>Doch Gore ist so schlau, dass er Maurice durchschaut und dessen Anbiederungen abblitzen l\u00e4sst. Allerdings schweren Herzens, weil der Junge einfach so gut aussieht.<br>Gl\u00fcck gehabt, Gore!<br>Sehr sch\u00f6n auch, dass ,sp\u00e4ter im Roman, dieser Besuch auch noch aus der Sicht von Maurice beschrieben wird.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"430\" src=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2021\/01\/john-boyne-rezension-geschichte-eines-luegners.jpg\" alt=\"Johne Boyne: Maurice Swift: Die Geschichte eines L\u00fcgners, Rezension, Piper Verlag\" class=\"wp-image-16217\" srcset=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2021\/01\/john-boyne-rezension-geschichte-eines-luegners.jpg 640w, https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2021\/01\/john-boyne-rezension-geschichte-eines-luegners-300x202.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Edith<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Sprung ins Jahr 2000. Edith ist Dozentin und renommierte Autorin. Sie arbeitet fieberhaft an ihrem neuen Buch. Seit 5 Jahren ist sie mit einem Autor verheiratet, der mit seinem Erstling viel verdient hat und danach mehr in der Versenkung verschwand. Ihr ahnt es: er hei\u00dft Maurice.<br>Da ich als Leserin Maurice ja schon kenne, war klar: Edith muss aufpassen. Macht sie aber nicht. Immer will ich ihr zurufen: pass auf! Schmei\u00df ihn raus! Doch sie kann mich nicht h\u00f6ren.<br>Die Konstruktion dieses Kapitels, die Perspektive von Edith und die Situation aus der sie ihre Geschichte heraus erz\u00e4hlt: einfach super. Mehr will ich dazu nicht verraten.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">New York<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Nur die letzten 150 Seiten des Buches sind aus Maurice Sicht geschrieben.<br>Zwei Abschnitte aus seinem Leben werden damit beschrieben.&nbsp; Etwa 8 Jahre nach den von Edith beschriebenen Ereignissen, lebt Maurice mit seinem Sohn Daniel allein in New York. Sein B\u00fccherregal kann mehrere neue, erfolgreiche Romane von ihm selbst aufweisen. In New York hat er eine Literaturzeitschrift gegr\u00fcndet, die jungen Autorenstimmen die M\u00f6glichkeit bietet Erz\u00e4hlungen zu ver\u00f6ffentlichen.<br>Maurice hat immer von einem Kind getr\u00e4umt. Er geht ganz liebevoll mit dem Jungen um, der schon mal Probleme in der Schule und starkes Asthma hat. Doch er wirkt irgendwie auch genervt von den Vaterpflichten.<br>Gut gef\u00e4llt mir auch, dass ich als Leserin einfach in die neue Situation des n\u00e4chsten Abschnittes hineingeworfen werde. Es dauert immer ein wenig, bis ich mich zurechtfinde, doch diese kleinen R\u00e4tsel machen mir Spa\u00df. So wie hier: wo kommt pl\u00f6tzlich das Kind her? Oder auch im n\u00e4chsten Abschnitt: wo ist Daniel jetzt? Die Aufl\u00f6sung kommt immer, aber manchmal w\u00fcnschte ich mir fast sie nicht zu kennen, weil Maurice wirklich alles f\u00fcr seinen Eigenschutz macht.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">London<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Noch ein paar Jahre sp\u00e4ter. Maurice hat die Zeitung verkauft, lebt in London, ist Alkoholiker und dabei sich zu Tode zu saufen. Sein Geld reicht daf\u00fcr. Ein neues Buch f\u00e4ngt er erst gar nicht an. Jeden Tag ein anderer Pub, jeden Tag eine bestimmte Getr\u00e4nkefolge. Jeden Tag betrunken nach Hause. Er ist ein Wrack.<br>Aber er nimmt das irgendwie leicht. Das ist sicher eine der St\u00e4rken dieses Romans: obwohl viele tragische, dramatische, traurige Dinge passieren, zieht das Buch nicht runter. Es ist leicht, heiter, voller Humor und Ironie. Ganz mein Ding!<br>Doch zur\u00fcck nach London. Hier lernt Maurice einen jungen Mann kennen, der ihn interviewen und \u00a0vielleicht eine Biographie, auf alle F\u00e4lle eine Studienarbeit \u00fcber ihn schreiben m\u00f6chte. Maurice ist total geschmeichelt. Endlich widmet ihm jemand wieder Aufmerksamkeit. Sie treffen sich in Pubs. Im Alkoholnebel erz\u00e4hlt Maurice vielleicht zu viel.<br>In diesem Abschnitt erfuhr ich endlich viel \u00fcber Motive und das Innenleben von Maurice. Er rollt auch einige Ereignisse aus der Vergangenheit aus seiner Sicht auf. Sympathisch wird er dadurch nicht. Will Maurice auch nicht.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Vorbilder<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Viele Personen, die es tats\u00e4chlich gab und gibt werden im Buch und vor allem im Abschnitt aus Gores Sicht aufgef\u00fchrt. Ob auch die fiktiven Personen ein reales Vorbild haben? Dar\u00fcber w\u00fcrde ich mit John Boyne gerne mal reden. Denn um Mutma\u00dfungen anzustellen kenne ich mich im Privatleben von Autoren zu wenig aus. Es werden auch immer wieder Titel fiktiver B\u00fccher genannt. Ob Boyne dabei auch an reale Romane gedacht hat?<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"428\" src=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2021\/01\/john-booyne-maurice-rezension-luegner.jpg\" alt=\"Johne Boyne: Maurice Swift: Die Geschichte eines L\u00fcgners, Rezension, Piper Verlag\" class=\"wp-image-16218\" srcset=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2021\/01\/john-booyne-maurice-rezension-luegner.jpg 640w, https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2021\/01\/john-booyne-maurice-rezension-luegner-300x201.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Maurice der L\u00fcgner<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Maurice ist ein ganz und gar intriganter, egozentrischer, gef\u00fchlloser Mensch. Er geht \u00fcber Leichen, was z\u00e4hlt, ist einzig der Erfolg. Er kann einigerma\u00dfen schreiben, hat aber einfach keine Ideen. Die klaut er sich halt. Dabei ist er auch sehr kreativ. Sein L\u00fcgengeflecht funktioniert \u00fcber lange Zeit. Durchschaut wird er selten, meist zu sp\u00e4t. Auf dem Klappentext wird er mit Ripley vergleichen, das hinkt meiner Meinung etwas, weil Ripley ein netter Typ ist, Maurice m\u00f6chte ich nicht begegnen.<br>Er punktet mit seinem \u00c4u\u00dferen, und er geht bis zum \u00c4u\u00dferstem. Er ist skrupellos.<br>Somit ist er ein Sinnbild vieler Kritikpunkte unserer Gesellschaft: K\u00f6rperkult, harte Manager, jeder ist sich selbst der N\u00e4chste, es geht um Macht, Geld und Ruhm.&nbsp; &nbsp;<br>Meiner Meinung nach hat Boyne in seinem Roman nicht nur den Literaturbetrieb, sondern auch die Menschheit an sich auf die Schippe genommen.<br>Autoren, die gerne schreiben wollen, aber keine Idee haben, bekommen hier sicher Anregungen, die sie aber nicht so \u00fcbernehmen sollten.<br>Obwohl Maurice ein schrecklicher Mensch ist, macht es echt Spa\u00df ihm zu folgen.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Fazit<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.piper.de\/buecher\/die-geschichte-eines-luegners-isbn-978-3-492-05963-3\" target=\"_blank\" rel=\"noreferrer noopener\">Die Geschichte eines L\u00fcgners<\/a> von John Boyne ist ein spannender, tragischer und auch am\u00fcsanter Roman.\u00a0 Das Buch ist durchdacht konstruiert. Durch die verschiedenen Perspektiven und Zeitspr\u00fcnge wird er nie langweilig. Sehr gute Unterhaltung!<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Weitere B\u00fccher des Autors<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">John Boynes erfolgreichstes Buch ist sicher &#8222;Der Junge im gestreifen Pyjama&#8220;. Eine absolute Leseempfehlung. <br>Auf diesem Blog haben wir noch folgende B\u00fccher von ihm rezensiert:<br><a href=\"https:\/\/leckerekekse.de\/wordpress\/cyril-avery\/\">Cyril Avery<\/a><br><a href=\"https:\/\/leckerekekse.de\/wordpress\/rezension-der-junge-auf-dem-berg\/\">Der Junge auf dem Berg<\/a>.<\/p>\n\n\n\n<figure class=\"wp-block-image size-medium is-style-default\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"219\" src=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2016\/04\/Signatur-002-300x219.jpg\" alt=\"\" class=\"wp-image-5977\" srcset=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2016\/04\/Signatur-002-300x219.jpg 300w, https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2016\/04\/Signatur-002.jpg 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Woher nehmen Autoren ihre Ideen? Maurice Swift ist ein sehr gut aussehender junger Mann. Hoch ambitioniert. Er will unbedingt ber\u00fchmt werden und das am besten als Schriftsteller. Als er den bereits erfolgreichen Autor Erich Ackermann kennenlernt, erkennt Maurice schnell, dass dort eine gute Geschichte zu holen ist. Der Roman begleitet Maurice durch einen gro\u00dfen Teil [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":16216,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,3,788],"tags":[143,1399,195,104,459,1400],"class_list":["post-16211","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-buecher","category-rezension","tag-betrug","tag-literaturbetrieb","tag-london","tag-new-york","tag-roman","tag-verlagswelt"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>John Boyne: die Geschichte eines L\u00fcgners | Leckere Kekse &amp; mehr<\/title>\n<meta name=\"description\" content=\"Maurice Swift ist ein gutaussehender, aufstrebender Jungautor. F\u00fcr seine Karriere macht er alles. Rezension eines unterhaltsamen Romans.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/leckerekekse.de\/wordpress\/john-boyne-die-geschichte-eines-luegners\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"John Boyne: die Geschichte eines L\u00fcgners | Leckere Kekse &amp; mehr\" \/>\n<meta property=\"og:description\" content=\"Maurice Swift ist ein gutaussehender, aufstrebender Jungautor. F\u00fcr seine Karriere macht er alles. Rezension eines unterhaltsamen Romans.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/leckerekekse.de\/wordpress\/john-boyne-die-geschichte-eines-luegners\/\" \/>\n<meta property=\"og:site_name\" content=\"Leckere Kekse &amp; mehr\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-24T07:02:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2021\/01\/john-boyne-maurice-swift-rezension.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"428\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Buchlieberin\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Buchlieberin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"6\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/john-boyne-die-geschichte-eines-luegners\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/john-boyne-die-geschichte-eines-luegners\\\/\"},\"author\":{\"name\":\"Buchlieberin\",\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/2374d41b5cda28a27f6924e58f3afcc2\"},\"headline\":\"John Boyne: die Geschichte eines L\u00fcgners\",\"datePublished\":\"2021-01-24T07:02:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/john-boyne-die-geschichte-eines-luegners\\\/\"},\"wordCount\":1272,\"commentCount\":2,\"publisher\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/72061e7e8c1c70c8e8e542a13e5acbfe\"},\"image\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/john-boyne-die-geschichte-eines-luegners\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/john-boyne-maurice-swift-rezension.jpg\",\"keywords\":[\"Betrug\",\"Literaturbetrieb\",\"London\",\"New York\",\"Roman\",\"Verlagswelt\"],\"articleSection\":{\"1\":\"B\u00fccher\",\"2\":\"Rezension\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/john-boyne-die-geschichte-eines-luegners\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/john-boyne-die-geschichte-eines-luegners\\\/\",\"url\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/john-boyne-die-geschichte-eines-luegners\\\/\",\"name\":\"John Boyne: die Geschichte eines L\u00fcgners | Leckere Kekse &amp; mehr\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/john-boyne-die-geschichte-eines-luegners\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/john-boyne-die-geschichte-eines-luegners\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/john-boyne-maurice-swift-rezension.jpg\",\"datePublished\":\"2021-01-24T07:02:00+00:00\",\"description\":\"Maurice Swift ist ein gutaussehender, aufstrebender Jungautor. F\u00fcr seine Karriere macht er alles. Rezension eines unterhaltsamen Romans.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/john-boyne-die-geschichte-eines-luegners\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/john-boyne-die-geschichte-eines-luegners\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/john-boyne-die-geschichte-eines-luegners\\\/#primaryimage\",\"url\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/john-boyne-maurice-swift-rezension.jpg\",\"contentUrl\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/john-boyne-maurice-swift-rezension.jpg\",\"width\":640,\"height\":428},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/john-boyne-die-geschichte-eines-luegners\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"John Boyne: die Geschichte eines L\u00fcgners\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#website\",\"url\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/\",\"name\":\"Leckere Kekse &amp; mehr\",\"description\":\"Kekse backen, B\u00fccher lesen und mehr\",\"publisher\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/72061e7e8c1c70c8e8e542a13e5acbfe\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/72061e7e8c1c70c8e8e542a13e5acbfe\",\"name\":\"Astrid\",\"logo\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/leckerekekse.de\\\/wordpress\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/2374d41b5cda28a27f6924e58f3afcc2\",\"name\":\"Buchlieberin\",\"sameAs\":[\"https:\\\/\\\/leckerekekse.de\\\/wordpress\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"John Boyne: die Geschichte eines L\u00fcgners | Leckere Kekse &amp; mehr","description":"Maurice Swift ist ein gutaussehender, aufstrebender Jungautor. F\u00fcr seine Karriere macht er alles. Rezension eines unterhaltsamen Romans.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/leckerekekse.de\/wordpress\/john-boyne-die-geschichte-eines-luegners\/","og_locale":"de_DE","og_type":"article","og_title":"John Boyne: die Geschichte eines L\u00fcgners | Leckere Kekse &amp; mehr","og_description":"Maurice Swift ist ein gutaussehender, aufstrebender Jungautor. F\u00fcr seine Karriere macht er alles. Rezension eines unterhaltsamen Romans.","og_url":"https:\/\/leckerekekse.de\/wordpress\/john-boyne-die-geschichte-eines-luegners\/","og_site_name":"Leckere Kekse &amp; mehr","article_published_time":"2021-01-24T07:02:00+00:00","og_image":[{"width":640,"height":428,"url":"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2021\/01\/john-boyne-maurice-swift-rezension.jpg","type":"image\/jpeg"}],"author":"Buchlieberin","twitter_misc":{"Verfasst von":"Buchlieberin","Gesch\u00e4tzte Lesezeit":"6\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/leckerekekse.de\/wordpress\/john-boyne-die-geschichte-eines-luegners\/#article","isPartOf":{"@id":"https:\/\/leckerekekse.de\/wordpress\/john-boyne-die-geschichte-eines-luegners\/"},"author":{"name":"Buchlieberin","@id":"https:\/\/leckerekekse.de\/wordpress\/#\/schema\/person\/2374d41b5cda28a27f6924e58f3afcc2"},"headline":"John Boyne: die Geschichte eines L\u00fcgners","datePublished":"2021-01-24T07:02:00+00:00","mainEntityOfPage":{"@id":"https:\/\/leckerekekse.de\/wordpress\/john-boyne-die-geschichte-eines-luegners\/"},"wordCount":1272,"commentCount":2,"publisher":{"@id":"https:\/\/leckerekekse.de\/wordpress\/#\/schema\/person\/72061e7e8c1c70c8e8e542a13e5acbfe"},"image":{"@id":"https:\/\/leckerekekse.de\/wordpress\/john-boyne-die-geschichte-eines-luegners\/#primaryimage"},"thumbnailUrl":"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2021\/01\/john-boyne-maurice-swift-rezension.jpg","keywords":["Betrug","Literaturbetrieb","London","New York","Roman","Verlagswelt"],"articleSection":{"1":"B\u00fccher","2":"Rezension"},"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/leckerekekse.de\/wordpress\/john-boyne-die-geschichte-eines-luegners\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/leckerekekse.de\/wordpress\/john-boyne-die-geschichte-eines-luegners\/","url":"https:\/\/leckerekekse.de\/wordpress\/john-boyne-die-geschichte-eines-luegners\/","name":"John Boyne: die Geschichte eines L\u00fcgners | Leckere Kekse &amp; mehr","isPartOf":{"@id":"https:\/\/leckerekekse.de\/wordpress\/#website"},"primaryImageOfPage":{"@id":"https:\/\/leckerekekse.de\/wordpress\/john-boyne-die-geschichte-eines-luegners\/#primaryimage"},"image":{"@id":"https:\/\/leckerekekse.de\/wordpress\/john-boyne-die-geschichte-eines-luegners\/#primaryimage"},"thumbnailUrl":"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2021\/01\/john-boyne-maurice-swift-rezension.jpg","datePublished":"2021-01-24T07:02:00+00:00","description":"Maurice Swift ist ein gutaussehender, aufstrebender Jungautor. F\u00fcr seine Karriere macht er alles. Rezension eines unterhaltsamen Romans.","breadcrumb":{"@id":"https:\/\/leckerekekse.de\/wordpress\/john-boyne-die-geschichte-eines-luegners\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/leckerekekse.de\/wordpress\/john-boyne-die-geschichte-eines-luegners\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/leckerekekse.de\/wordpress\/john-boyne-die-geschichte-eines-luegners\/#primaryimage","url":"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2021\/01\/john-boyne-maurice-swift-rezension.jpg","contentUrl":"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2021\/01\/john-boyne-maurice-swift-rezension.jpg","width":640,"height":428},{"@type":"BreadcrumbList","@id":"https:\/\/leckerekekse.de\/wordpress\/john-boyne-die-geschichte-eines-luegners\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/leckerekekse.de\/wordpress\/"},{"@type":"ListItem","position":2,"name":"John Boyne: die Geschichte eines L\u00fcgners"}]},{"@type":"WebSite","@id":"https:\/\/leckerekekse.de\/wordpress\/#website","url":"https:\/\/leckerekekse.de\/wordpress\/","name":"Leckere Kekse &amp; mehr","description":"Kekse backen, B\u00fccher lesen und mehr","publisher":{"@id":"https:\/\/leckerekekse.de\/wordpress\/#\/schema\/person\/72061e7e8c1c70c8e8e542a13e5acbfe"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/leckerekekse.de\/wordpress\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/leckerekekse.de\/wordpress\/#\/schema\/person\/72061e7e8c1c70c8e8e542a13e5acbfe","name":"Astrid","logo":{"@id":"https:\/\/leckerekekse.de\/wordpress\/#\/schema\/person\/image\/"},"sameAs":["https:\/\/leckerekekse.de\/wordpress"]},{"@type":"Person","@id":"https:\/\/leckerekekse.de\/wordpress\/#\/schema\/person\/2374d41b5cda28a27f6924e58f3afcc2","name":"Buchlieberin","sameAs":["https:\/\/leckerekekse.de\/wordpress"]}]}},"_links":{"self":[{"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/posts\/16211","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/comments?post=16211"}],"version-history":[{"count":3,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/posts\/16211\/revisions"}],"predecessor-version":[{"id":16219,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/posts\/16211\/revisions\/16219"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/media\/16216"}],"wp:attachment":[{"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/media?parent=16211"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/categories?post=16211"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/tags?post=16211"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}