{"id":16981,"date":"2022-01-16T09:15:00","date_gmt":"2022-01-16T08:15:00","guid":{"rendered":"https:\/\/leckerekekse.de\/wordpress\/?p=16981"},"modified":"2022-01-12T17:15:34","modified_gmt":"2022-01-12T16:15:34","slug":"ariane-koch-die-aufdraengung","status":"publish","type":"post","link":"https:\/\/leckerekekse.de\/wordpress\/ariane-koch-die-aufdraengung\/","title":{"rendered":"Ariane Koch: Die Aufdr\u00e4ngung"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"377\" src=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2021\/12\/die-aufdraengung-ariane-koch.jpg\" alt=\"\" class=\"wp-image-16982\" srcset=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2021\/12\/die-aufdraengung-ariane-koch.jpg 640w, https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2021\/12\/die-aufdraengung-ariane-koch-300x177.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Deb\u00fctroman, nominiert f\u00fcr den Bloggerpreis<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Frau nimmt einen Fremden, den \u201eGast\u201c bei sich auf. Sie bewohnt ein gro\u00dfes Haus mit zehn Zimmern und \u00fcberl\u00e4sst ihm eines. Die Frau bleibt namenlos, nennen wir sie Gastgeberin. Das Verh\u00e4ltnis zwischen den beiden bleibt sehr ambivalent. Wer dr\u00e4ngt sich hier wem auf?<br>Dieser Roman steht auf der Shortlist f\u00fcr den Bloggerpreis f\u00fcr das beste Deb\u00fct des Jahres 2021, ausgelobt vom Blog Das Deb\u00fct.<\/p>\n\n\n\n<!--more-->\n\n\n\n<h3 class=\"wp-block-heading\">Wer ist der Gast?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Ein Fremder im Ort. Ein Migrant? Ein Obdachloser? Stammt er aus einem anderen Land? Spricht er dieselbe Sprache? Manchmal nicht, manchmal doch. Im Roman finde ich immer wieder Fragen, weniger Antworten. Immer wenn ich denke ich habe es begriffen, entgleiten mir die Protagonisten wieder.<br>Ein Gast zu sein, oder einen Gast zu beherbergen, ist ein Konzept, dass es in allen Kulturen gibt. Zwei Menschen, die sich nicht kennen und zueinander finden. Sie n\u00e4hern sich immer mehr aneinander an. Es gibt dann Momente starker N\u00e4he, auch k\u00f6rperlich, aber sie driften auch immer wieder auseinander. Mal dr\u00e4ngt sich der Gast, mal die Gastgeberin auf. Die Aufdr\u00e4ngung ist also beidseitig.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Episoden<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Der Roman verfolgt keine stringente Handlung. Er ist eher die Aneinanderreihung von einzelnen Episoden. Manche Abschnitte umfassen nur einen Satz, andere gehen \u00fcber mehrere Seiten.<br>Aber eine Entwicklung der Personen und der Beziehung des Gastes und seiner Gastgeberin ist immer erkennbar. Nichts bleibt, es gibt eher st\u00e4ndige Ver\u00e4nderung.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Wie kann ich ihn konturieren, wenn er stets in Bewegung ist? Wie soll ich ihn festzuhalten im Stande sein, wenn er im Zerflie\u00dfen begriffen ist?<\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Auch die Gastgeberin ver\u00e4ndert sich st\u00e4ndig, macht starke Entwicklungen durch. Zum Beispiel hat sie Anfangs eher einen Putzfimmel, am Ende versinken Haus und Garten im Chaos.<br>Sie stellt auch ein Regelwerk f\u00fcr das Zusammenleben auf, doch ver\u00e4ndern sich diese Regeln schon w\u00e4hrend sie aufgeschrieben werden.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Humor<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Bei allen Herausforderungen die sich mir durch die Lekt\u00fcre des Buches bieten ist Die Aufdr\u00e4ngung durchaus auch ein humorvolles Buch. Zum Teil durch die Absurdit\u00e4t die immer wieder aufblitzt. So gibt es eine Art Staubsaugerr\u00fcsselballett, einen Zierfischfriedhof, lange Schlangen von Menschen die ebenfalls Gast sein m\u00f6chten vor dem Haus.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Namen<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Wenn ich mich richtig erinnere gibt es im gesamten Roman nur zwei Personen mit Namen Laurenz, der Freund aus der Kindheit und Carla. Alle anderen bleiben Namenlos. Die Gastgeberin selbst bleibt namenlos. Das spricht meiner Ansicht nach daf\u00fcr, dass es hier um Identit\u00e4tsfindung geht. &nbsp;<br>Der Gast bleibt einfach \u201eder Gast\u201c. Andere Personen werden mit ihrer Funktion benannt: der Kellner in der nahegelegenen Bar, die Eltern, die Geschwister. &nbsp;<br>Apropos Familie. Normalerweise beschweren sich Eltern, wenn die Kinder zu lange zu Hause wohnen bleiben. Nicht so die der Gastgeberin: sie ziehen selbst aus und lassen die Tochter zur\u00fcck. Sie verbleibt in dem gro\u00dfen Haus mit den L\u00f6wenstatuen an der Einfahrt. Dort lebt sie in der st\u00e4ndigen Angst, ihre Geschwister k\u00f6nnten sie aus diesem Haus vertreiben und es selbst beanspruchen. Andererseits w\u00fcnscht es sich die Gastgeberin das fast, sie hat schon l\u00e4ngst alles in Kartons verpasst und tr\u00e4umt immer wieder davon das Haus und die Kleinstadt zu verlassen. Auch der Gast versucht sie zum Ausziehen zu bewegen:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Der Gast sagt: Du musst dieses Haus verlassen, denn dieses Haus geh\u00f6rt seinen Eltern, geh\u00f6rt deinen Geschwistern, geh\u00f6rt nicht dir und \u00fcberhaupt bist du schon viel zu lange in diesem Haus.<\/p><\/blockquote>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"640\" src=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2022\/01\/Ariane-koch-aufdraengung-rezension.jpg\" alt=\"\" class=\"wp-image-17031\" srcset=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2022\/01\/Ariane-koch-aufdraengung-rezension.jpg 480w, https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2022\/01\/Ariane-koch-aufdraengung-rezension-225x300.jpg 225w\" sizes=\"auto, (max-width: 480px) 100vw, 480px\" \/><\/figure><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Worum geht es?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Identit\u00e4tsfindung? Erwachsenwerden? Losl\u00f6sen von der Heimat, der gewohnten Umgebung? \u00dcberwindung der Angst, in ein eigenes, autarkes Leben zu spazieren? Willkommenskultur? Fremdenintegration?<br>Manchmal fragte ich mich auch: ist der Gast \u00fcberhaupt ein Mensch? Seine Behaartheit wird immer wieder hervorgehoben, auch das Cover zeigt ein Tier. Es gibt auch Szenen, in denen er seine Gastgeberin verfolgt, wie ein Hund, der sein Frauchen auf Schritt und Tritt folgt. Ich glaube, dass der Text viel Freiraum f\u00fcr eigene Interpretationen zul\u00e4sst.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Meine Interpretation<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Ich sehe den Gast als eine Depression. Es gibt Hochs und Tiefs. Am Ende befreit sich die Gastgeberin davon. Der Gast packt seine Plastikt\u00fcten und geht. Das gibt ihr so viel Kraft, sich selbst von der erdr\u00fcckenden Enge der Kleinstadt zu entledigen und schafft es selbst zu gehen. Wird selbst zum Gast in einem fremden Land. Sie macht sich frei und dreht die Rollen um. Irgendwo im Buch steht auch, der Mensch sei zum Reisen gemacht. Das verwirklicht sie f\u00fcr sich. Gerne w\u00fcrde ich mit der Autorin meinen Ansatz mal diskutieren.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Die Autorin<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Ariane Koch wurde 1988 geboren. Sie machte Ihren Bachelor in bildender Kunst, den Master in Interdisziplinarit\u00e4t. Sie lebt in Basel und Berlin und schreibt gerne in Badeanstalten.<br>Die Audr\u00e4ngung ist ihr erster Roman, aber sie hat bereits Theater-, Performancetexte geschrieben und zur Auff\u00fchrung gebracht. Eine <a href=\"https:\/\/www.suhrkamp.de\/video\/ariane-koch-liest-aus-ihrem-roman-die-aufdraengung-b-3353\">Lesung aus dem Roman<\/a> findest du auf der Verlagsseite. Ebenso ein Video, in dem sie \u00fcber ihren Roman <a href=\"https:\/\/www.suhrkamp.de\/video\/ariane-koch-stellt-ihren-roman-die-aufdraengung-vor-b-3352\">Die Aufdr\u00e4ngung<\/a> spricht.<br>2021 gewann sie den <a href=\"https:\/\/www.zdf.de\/kultur\/aspekte\/ariane-koch-die-aufdraengung-aspekte-literaturpreis-2021-100.html\">Aspekte Literaturpreis.<\/a><br>Ihr Deb\u00fctroman steht auf der <a href=\"https:\/\/dasdebuet.com\/2021\/12\/06\/das-debut-2021-die-shortlist\/\">Shortlist<\/a> f\u00fcr den Bloggerpreis f\u00fcr das beste Romandeb\u00fct 2021, ausgelobt vom Blog Das Deb\u00fct.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Fazit<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.suhrkamp.de\/buch\/ariane-koch-die-aufdraengung-t-9783518127841\">Die Aufdr\u00e4ngung<\/a> von Ariane Koch ist ein anspruchsvoller, sprachlich sehr ungew\u00f6hnlicher Roman. Er bietet viel Interpretationsspielraum und auch Raum f\u00fcr Diskussionen, zum Beispiel in einem Lesekreis. Ich als Leserin musste mich erst \u00f6ffnen f\u00fcr diese Sprache, diesen Stil. Ich sch\u00e4tze B\u00fccher, die meinen Geist besch\u00e4ftigen.<\/p>\n\n\n\n<figure class=\"wp-block-image size-medium\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"219\" src=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2016\/04\/Signatur-002-300x219.jpg\" alt=\"\" class=\"wp-image-5977\" srcset=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2016\/04\/Signatur-002-300x219.jpg 300w, https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2016\/04\/Signatur-002.jpg 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Lust auf mehr Deb\u00fctromane?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">F\u00fcnf Deb\u00fctautor*innen wurden f\u00fcr die Shortlist des Bloggerpreises vom Blog das Deb\u00fct nominiert. Neben Ariane Koch sind es folgende:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sharon Dodua Ottoo: <a href=\"https:\/\/leckerekekse.de\/wordpress\/rezension-adas-raum-von-sharon-dodua-otoo\/\">Adas Raum<\/a><br>Thomas Arzt: Die Gegenstimme<br>Jessica Lind: Mama<br>Stefanie von Schulte: Junge mit schwarzem Hahn<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Deb\u00fctroman, nominiert f\u00fcr den Bloggerpreis Frau nimmt einen Fremden, den \u201eGast\u201c bei sich auf. Sie bewohnt ein gro\u00dfes Haus mit zehn Zimmern und \u00fcberl\u00e4sst ihm eines. Die Frau bleibt namenlos, nennen wir sie Gastgeberin. Das Verh\u00e4ltnis zwischen den beiden bleibt sehr ambivalent. Wer dr\u00e4ngt sich hier wem auf?Dieser Roman steht auf der Shortlist f\u00fcr den [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":16982,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,3,788],"tags":[1046,57,1072,459],"class_list":["post-16981","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-buecher","category-rezension","tag-bloggerpreis","tag-debuet","tag-debuetroman","tag-roman"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ariane Koch: Die Aufdr\u00e4ngung | Leckere Kekse &amp; mehr<\/title>\n<meta name=\"description\" content=\"Der Deb\u00fctroman von Ariane Koch hei\u00dft Die Aufdr\u00e4ngung. Er steht auf der Shortlist f\u00fcr den Bloggerpreis f\u00fcr das beste Deb\u00fct 2021.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/leckerekekse.de\/wordpress\/ariane-koch-die-aufdraengung\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ariane Koch: Die Aufdr\u00e4ngung | Leckere Kekse &amp; mehr\" \/>\n<meta property=\"og:description\" content=\"Der Deb\u00fctroman von Ariane Koch hei\u00dft Die Aufdr\u00e4ngung. Er steht auf der Shortlist f\u00fcr den Bloggerpreis f\u00fcr das beste Deb\u00fct 2021.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/leckerekekse.de\/wordpress\/ariane-koch-die-aufdraengung\/\" \/>\n<meta property=\"og:site_name\" content=\"Leckere Kekse &amp; mehr\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-16T08:15:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2021\/12\/die-aufdraengung-ariane-koch.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"377\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Buchlieberin\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Buchlieberin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/ariane-koch-die-aufdraengung\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/ariane-koch-die-aufdraengung\\\/\"},\"author\":{\"name\":\"Buchlieberin\",\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/2374d41b5cda28a27f6924e58f3afcc2\"},\"headline\":\"Ariane Koch: Die Aufdr\u00e4ngung\",\"datePublished\":\"2022-01-16T08:15:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/ariane-koch-die-aufdraengung\\\/\"},\"wordCount\":970,\"commentCount\":5,\"publisher\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/72061e7e8c1c70c8e8e542a13e5acbfe\"},\"image\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/ariane-koch-die-aufdraengung\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/die-aufdraengung-ariane-koch.jpg\",\"keywords\":[\"Bloggerpreis\",\"Deb\u00fct\",\"Deb\u00fctroman\",\"Roman\"],\"articleSection\":{\"1\":\"B\u00fccher\",\"2\":\"Rezension\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/ariane-koch-die-aufdraengung\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/ariane-koch-die-aufdraengung\\\/\",\"url\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/ariane-koch-die-aufdraengung\\\/\",\"name\":\"Ariane Koch: Die Aufdr\u00e4ngung | Leckere Kekse &amp; mehr\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/ariane-koch-die-aufdraengung\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/ariane-koch-die-aufdraengung\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/die-aufdraengung-ariane-koch.jpg\",\"datePublished\":\"2022-01-16T08:15:00+00:00\",\"description\":\"Der Deb\u00fctroman von Ariane Koch hei\u00dft Die Aufdr\u00e4ngung. Er steht auf der Shortlist f\u00fcr den Bloggerpreis f\u00fcr das beste Deb\u00fct 2021.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/ariane-koch-die-aufdraengung\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/ariane-koch-die-aufdraengung\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/ariane-koch-die-aufdraengung\\\/#primaryimage\",\"url\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/die-aufdraengung-ariane-koch.jpg\",\"contentUrl\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/die-aufdraengung-ariane-koch.jpg\",\"width\":640,\"height\":377},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/ariane-koch-die-aufdraengung\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ariane Koch: Die Aufdr\u00e4ngung\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#website\",\"url\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/\",\"name\":\"Leckere Kekse &amp; mehr\",\"description\":\"Kekse backen, B\u00fccher lesen und mehr\",\"publisher\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/72061e7e8c1c70c8e8e542a13e5acbfe\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/72061e7e8c1c70c8e8e542a13e5acbfe\",\"name\":\"Astrid\",\"logo\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/leckerekekse.de\\\/wordpress\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/2374d41b5cda28a27f6924e58f3afcc2\",\"name\":\"Buchlieberin\",\"sameAs\":[\"https:\\\/\\\/leckerekekse.de\\\/wordpress\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ariane Koch: Die Aufdr\u00e4ngung | Leckere Kekse &amp; mehr","description":"Der Deb\u00fctroman von Ariane Koch hei\u00dft Die Aufdr\u00e4ngung. Er steht auf der Shortlist f\u00fcr den Bloggerpreis f\u00fcr das beste Deb\u00fct 2021.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/leckerekekse.de\/wordpress\/ariane-koch-die-aufdraengung\/","og_locale":"de_DE","og_type":"article","og_title":"Ariane Koch: Die Aufdr\u00e4ngung | Leckere Kekse &amp; mehr","og_description":"Der Deb\u00fctroman von Ariane Koch hei\u00dft Die Aufdr\u00e4ngung. Er steht auf der Shortlist f\u00fcr den Bloggerpreis f\u00fcr das beste Deb\u00fct 2021.","og_url":"https:\/\/leckerekekse.de\/wordpress\/ariane-koch-die-aufdraengung\/","og_site_name":"Leckere Kekse &amp; mehr","article_published_time":"2022-01-16T08:15:00+00:00","og_image":[{"width":640,"height":377,"url":"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2021\/12\/die-aufdraengung-ariane-koch.jpg","type":"image\/jpeg"}],"author":"Buchlieberin","twitter_misc":{"Verfasst von":"Buchlieberin","Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/leckerekekse.de\/wordpress\/ariane-koch-die-aufdraengung\/#article","isPartOf":{"@id":"https:\/\/leckerekekse.de\/wordpress\/ariane-koch-die-aufdraengung\/"},"author":{"name":"Buchlieberin","@id":"https:\/\/leckerekekse.de\/wordpress\/#\/schema\/person\/2374d41b5cda28a27f6924e58f3afcc2"},"headline":"Ariane Koch: Die Aufdr\u00e4ngung","datePublished":"2022-01-16T08:15:00+00:00","mainEntityOfPage":{"@id":"https:\/\/leckerekekse.de\/wordpress\/ariane-koch-die-aufdraengung\/"},"wordCount":970,"commentCount":5,"publisher":{"@id":"https:\/\/leckerekekse.de\/wordpress\/#\/schema\/person\/72061e7e8c1c70c8e8e542a13e5acbfe"},"image":{"@id":"https:\/\/leckerekekse.de\/wordpress\/ariane-koch-die-aufdraengung\/#primaryimage"},"thumbnailUrl":"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2021\/12\/die-aufdraengung-ariane-koch.jpg","keywords":["Bloggerpreis","Deb\u00fct","Deb\u00fctroman","Roman"],"articleSection":{"1":"B\u00fccher","2":"Rezension"},"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/leckerekekse.de\/wordpress\/ariane-koch-die-aufdraengung\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/leckerekekse.de\/wordpress\/ariane-koch-die-aufdraengung\/","url":"https:\/\/leckerekekse.de\/wordpress\/ariane-koch-die-aufdraengung\/","name":"Ariane Koch: Die Aufdr\u00e4ngung | Leckere Kekse &amp; mehr","isPartOf":{"@id":"https:\/\/leckerekekse.de\/wordpress\/#website"},"primaryImageOfPage":{"@id":"https:\/\/leckerekekse.de\/wordpress\/ariane-koch-die-aufdraengung\/#primaryimage"},"image":{"@id":"https:\/\/leckerekekse.de\/wordpress\/ariane-koch-die-aufdraengung\/#primaryimage"},"thumbnailUrl":"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2021\/12\/die-aufdraengung-ariane-koch.jpg","datePublished":"2022-01-16T08:15:00+00:00","description":"Der Deb\u00fctroman von Ariane Koch hei\u00dft Die Aufdr\u00e4ngung. Er steht auf der Shortlist f\u00fcr den Bloggerpreis f\u00fcr das beste Deb\u00fct 2021.","breadcrumb":{"@id":"https:\/\/leckerekekse.de\/wordpress\/ariane-koch-die-aufdraengung\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/leckerekekse.de\/wordpress\/ariane-koch-die-aufdraengung\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/leckerekekse.de\/wordpress\/ariane-koch-die-aufdraengung\/#primaryimage","url":"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2021\/12\/die-aufdraengung-ariane-koch.jpg","contentUrl":"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2021\/12\/die-aufdraengung-ariane-koch.jpg","width":640,"height":377},{"@type":"BreadcrumbList","@id":"https:\/\/leckerekekse.de\/wordpress\/ariane-koch-die-aufdraengung\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/leckerekekse.de\/wordpress\/"},{"@type":"ListItem","position":2,"name":"Ariane Koch: Die Aufdr\u00e4ngung"}]},{"@type":"WebSite","@id":"https:\/\/leckerekekse.de\/wordpress\/#website","url":"https:\/\/leckerekekse.de\/wordpress\/","name":"Leckere Kekse &amp; mehr","description":"Kekse backen, B\u00fccher lesen und mehr","publisher":{"@id":"https:\/\/leckerekekse.de\/wordpress\/#\/schema\/person\/72061e7e8c1c70c8e8e542a13e5acbfe"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/leckerekekse.de\/wordpress\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/leckerekekse.de\/wordpress\/#\/schema\/person\/72061e7e8c1c70c8e8e542a13e5acbfe","name":"Astrid","logo":{"@id":"https:\/\/leckerekekse.de\/wordpress\/#\/schema\/person\/image\/"},"sameAs":["https:\/\/leckerekekse.de\/wordpress"]},{"@type":"Person","@id":"https:\/\/leckerekekse.de\/wordpress\/#\/schema\/person\/2374d41b5cda28a27f6924e58f3afcc2","name":"Buchlieberin","sameAs":["https:\/\/leckerekekse.de\/wordpress"]}]}},"_links":{"self":[{"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/posts\/16981","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/comments?post=16981"}],"version-history":[{"count":3,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/posts\/16981\/revisions"}],"predecessor-version":[{"id":17033,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/posts\/16981\/revisions\/17033"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/media\/16982"}],"wp:attachment":[{"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/media?parent=16981"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/categories?post=16981"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/tags?post=16981"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}