{"id":17016,"date":"2022-01-14T12:04:00","date_gmt":"2022-01-14T11:04:00","guid":{"rendered":"https:\/\/leckerekekse.de\/wordpress\/?p=17016"},"modified":"2022-01-12T17:04:51","modified_gmt":"2022-01-12T16:04:51","slug":"thomas-arzt-die-gegenstimme","status":"publish","type":"post","link":"https:\/\/leckerekekse.de\/wordpress\/thomas-arzt-die-gegenstimme\/","title":{"rendered":"Thomas Arzt: Die Gegenstimme"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"377\" src=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2022\/01\/Thomas-Arzt-Gegenstimme-Rezension.jpg\" alt=\"Cover Thomas Arzt, Die Gegenstimme, Deb\u00fctpreis 2021\" class=\"wp-image-17020\" srcset=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2022\/01\/Thomas-Arzt-Gegenstimme-Rezension.jpg 640w, https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2022\/01\/Thomas-Arzt-Gegenstimme-Rezension-300x177.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">\u00d6sterreichischer Deb\u00fctroman<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">1938 gab es in \u00d6sterreich eine merkw\u00fcrdige, pseudodemokratische Wahl. Eine Volksabstimmung zum Anschluss \u00d6sterreichs an das deutsche Reich. Nachtr\u00e4glich.<br>Ein Ort in Ober\u00f6sterreich nimmt es sportlich und fordert von allen Wahlberechtigten ein einstimmiges Ergebnis. Nat\u00fcrlich f\u00fcr die Wiedervereinigung.<br>&nbsp;Doch da gibt es Karl, den Studenten, der f\u00fcr das Wochenende nach Hause gekommen ist. Er ist einer der wenigen, die die Wahlkabine benutzen. Das ist schon sehr verd\u00e4chtig.<\/p>\n\n\n\n<!--more-->\n\n\n\n<h3 class=\"wp-block-heading\">Einstimmigkeit<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Es wird Druck ausge\u00fcbt auf die wahlberechtigten Einwohner. Nicht-w\u00e4hlen gilt auch nicht. Diese Personen werden durch \u00f6ffentliche Markierung an der Haust\u00fcr blo\u00dfgestellt. Gegenstimmen kommen gar nicht in Frage.Schon der Wahlzettel macht klar, was hier gefordert ist: der Kreis mit dem \u201eNein\u201c ist viel kleiner, als der f\u00fcr das \u201eJa\u201c.<br>Gruselig. Nicht nur \u201eWahlrecht\u201c, sondern auch Wahlpflicht und auch noch genaues Beobachten, was angekreuzt wird.<br>Dabei gibt es einige, die dagegen sind. Die die braune Gefahr wittern.<br>Den nahenden Krieg sp\u00fcren auch viele, die aus \u00dcberzeugung mit \u201eJa stimmen. Sie begr\u00fc\u00dfen ihn und sehen sich nach Heldentum.<br>Und das in einer Zeit, in der die Verletzungen des vorherigen Weltkrieges bei den Veteranen noch \u00fcberall sichtbar sind.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Stil<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">F\u00fcr mich sehr gew\u00f6hnungsbed\u00fcrftig. Die Leseprobe habe ich nach einer Seite abgebrochen. Zu anstrengend erschien mir der mundartliche Touch. Die leicht verdrehten S\u00e4tze.<br>Doch nach ca. 20 Seiten hatte ich mich daran gew\u00f6hnt und das Buch wird super spannend.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Karl<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Er steht im Verdacht dagegen gestimmt zu haben. Doch wissen tut das au\u00dfer ihm niemand. Doch wer sollte es sonst gewesen sein?<br>Karl l\u00e4sst ein wenig in sich, sein Studenten- und Liebesleben blicken. Er ist in der Stadt anderen Einfl\u00fcssen ausgesetzt und das hat schon Exzesse der \u201eBraunen\u201c miterlebt.<br>Er streitet sich an dem Tag mit seiner Familie und fl\u00fcchtet in den Wald. Dort versteckt er sich vor der Welt.<br>Parallel rottet sich eine Gruppe junger Menschen, mehr oder weniger enthusiastisch, zusammen und sucht ihn. Sie haben Waffen dabei und sind bereit bis zum \u00c4u\u00dfersten zu gehen. Vielleicht nicht alle, aber die Zauderer werden unter Druck gesetzt.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"480\" src=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2022\/01\/IMG_0992.jpg\" alt=\"Cover ebook Thomas Arzt Die Gegenstimme mit fingiertem Wahlzettel\" class=\"wp-image-17029\" srcset=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2022\/01\/IMG_0992.jpg 640w, https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2022\/01\/IMG_0992-300x225.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><figcaption>Thomas Arzt, \u00a9 Joseph Krpelan<\/figcaption><\/figure><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Seppl<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Meine Lieblingsfigur. Ein Mann, der f\u00fcr eine Art Dorfdepp gehalten wird und sehr viel Mut beweist! Ein gutes Beispiel, dass viele Menschen kolossal untersch\u00e4tzt werden.<br>Seppl ist eine Art Dorf-Faktotum. Wird von einigen f\u00fcr dumm und willf\u00e4hrig gehalten. Er baut bei der Wahl mit auf. Hilft bei der Ausz\u00e4hlung. Aber Seppl ist irgendwie klar, dass Hitler f\u00fcr Menschen wie ihn nicht Gutes bedeutet. Er begehrt auf. Aber heimlich. Doch niemand traut ihm zu, dass er etwas anderes als mit Ja gestimmt haben k\u00f6nnte.<br>Er bekommt unheimliche Angst, dass es rauskommt. Das sein Stimmzettel ihm zugeordnet werden k\u00f6nnte.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Spannend<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">H\u00e4ufig laufen mehrere Handlungsstr\u00e4nge parallel. Dadurch nimmt das Buch eine ungeheure Spannung und ein ziemliches Tempo auf. Das stand f\u00fcr mich im krassen Gegensatz zu meinem inneren Bild von einem kleinen. Beschaulichen Ort in den Bergen.<br>Das Buch beinhaltet auch sehr viel Personal und ver\u00e4ndert st\u00e4ndig die Perspektive. Sehr rasant. Der Autor Thomas Arzt hat sich bereits einen Namen als Dramatiker gemacht. Vielleicht sollte er auch Drehb\u00fccher schreiben. Die packende Handlung eignet sich sicher auch gut als Film.<br>In einem <a href=\"https:\/\/www.br.de\/kultur\/thomas-arzt-die-gegenstimme-ard-radiofestival-100.html\">Interview mit dem BR<\/a> erz\u00e4hlt Arzt, die er die Personen in seinem Roman recherchiert hat.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Fazit<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.residenzverlag.com\/buch\/die-gegenstimme\">Die Gegenstimme<\/a> von Thomas Arzt hat mich Anfangs durch den ungew\u00f6hnlichen Stil irritiert. Doch sp\u00e4ter passt er einfach perfekt zu den beschriebenen Ereignissen. Das Buch ist ungeheuer spannend und l\u00e4sst viel Freiraum f\u00fcr die (bei mir immer wiederkehrenden) Fragen \u201eWie h\u00e4tte ich gehandelt\u201c und \u201eWie konnte es soweit kommen\u201c.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Der Bloggerpreis<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Das Blog <a href=\"https:\/\/dasdebuet.com\/\">Das Deb\u00fct<\/a> lobt allj\u00e4hrlich den Bloggerpreis f\u00fcr das beste Romandeb\u00fct aus.<br>Die Jury bilden dieses Jahr <a href=\"https:\/\/dasdebuet.com\/bloggerpreis\/teilnehmende-literaturblogger\/\">16 Literaturblogger*innen<\/a>.<br>Neben Thomas Arzt stehen folgende Autor*innen mit ihren Deb\u00fctromanen auf der <a href=\"https:\/\/dasdebuet.com\/2021\/12\/06\/das-debut-2021-die-shortlist\/\">Shortlist f\u00fcr 2021<\/a>:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ariane Koch \u2013 Die Aufdr\u00e4ngung<br>Sharon Dodua Otoo \u2013 <a href=\"https:\/\/leckerekekse.de\/wordpress\/rezension-adas-raum-von-sharon-dodua-otoo\/\">Adas Raum<\/a><br><a href=\"https:\/\/leckerekekse.de\/wordpress\/interview-stefanie-vor-schulte\/\">Stefanie vor Schulte<\/a> \u2013 <a href=\"https:\/\/leckerekekse.de\/wordpress\/stefanie-von-schulte-junge-mit-schwarzem-hahn\/\">Junge mit schwarzem Hahn<\/a><br>Jessica Lind \u2013 Mama<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Weitere Rezensionen von Jurymitgliedern zu &#8222;Die Gegenstimme&#8220;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/schiefgelesen.net\/2022\/01\/01\/der-mut-zum-widerstand-die-gegenstimme-von-thomas-arzt\/\">Schiefgelesen<\/a><br><a href=\"http:\/\/ruthjusten.de\/thomas-arzt-die-gegenstimme\">Ruth liest<\/a><br><a href=\"https:\/\/literaturgefluester.wordpress.com\/2022\/01\/08\/die-gegenstimme\/\">Literaturgefl\u00fcster<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00d6sterreichischer Deb\u00fctroman 1938 gab es in \u00d6sterreich eine merkw\u00fcrdige, pseudodemokratische Wahl. Eine Volksabstimmung zum Anschluss \u00d6sterreichs an das deutsche Reich. Nachtr\u00e4glich.Ein Ort in Ober\u00f6sterreich nimmt es sportlich und fordert von allen Wahlberechtigten ein einstimmiges Ergebnis. Nat\u00fcrlich f\u00fcr die Wiedervereinigung.&nbsp;Doch da gibt es Karl, den Studenten, der f\u00fcr das Wochenende nach Hause gekommen ist. Er ist [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":17020,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,3,788],"tags":[1046,57,1072,555,243],"class_list":["post-17016","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-buecher","category-rezension","tag-bloggerpreis","tag-debuet","tag-debuetroman","tag-nationalsozialismus","tag-oesterreich"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Thomas Arzt: Die Gegenstimme | Leckere Kekse &amp; mehr<\/title>\n<meta name=\"description\" content=\"Der Deb\u00fctroman von Thomas Arzt spielt in einem \u00f6sterreichischen Dorf anno 1938. Es gibt eine Gegenstimme gegen den Anschluss an Deutschland.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/leckerekekse.de\/wordpress\/thomas-arzt-die-gegenstimme\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Thomas Arzt: Die Gegenstimme | Leckere Kekse &amp; mehr\" \/>\n<meta property=\"og:description\" content=\"Der Deb\u00fctroman von Thomas Arzt spielt in einem \u00f6sterreichischen Dorf anno 1938. Es gibt eine Gegenstimme gegen den Anschluss an Deutschland.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/leckerekekse.de\/wordpress\/thomas-arzt-die-gegenstimme\/\" \/>\n<meta property=\"og:site_name\" content=\"Leckere Kekse &amp; mehr\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-14T11:04:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2022\/01\/Thomas-Arzt-Gegenstimme-Rezension.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"377\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Buchlieberin\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Buchlieberin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/thomas-arzt-die-gegenstimme\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/thomas-arzt-die-gegenstimme\\\/\"},\"author\":{\"name\":\"Buchlieberin\",\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/2374d41b5cda28a27f6924e58f3afcc2\"},\"headline\":\"Thomas Arzt: Die Gegenstimme\",\"datePublished\":\"2022-01-14T11:04:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/thomas-arzt-die-gegenstimme\\\/\"},\"wordCount\":703,\"commentCount\":5,\"publisher\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/72061e7e8c1c70c8e8e542a13e5acbfe\"},\"image\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/thomas-arzt-die-gegenstimme\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Thomas-Arzt-Gegenstimme-Rezension.jpg\",\"keywords\":[\"Bloggerpreis\",\"Deb\u00fct\",\"Deb\u00fctroman\",\"Nationalsozialismus\",\"\u00d6sterreich\"],\"articleSection\":{\"1\":\"B\u00fccher\",\"2\":\"Rezension\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/thomas-arzt-die-gegenstimme\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/thomas-arzt-die-gegenstimme\\\/\",\"url\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/thomas-arzt-die-gegenstimme\\\/\",\"name\":\"Thomas Arzt: Die Gegenstimme | Leckere Kekse &amp; mehr\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/thomas-arzt-die-gegenstimme\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/thomas-arzt-die-gegenstimme\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Thomas-Arzt-Gegenstimme-Rezension.jpg\",\"datePublished\":\"2022-01-14T11:04:00+00:00\",\"description\":\"Der Deb\u00fctroman von Thomas Arzt spielt in einem \u00f6sterreichischen Dorf anno 1938. Es gibt eine Gegenstimme gegen den Anschluss an Deutschland.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/thomas-arzt-die-gegenstimme\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/thomas-arzt-die-gegenstimme\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/thomas-arzt-die-gegenstimme\\\/#primaryimage\",\"url\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Thomas-Arzt-Gegenstimme-Rezension.jpg\",\"contentUrl\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Thomas-Arzt-Gegenstimme-Rezension.jpg\",\"width\":640,\"height\":377},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/thomas-arzt-die-gegenstimme\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Thomas Arzt: Die Gegenstimme\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#website\",\"url\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/\",\"name\":\"Leckere Kekse &amp; mehr\",\"description\":\"Kekse backen, B\u00fccher lesen und mehr\",\"publisher\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/72061e7e8c1c70c8e8e542a13e5acbfe\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/72061e7e8c1c70c8e8e542a13e5acbfe\",\"name\":\"Astrid\",\"logo\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/leckerekekse.de\\\/wordpress\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/2374d41b5cda28a27f6924e58f3afcc2\",\"name\":\"Buchlieberin\",\"sameAs\":[\"https:\\\/\\\/leckerekekse.de\\\/wordpress\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Thomas Arzt: Die Gegenstimme | Leckere Kekse &amp; mehr","description":"Der Deb\u00fctroman von Thomas Arzt spielt in einem \u00f6sterreichischen Dorf anno 1938. Es gibt eine Gegenstimme gegen den Anschluss an Deutschland.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/leckerekekse.de\/wordpress\/thomas-arzt-die-gegenstimme\/","og_locale":"de_DE","og_type":"article","og_title":"Thomas Arzt: Die Gegenstimme | Leckere Kekse &amp; mehr","og_description":"Der Deb\u00fctroman von Thomas Arzt spielt in einem \u00f6sterreichischen Dorf anno 1938. Es gibt eine Gegenstimme gegen den Anschluss an Deutschland.","og_url":"https:\/\/leckerekekse.de\/wordpress\/thomas-arzt-die-gegenstimme\/","og_site_name":"Leckere Kekse &amp; mehr","article_published_time":"2022-01-14T11:04:00+00:00","og_image":[{"width":640,"height":377,"url":"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2022\/01\/Thomas-Arzt-Gegenstimme-Rezension.jpg","type":"image\/jpeg"}],"author":"Buchlieberin","twitter_misc":{"Verfasst von":"Buchlieberin","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/leckerekekse.de\/wordpress\/thomas-arzt-die-gegenstimme\/#article","isPartOf":{"@id":"https:\/\/leckerekekse.de\/wordpress\/thomas-arzt-die-gegenstimme\/"},"author":{"name":"Buchlieberin","@id":"https:\/\/leckerekekse.de\/wordpress\/#\/schema\/person\/2374d41b5cda28a27f6924e58f3afcc2"},"headline":"Thomas Arzt: Die Gegenstimme","datePublished":"2022-01-14T11:04:00+00:00","mainEntityOfPage":{"@id":"https:\/\/leckerekekse.de\/wordpress\/thomas-arzt-die-gegenstimme\/"},"wordCount":703,"commentCount":5,"publisher":{"@id":"https:\/\/leckerekekse.de\/wordpress\/#\/schema\/person\/72061e7e8c1c70c8e8e542a13e5acbfe"},"image":{"@id":"https:\/\/leckerekekse.de\/wordpress\/thomas-arzt-die-gegenstimme\/#primaryimage"},"thumbnailUrl":"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2022\/01\/Thomas-Arzt-Gegenstimme-Rezension.jpg","keywords":["Bloggerpreis","Deb\u00fct","Deb\u00fctroman","Nationalsozialismus","\u00d6sterreich"],"articleSection":{"1":"B\u00fccher","2":"Rezension"},"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/leckerekekse.de\/wordpress\/thomas-arzt-die-gegenstimme\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/leckerekekse.de\/wordpress\/thomas-arzt-die-gegenstimme\/","url":"https:\/\/leckerekekse.de\/wordpress\/thomas-arzt-die-gegenstimme\/","name":"Thomas Arzt: Die Gegenstimme | Leckere Kekse &amp; mehr","isPartOf":{"@id":"https:\/\/leckerekekse.de\/wordpress\/#website"},"primaryImageOfPage":{"@id":"https:\/\/leckerekekse.de\/wordpress\/thomas-arzt-die-gegenstimme\/#primaryimage"},"image":{"@id":"https:\/\/leckerekekse.de\/wordpress\/thomas-arzt-die-gegenstimme\/#primaryimage"},"thumbnailUrl":"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2022\/01\/Thomas-Arzt-Gegenstimme-Rezension.jpg","datePublished":"2022-01-14T11:04:00+00:00","description":"Der Deb\u00fctroman von Thomas Arzt spielt in einem \u00f6sterreichischen Dorf anno 1938. Es gibt eine Gegenstimme gegen den Anschluss an Deutschland.","breadcrumb":{"@id":"https:\/\/leckerekekse.de\/wordpress\/thomas-arzt-die-gegenstimme\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/leckerekekse.de\/wordpress\/thomas-arzt-die-gegenstimme\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/leckerekekse.de\/wordpress\/thomas-arzt-die-gegenstimme\/#primaryimage","url":"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2022\/01\/Thomas-Arzt-Gegenstimme-Rezension.jpg","contentUrl":"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2022\/01\/Thomas-Arzt-Gegenstimme-Rezension.jpg","width":640,"height":377},{"@type":"BreadcrumbList","@id":"https:\/\/leckerekekse.de\/wordpress\/thomas-arzt-die-gegenstimme\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/leckerekekse.de\/wordpress\/"},{"@type":"ListItem","position":2,"name":"Thomas Arzt: Die Gegenstimme"}]},{"@type":"WebSite","@id":"https:\/\/leckerekekse.de\/wordpress\/#website","url":"https:\/\/leckerekekse.de\/wordpress\/","name":"Leckere Kekse &amp; mehr","description":"Kekse backen, B\u00fccher lesen und mehr","publisher":{"@id":"https:\/\/leckerekekse.de\/wordpress\/#\/schema\/person\/72061e7e8c1c70c8e8e542a13e5acbfe"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/leckerekekse.de\/wordpress\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/leckerekekse.de\/wordpress\/#\/schema\/person\/72061e7e8c1c70c8e8e542a13e5acbfe","name":"Astrid","logo":{"@id":"https:\/\/leckerekekse.de\/wordpress\/#\/schema\/person\/image\/"},"sameAs":["https:\/\/leckerekekse.de\/wordpress"]},{"@type":"Person","@id":"https:\/\/leckerekekse.de\/wordpress\/#\/schema\/person\/2374d41b5cda28a27f6924e58f3afcc2","name":"Buchlieberin","sameAs":["https:\/\/leckerekekse.de\/wordpress"]}]}},"_links":{"self":[{"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/posts\/17016","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/comments?post=17016"}],"version-history":[{"count":3,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/posts\/17016\/revisions"}],"predecessor-version":[{"id":17030,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/posts\/17016\/revisions\/17030"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/media\/17020"}],"wp:attachment":[{"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/media?parent=17016"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/categories?post=17016"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/tags?post=17016"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}