{"id":278,"date":"2014-09-07T11:32:33","date_gmt":"2014-09-07T09:32:33","guid":{"rendered":"http:\/\/leckerekekse.de\/wordpress\/?p=278"},"modified":"2018-10-09T09:39:18","modified_gmt":"2018-10-09T07:39:18","slug":"jean-echenoz-14","status":"publish","type":"post","link":"https:\/\/leckerekekse.de\/wordpress\/jean-echenoz-14\/","title":{"rendered":"Jean Echenoz: 14"},"content":{"rendered":"<h3><a href=\"http:\/\/www.hanser-literaturverlage.de\/buecher\/buch.html?isbn=978-3-446-24500-6\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-279\" src=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2014\/08\/14-183x300.jpg\" alt=\"Echenoz_24500_MR1.indd\" width=\"391\" height=\"640\" srcset=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2014\/08\/14-183x300.jpg 183w, https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2014\/08\/14-625x1024.jpg 625w, https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2014\/08\/14-1200x1964.jpg 1200w, https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2014\/08\/14-900x1473.jpg 900w, https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2014\/08\/14.jpg 1400w\" sizes=\"auto, (max-width: 391px) 100vw, 391px\" \/><\/a>Ein kleines Buch \u00fcber einen gro\u00dfen Krieg<\/h3>\n<p>1914.<\/p>\n<p>Anthime hat einen freien Tag und macht eine kleine Radtour. Da h\u00f6rt er Glocken l\u00e4uten.<\/p>\n<p>Die Mobilmachung!<\/p>\n<p>Er und einige seiner Freunde, wie auch sein Bruder Charles, finden sich am n\u00e4chsten Tag ein, um sich ordnungsgem\u00e4\u00df zu melden. Ganz Frankreich ist \u00fcberzeugt, dass der Krieg nur ein paar Wochen dauern wird.<br \/>\nCharles hinterl\u00e4sst die schwangere Blanche, Industriellentochter, in die auch Anthime verliebt ist.<\/p>\n<p>Im Krieg sind nicht alle Soldaten gleich: au\u00dfer den Rangunterschieden gibt es auch Unterschiede in der Todesart, der Schwere einer Verwundung und im Verm\u00f6gen die Gr\u00e4uel zu verwinden.<br \/>\nEin verlorener Arm wird als gl\u00fcckliche Verwundung angesehen. Denn danach muss man nicht mehr an die Front, man kommt aber noch besser durch das restliche Leben, als wenn ein Bein verloren ging.<\/p>\n<p>Das Buch hat ganze 79 Seiten (zumindest meine eBook-Ausgabe), schildert kompakt den Krieg aus Sicht franz\u00f6sischer Soldaten, der zur\u00fcckgebliebenen Zivilisten und den heimkehrenden Verwundeten.<br \/>\nAufgriffen werden auch ganz unvermutete Probleme wie die Langeweile im Sch\u00fctzengraben.<br \/>\nUmrahmt wird alles von neuem Leben welches den Krieg fast in den Hintergrund treten l\u00e4sst.<br \/>\nAlle Geschehnisse werden in einer fast beil\u00e4ufigen, undramatischen Art erz\u00e4hlt.<\/p>\n<p>F\u00fcr mich ein empfehlenswertes Buch um sich dem 1. Weltkrieg literarisch zu n\u00e4hern. Wem das dann schon zu heftig ist, sollte von weiteren B\u00fcchern zu diesem Thema besser absehen.<\/p>\n<p>Jean Echenoz kommt \u00fcbrigens auch kurz im Buch <a href=\"https:\/\/leckerekekse.de\/wordpress\/?p=175\">Zweiundzwanzig<\/a> von Jean-Phillipe Blondel vor.<\/p>\n<p>Jean Echenoz: 14, Hanser Berlin, ISBN 978-3-446-24500-6<br \/>\nLeseprobe: 14<br \/>\n&#x264c;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ein kleines Buch \u00fcber einen gro\u00dfen Krieg 1914. Anthime hat einen freien Tag und macht eine kleine Radtour. Da h\u00f6rt er Glocken l\u00e4uten. Die Mobilmachung! Er und einige seiner Freunde, wie auch sein Bruder Charles, finden sich am n\u00e4chsten Tag ein, um sich ordnungsgem\u00e4\u00df zu melden. Ganz Frankreich ist \u00fcberzeugt, dass der Krieg nur ein [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":279,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,3],"tags":[680,872],"class_list":["post-278","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-buecher","tag-europa","tag-weltkrieg"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Jean Echenoz: 14 | Leckere Kekse &amp; mehr<\/title>\n<meta name=\"description\" content=\"Ein empfehlenswertes Buch um sich dem 1. Weltkrieg literarisch zu n\u00e4hern. 14 von Jean Echenoz spielt in Frankreich und schildert den Ausbruch.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/leckerekekse.de\/wordpress\/jean-echenoz-14\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jean Echenoz: 14 | Leckere Kekse &amp; mehr\" \/>\n<meta property=\"og:description\" content=\"Ein empfehlenswertes Buch um sich dem 1. Weltkrieg literarisch zu n\u00e4hern. 14 von Jean Echenoz spielt in Frankreich und schildert den Ausbruch.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/leckerekekse.de\/wordpress\/jean-echenoz-14\/\" \/>\n<meta property=\"og:site_name\" content=\"Leckere Kekse &amp; mehr\" \/>\n<meta property=\"article:published_time\" content=\"2014-09-07T09:32:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-10-09T07:39:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2014\/08\/14.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t<meta property=\"og:image:height\" content=\"2292\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Buchlieberin\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Buchlieberin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/jean-echenoz-14\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/jean-echenoz-14\\\/\"},\"author\":{\"name\":\"Buchlieberin\",\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/2374d41b5cda28a27f6924e58f3afcc2\"},\"headline\":\"Jean Echenoz: 14\",\"datePublished\":\"2014-09-07T09:32:33+00:00\",\"dateModified\":\"2018-10-09T07:39:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/jean-echenoz-14\\\/\"},\"wordCount\":262,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/72061e7e8c1c70c8e8e542a13e5acbfe\"},\"image\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/jean-echenoz-14\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2014\\\/08\\\/14.jpg\",\"keywords\":[\"Europa\",\"Weltkrieg\"],\"articleSection\":{\"1\":\"B\u00fccher\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/jean-echenoz-14\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/jean-echenoz-14\\\/\",\"url\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/jean-echenoz-14\\\/\",\"name\":\"Jean Echenoz: 14 | Leckere Kekse &amp; mehr\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/jean-echenoz-14\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/jean-echenoz-14\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2014\\\/08\\\/14.jpg\",\"datePublished\":\"2014-09-07T09:32:33+00:00\",\"dateModified\":\"2018-10-09T07:39:18+00:00\",\"description\":\"Ein empfehlenswertes Buch um sich dem 1. Weltkrieg literarisch zu n\u00e4hern. 14 von Jean Echenoz spielt in Frankreich und schildert den Ausbruch.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/jean-echenoz-14\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/jean-echenoz-14\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/jean-echenoz-14\\\/#primaryimage\",\"url\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2014\\\/08\\\/14.jpg\",\"contentUrl\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2014\\\/08\\\/14.jpg\",\"width\":1400,\"height\":2292},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/jean-echenoz-14\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jean Echenoz: 14\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#website\",\"url\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/\",\"name\":\"Leckere Kekse &amp; mehr\",\"description\":\"Kekse backen, B\u00fccher lesen und mehr\",\"publisher\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/72061e7e8c1c70c8e8e542a13e5acbfe\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/72061e7e8c1c70c8e8e542a13e5acbfe\",\"name\":\"Astrid\",\"logo\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/leckerekekse.de\\\/wordpress\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/2374d41b5cda28a27f6924e58f3afcc2\",\"name\":\"Buchlieberin\",\"sameAs\":[\"https:\\\/\\\/leckerekekse.de\\\/wordpress\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jean Echenoz: 14 | Leckere Kekse &amp; mehr","description":"Ein empfehlenswertes Buch um sich dem 1. Weltkrieg literarisch zu n\u00e4hern. 14 von Jean Echenoz spielt in Frankreich und schildert den Ausbruch.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/leckerekekse.de\/wordpress\/jean-echenoz-14\/","og_locale":"de_DE","og_type":"article","og_title":"Jean Echenoz: 14 | Leckere Kekse &amp; mehr","og_description":"Ein empfehlenswertes Buch um sich dem 1. Weltkrieg literarisch zu n\u00e4hern. 14 von Jean Echenoz spielt in Frankreich und schildert den Ausbruch.","og_url":"https:\/\/leckerekekse.de\/wordpress\/jean-echenoz-14\/","og_site_name":"Leckere Kekse &amp; mehr","article_published_time":"2014-09-07T09:32:33+00:00","article_modified_time":"2018-10-09T07:39:18+00:00","og_image":[{"width":1400,"height":2292,"url":"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2014\/08\/14.jpg","type":"image\/jpeg"}],"author":"Buchlieberin","twitter_misc":{"Verfasst von":"Buchlieberin","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/leckerekekse.de\/wordpress\/jean-echenoz-14\/#article","isPartOf":{"@id":"https:\/\/leckerekekse.de\/wordpress\/jean-echenoz-14\/"},"author":{"name":"Buchlieberin","@id":"https:\/\/leckerekekse.de\/wordpress\/#\/schema\/person\/2374d41b5cda28a27f6924e58f3afcc2"},"headline":"Jean Echenoz: 14","datePublished":"2014-09-07T09:32:33+00:00","dateModified":"2018-10-09T07:39:18+00:00","mainEntityOfPage":{"@id":"https:\/\/leckerekekse.de\/wordpress\/jean-echenoz-14\/"},"wordCount":262,"commentCount":0,"publisher":{"@id":"https:\/\/leckerekekse.de\/wordpress\/#\/schema\/person\/72061e7e8c1c70c8e8e542a13e5acbfe"},"image":{"@id":"https:\/\/leckerekekse.de\/wordpress\/jean-echenoz-14\/#primaryimage"},"thumbnailUrl":"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2014\/08\/14.jpg","keywords":["Europa","Weltkrieg"],"articleSection":{"1":"B\u00fccher"},"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/leckerekekse.de\/wordpress\/jean-echenoz-14\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/leckerekekse.de\/wordpress\/jean-echenoz-14\/","url":"https:\/\/leckerekekse.de\/wordpress\/jean-echenoz-14\/","name":"Jean Echenoz: 14 | Leckere Kekse &amp; mehr","isPartOf":{"@id":"https:\/\/leckerekekse.de\/wordpress\/#website"},"primaryImageOfPage":{"@id":"https:\/\/leckerekekse.de\/wordpress\/jean-echenoz-14\/#primaryimage"},"image":{"@id":"https:\/\/leckerekekse.de\/wordpress\/jean-echenoz-14\/#primaryimage"},"thumbnailUrl":"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2014\/08\/14.jpg","datePublished":"2014-09-07T09:32:33+00:00","dateModified":"2018-10-09T07:39:18+00:00","description":"Ein empfehlenswertes Buch um sich dem 1. Weltkrieg literarisch zu n\u00e4hern. 14 von Jean Echenoz spielt in Frankreich und schildert den Ausbruch.","breadcrumb":{"@id":"https:\/\/leckerekekse.de\/wordpress\/jean-echenoz-14\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/leckerekekse.de\/wordpress\/jean-echenoz-14\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/leckerekekse.de\/wordpress\/jean-echenoz-14\/#primaryimage","url":"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2014\/08\/14.jpg","contentUrl":"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2014\/08\/14.jpg","width":1400,"height":2292},{"@type":"BreadcrumbList","@id":"https:\/\/leckerekekse.de\/wordpress\/jean-echenoz-14\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/leckerekekse.de\/wordpress\/"},{"@type":"ListItem","position":2,"name":"Jean Echenoz: 14"}]},{"@type":"WebSite","@id":"https:\/\/leckerekekse.de\/wordpress\/#website","url":"https:\/\/leckerekekse.de\/wordpress\/","name":"Leckere Kekse &amp; mehr","description":"Kekse backen, B\u00fccher lesen und mehr","publisher":{"@id":"https:\/\/leckerekekse.de\/wordpress\/#\/schema\/person\/72061e7e8c1c70c8e8e542a13e5acbfe"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/leckerekekse.de\/wordpress\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/leckerekekse.de\/wordpress\/#\/schema\/person\/72061e7e8c1c70c8e8e542a13e5acbfe","name":"Astrid","logo":{"@id":"https:\/\/leckerekekse.de\/wordpress\/#\/schema\/person\/image\/"},"sameAs":["https:\/\/leckerekekse.de\/wordpress"]},{"@type":"Person","@id":"https:\/\/leckerekekse.de\/wordpress\/#\/schema\/person\/2374d41b5cda28a27f6924e58f3afcc2","name":"Buchlieberin","sameAs":["https:\/\/leckerekekse.de\/wordpress"]}]}},"_links":{"self":[{"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/posts\/278","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/comments?post=278"}],"version-history":[{"count":3,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/posts\/278\/revisions"}],"predecessor-version":[{"id":12276,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/posts\/278\/revisions\/12276"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/media\/279"}],"wp:attachment":[{"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/media?parent=278"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/categories?post=278"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/tags?post=278"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}