{"id":4954,"date":"2016-01-17T07:26:26","date_gmt":"2016-01-17T05:26:26","guid":{"rendered":"http:\/\/leckerekekse.de\/wordpress\/?p=4954"},"modified":"2016-01-19T18:40:00","modified_gmt":"2016-01-19T16:40:00","slug":"paul-auster-winterjournal","status":"publish","type":"post","link":"https:\/\/leckerekekse.de\/wordpress\/paul-auster-winterjournal\/","title":{"rendered":"Paul Auster: Winterjournal"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-5085 aligncenter\" src=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2016\/01\/Winterjournal-10.jpg\" alt=\"Paul Auster Winterjournal\" width=\"640\" height=\"427\" srcset=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2016\/01\/Winterjournal-10.jpg 640w, https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2016\/01\/Winterjournal-10-300x200.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<p>Seit ich vor meinem New York Urlaub <a href=\"https:\/\/leckerekekse.de\/wordpress\/buchtipps-fuer-new-york\/\" target=\"_blank\">Biografien \u00fcber New Yorker<\/a> gelesen habe, wollte ich unbedingt mal wieder ein Buch von Paul Auster lesen. &#8222;Mond \u00fcber Manhattan&#8220; hatte ich vor ewigen Zeit gelesen und nicht mehr in Erinnerung. Und ehrlich gesagt: irgendwann entsorgt! Da Auster schon so viele B\u00fccher verfasst hat, wu\u00dfte ich nun aber gar nicht, mit welchem ich beginnen sollte. Da empfahl mir die <a href=\"http:\/\/dieBuchbloggerin.de\" target=\"_blank\">Buchbloggerin<\/a>\u00a0eines Tages &#8222;Winterjournal&#8220;. Das kam zur richtigen Zeit. Vielen Dank Frederike.<!--more--><\/p>\n<p>Paul Auster zieht in seinem Buch Bilanz seines bisherigen Lebens. Er ist 63 Jahre alt, als er das Buch schreibt. Angefangen bei seiner Kindheit, Pubert\u00e4t bis hin zu seinem heutigen Leben. Da er in sehr vielen Wohnungen gelebt hat, in 21, um genau zu sein, berichtet er in mehr als 50 Seiten von jeder einzelnen. Spannend fand ich nat\u00fcrlich, dass er auch eine kurze Zeit in der N\u00e4he meines Urlaubsappartments gewohnt hat.<\/p>\n<p>Er berichtet sehr ausf\u00fchrlich \u00fcber viele Bereiche seinens Lebens. Besonders seine Eltern nehmen einen gro\u00dfen Teil des Buches ein.<\/p>\n<p>Auch \u00fcber seine ersten Alterserscheinungen spricht er offen. \u00dcber den Spruch eines Freundes denkt er lange nach<\/p>\n<blockquote><p>Paul, ich m\u00f6chte ihnen etwas sagen. Mit siebenundf\u00fcnfzig habe ich mich alt gef\u00fchlt. Jetzt, mit vierundsiebzig, f\u00fchle ich mich viel j\u00fcnger als damals.<\/p><\/blockquote>\n<p>Sehr liebevoll beschreibt er seine Liebesbeziehungen, seine zwei Ehen. Und nat\u00fcrlich seine Liebe zu New York. Mir ist ein wenig der Atem gestockt, als er vom 11. September schrieb. Wie muss es f\u00fcr jemanden sein, der tagt\u00e4glich an dieses Ereignis erinnert wird?<\/p>\n<blockquote><p>&#8230; seither weiterhin zwei- oder dreimal die Woche die Br\u00fccke \u00fcberquert hast, ist die Fahrt nicht mehr dieselbe, die Toten sind immer noch da, auch die T\u00fcrme sind noch da &#8211; pulsieren in der Erinnerung, anwesend als leeres Loch im Himmel.<\/p><\/blockquote>\n<p>Dieses Buch war f\u00fcr mich ein besonderes Lesevergn\u00fcgen. Ich f\u00fchlte mich au\u00dferordentlich wohl bei der Lekt\u00fcre. F\u00fcr leidenschaftliche Leser ist es doch auch immer wieder spannend, \u00fcber das Leben eines Autors zu lesen. Immer wieder bin ich erstaunt, dass das nahe Umfeld von Autoren h\u00e4ufig kein Interesse an den Werken der Autoren zeigt. Auster berichtet von seiner Mutter, die kein einziges Buch von ihm gelesen hat. Zwar standen sie alle an einem besonderes Platz in ihrer Wohnung, aber deren Inhalte kannte sie angeblich nicht.<\/p>\n<p>Ein sehr pers\u00f6nliches Buch, ich glaube, ich muss noch mehr von diesem Autor lesen.<\/p>\n<p>&nbsp;<\/p>\n<p>Paul Auster, Winterjournal, ISBN: 9783499259500, Rowohlt Taschenbuch Verlag, 254 Seiten, 10,99 \u20ac<\/p>\n<p><a href=\"https:\/\/leckerekekse.de\/wordpress\/wp-admin\/post.php?post=4954&amp;action=edit\" target=\"_blank\">Verlagsseite<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Seit ich vor meinem New York Urlaub Biografien \u00fcber New Yorker gelesen habe, wollte ich unbedingt mal wieder ein Buch von Paul Auster lesen. &#8222;Mond \u00fcber Manhattan&#8220; hatte ich vor ewigen Zeit gelesen und nicht mehr in Erinnerung. Und ehrlich gesagt: irgendwann entsorgt! Da Auster schon so viele B\u00fccher verfasst hat, wu\u00dfte ich nun aber [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5085,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,3],"tags":[674,244,104,672,673],"class_list":["post-4954","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-buecher","tag-autor","tag-leben","tag-new-york","tag-paul-auster","tag-winterjournal"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Paul Auster: Winterjournal | Leckere Kekse &amp; mehr<\/title>\n<meta name=\"description\" content=\"Paul Auster schreibt in seinem Buch &quot;Winterjournal&quot; \u00fcber sein bisheriges Leben. \u00dcber seine Eltern, Liebesbeziehungen zu Frauen und seiner Stadt New York\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/leckerekekse.de\/wordpress\/paul-auster-winterjournal\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Paul Auster: Winterjournal | Leckere Kekse &amp; mehr\" \/>\n<meta property=\"og:description\" content=\"Paul Auster schreibt in seinem Buch &quot;Winterjournal&quot; \u00fcber sein bisheriges Leben. \u00dcber seine Eltern, Liebesbeziehungen zu Frauen und seiner Stadt New York\" \/>\n<meta property=\"og:url\" content=\"https:\/\/leckerekekse.de\/wordpress\/paul-auster-winterjournal\/\" \/>\n<meta property=\"og:site_name\" content=\"Leckere Kekse &amp; mehr\" \/>\n<meta property=\"article:published_time\" content=\"2016-01-17T05:26:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-01-19T16:40:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2016\/01\/Winterjournal-10.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"427\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Astrid\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Astrid\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/paul-auster-winterjournal\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/paul-auster-winterjournal\\\/\"},\"author\":{\"name\":\"Astrid\",\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/72061e7e8c1c70c8e8e542a13e5acbfe\"},\"headline\":\"Paul Auster: Winterjournal\",\"datePublished\":\"2016-01-17T05:26:26+00:00\",\"dateModified\":\"2016-01-19T16:40:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/paul-auster-winterjournal\\\/\"},\"wordCount\":423,\"commentCount\":7,\"publisher\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/72061e7e8c1c70c8e8e542a13e5acbfe\"},\"image\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/paul-auster-winterjournal\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/Winterjournal-10.jpg\",\"keywords\":[\"Autor\",\"Leben\",\"New York\",\"Paul Auster\",\"Winterjournal\"],\"articleSection\":{\"1\":\"B\u00fccher\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/paul-auster-winterjournal\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/paul-auster-winterjournal\\\/\",\"url\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/paul-auster-winterjournal\\\/\",\"name\":\"Paul Auster: Winterjournal | Leckere Kekse &amp; mehr\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/paul-auster-winterjournal\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/paul-auster-winterjournal\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/Winterjournal-10.jpg\",\"datePublished\":\"2016-01-17T05:26:26+00:00\",\"dateModified\":\"2016-01-19T16:40:00+00:00\",\"description\":\"Paul Auster schreibt in seinem Buch \\\"Winterjournal\\\" \u00fcber sein bisheriges Leben. \u00dcber seine Eltern, Liebesbeziehungen zu Frauen und seiner Stadt New York\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/paul-auster-winterjournal\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/paul-auster-winterjournal\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/paul-auster-winterjournal\\\/#primaryimage\",\"url\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/Winterjournal-10.jpg\",\"contentUrl\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/Winterjournal-10.jpg\",\"width\":640,\"height\":427,\"caption\":\"Paul Auster Winterjournal\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/paul-auster-winterjournal\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Paul Auster: Winterjournal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#website\",\"url\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/\",\"name\":\"Leckere Kekse &amp; mehr\",\"description\":\"Kekse backen, B\u00fccher lesen und mehr\",\"publisher\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/72061e7e8c1c70c8e8e542a13e5acbfe\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/72061e7e8c1c70c8e8e542a13e5acbfe\",\"name\":\"Astrid\",\"logo\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/leckerekekse.de\\\/wordpress\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Paul Auster: Winterjournal | Leckere Kekse &amp; mehr","description":"Paul Auster schreibt in seinem Buch \"Winterjournal\" \u00fcber sein bisheriges Leben. \u00dcber seine Eltern, Liebesbeziehungen zu Frauen und seiner Stadt New York","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/leckerekekse.de\/wordpress\/paul-auster-winterjournal\/","og_locale":"de_DE","og_type":"article","og_title":"Paul Auster: Winterjournal | Leckere Kekse &amp; mehr","og_description":"Paul Auster schreibt in seinem Buch \"Winterjournal\" \u00fcber sein bisheriges Leben. \u00dcber seine Eltern, Liebesbeziehungen zu Frauen und seiner Stadt New York","og_url":"https:\/\/leckerekekse.de\/wordpress\/paul-auster-winterjournal\/","og_site_name":"Leckere Kekse &amp; mehr","article_published_time":"2016-01-17T05:26:26+00:00","article_modified_time":"2016-01-19T16:40:00+00:00","og_image":[{"width":640,"height":427,"url":"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2016\/01\/Winterjournal-10.jpg","type":"image\/jpeg"}],"author":"Astrid","twitter_misc":{"Verfasst von":"Astrid","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/leckerekekse.de\/wordpress\/paul-auster-winterjournal\/#article","isPartOf":{"@id":"https:\/\/leckerekekse.de\/wordpress\/paul-auster-winterjournal\/"},"author":{"name":"Astrid","@id":"https:\/\/leckerekekse.de\/wordpress\/#\/schema\/person\/72061e7e8c1c70c8e8e542a13e5acbfe"},"headline":"Paul Auster: Winterjournal","datePublished":"2016-01-17T05:26:26+00:00","dateModified":"2016-01-19T16:40:00+00:00","mainEntityOfPage":{"@id":"https:\/\/leckerekekse.de\/wordpress\/paul-auster-winterjournal\/"},"wordCount":423,"commentCount":7,"publisher":{"@id":"https:\/\/leckerekekse.de\/wordpress\/#\/schema\/person\/72061e7e8c1c70c8e8e542a13e5acbfe"},"image":{"@id":"https:\/\/leckerekekse.de\/wordpress\/paul-auster-winterjournal\/#primaryimage"},"thumbnailUrl":"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2016\/01\/Winterjournal-10.jpg","keywords":["Autor","Leben","New York","Paul Auster","Winterjournal"],"articleSection":{"1":"B\u00fccher"},"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/leckerekekse.de\/wordpress\/paul-auster-winterjournal\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/leckerekekse.de\/wordpress\/paul-auster-winterjournal\/","url":"https:\/\/leckerekekse.de\/wordpress\/paul-auster-winterjournal\/","name":"Paul Auster: Winterjournal | Leckere Kekse &amp; mehr","isPartOf":{"@id":"https:\/\/leckerekekse.de\/wordpress\/#website"},"primaryImageOfPage":{"@id":"https:\/\/leckerekekse.de\/wordpress\/paul-auster-winterjournal\/#primaryimage"},"image":{"@id":"https:\/\/leckerekekse.de\/wordpress\/paul-auster-winterjournal\/#primaryimage"},"thumbnailUrl":"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2016\/01\/Winterjournal-10.jpg","datePublished":"2016-01-17T05:26:26+00:00","dateModified":"2016-01-19T16:40:00+00:00","description":"Paul Auster schreibt in seinem Buch \"Winterjournal\" \u00fcber sein bisheriges Leben. \u00dcber seine Eltern, Liebesbeziehungen zu Frauen und seiner Stadt New York","breadcrumb":{"@id":"https:\/\/leckerekekse.de\/wordpress\/paul-auster-winterjournal\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/leckerekekse.de\/wordpress\/paul-auster-winterjournal\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/leckerekekse.de\/wordpress\/paul-auster-winterjournal\/#primaryimage","url":"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2016\/01\/Winterjournal-10.jpg","contentUrl":"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2016\/01\/Winterjournal-10.jpg","width":640,"height":427,"caption":"Paul Auster Winterjournal"},{"@type":"BreadcrumbList","@id":"https:\/\/leckerekekse.de\/wordpress\/paul-auster-winterjournal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/leckerekekse.de\/wordpress\/"},{"@type":"ListItem","position":2,"name":"Paul Auster: Winterjournal"}]},{"@type":"WebSite","@id":"https:\/\/leckerekekse.de\/wordpress\/#website","url":"https:\/\/leckerekekse.de\/wordpress\/","name":"Leckere Kekse &amp; mehr","description":"Kekse backen, B\u00fccher lesen und mehr","publisher":{"@id":"https:\/\/leckerekekse.de\/wordpress\/#\/schema\/person\/72061e7e8c1c70c8e8e542a13e5acbfe"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/leckerekekse.de\/wordpress\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/leckerekekse.de\/wordpress\/#\/schema\/person\/72061e7e8c1c70c8e8e542a13e5acbfe","name":"Astrid","logo":{"@id":"https:\/\/leckerekekse.de\/wordpress\/#\/schema\/person\/image\/"},"sameAs":["https:\/\/leckerekekse.de\/wordpress"]}]}},"_links":{"self":[{"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/posts\/4954","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/comments?post=4954"}],"version-history":[{"count":3,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/posts\/4954\/revisions"}],"predecessor-version":[{"id":5147,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/posts\/4954\/revisions\/5147"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/media\/5085"}],"wp:attachment":[{"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/media?parent=4954"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/categories?post=4954"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/tags?post=4954"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}