{"id":7653,"date":"2016-12-11T08:02:33","date_gmt":"2016-12-11T07:02:33","guid":{"rendered":"http:\/\/leckerekekse.de\/wordpress\/?p=7653"},"modified":"2021-03-27T16:36:23","modified_gmt":"2021-03-27T15:36:23","slug":"steven-mccurry-lesen","status":"publish","type":"post","link":"https:\/\/leckerekekse.de\/wordpress\/steven-mccurry-lesen\/","title":{"rendered":"Steven McCurry: Lesen"},"content":{"rendered":"<h3><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-7654\" src=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2016\/11\/Buch-lesen-4.jpg\" alt=\"lesen\" width=\"640\" height=\"427\" srcset=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2016\/11\/Buch-lesen-4.jpg 640w, https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2016\/11\/Buch-lesen-4-300x200.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/h3>\n<h3>Eine Leidenschaft ohne Grenzen<\/h3>\n<p>Warum sind wir Buchmenschen eigentlich alle so verr\u00fcckt? Wir brauchen nicht nur B\u00fccher zum Lesen! Wir brauchen auch B\u00fccher um uns rum, wir laufen st\u00e4ndig in eine Buchhandlung, weil wir uns dort alle so wohl f\u00fchlen. Wir sehen gerne lesende Menschen, wir fotografieren gerne lesende Menschen.\u00a0<!--more--><\/p>\n<p>Steve McCurry, einer der bekanntesten Fotografen der Welt, hat jetzt ein Buch herausgebracht mit Fotos von lesenden Menschen. Viel lesen k\u00f6nnen wir in diesem Buch nicht, aber daf\u00fcr mit Hingabe Fotografien von Lesern bewundern.<\/p>\n<p>McCurry ist auf der ganzen Welt unterwegs. \u00dcberall hat er Menschen mit B\u00fcchern, Zeitungen oder \u00e4hnlichem fotografiert.<\/p>\n<p>Sehr unterschiedlich sind seine Aufnahmen, die er f\u00fcr das Buch ausgew\u00e4hlt hat. S\u00e4mtliche Altersgruppen sind vertreten, allerdings wesentlich mehr M\u00e4nner als Frauen. Da McCurry viel in L\u00e4ndern der dritten Welt unterwegs ist, frage ich mich, ob das Leseverhalten dort anders ist. W\u00e4hrend in Europa wesentlich mehr Frauen lesen, ist es dort den Bildern zu urteilen, anders.<\/p>\n<h3>Das Sch\u00f6nste ist das Cover<\/h3>\n<p>Das Sch\u00f6nste aller Bilder ist auf dem Cover abgebildet. So kann man das Buch super mit der Front ins Regal stellen und sich daran erfreuen.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-7655\" src=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2016\/11\/Buch-lesen-7.jpg\" alt=\"buch-lesen-7\" width=\"640\" height=\"427\" srcset=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2016\/11\/Buch-lesen-7.jpg 640w, https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2016\/11\/Buch-lesen-7-300x200.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<p>Das Buch beginnt mit einem Vorwort von Paul Theroux, einem amerikanischen Reiseschriftsteller. Er ist nicht nur Autor, sondern auch begeisterter Leser. \u00dcber diese Leidenschaft spricht er im Vorwort. Mit jedem Satz spricht er uns Lesern aus der Seele.<\/p>\n<h3>Der gro\u00dfe Unterschied<\/h3>\n<blockquote><p>Der gro\u00dfe Unterschied in der Welt, wie ich sie kenne, besteht nicht darin, dass es alte und junge Menschen gibt, schwarze und wei\u00dfe, Menschen der Dritten und Menschen der Ersten Welt, reiche und arme, gebildete und ungebildete, erwerbst\u00e4tige und arbeitslose Menschen, sondern darin, dass es Menschen gibt, die lesen, und andere, die nicht lesen. Die meisten tun es nicht.<\/p><\/blockquote>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-7657\" src=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2016\/11\/Buch-lesen-9.jpg\" alt=\"buch-lesen-9\" width=\"640\" height=\"427\" srcset=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2016\/11\/Buch-lesen-9.jpg 640w, https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2016\/11\/Buch-lesen-9-300x200.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<p>&nbsp;<\/p>\n<h3>Lesen ist eine ernste Angelegenheit<\/h3>\n<blockquote><p>&nbsp;<\/p>\n<p>Lesen ist eine ernste Angelegenheit, doch einsam oder gelangweilt sind Leser selten, denn Lesen ist eine Zuflucht und eine Erleuchtung, eine Erfahrung, die zuweilen offen zutage tritt. Mir kommt es immer so vor, als ginge vom Gesicht eines lesenden Menschen etwas Strahlendes aus.<\/p><\/blockquote>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-7656\" src=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2016\/11\/Buch-lesen-8.jpg\" alt=\"buch-lesen-8\" width=\"640\" height=\"427\" srcset=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2016\/11\/Buch-lesen-8.jpg 640w, https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2016\/11\/Buch-lesen-8-300x200.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Theroux beschreibt die Bilder von McCurry folgenderma\u00dfen:<\/p>\n<blockquote><p>Die Selbstvergessenheit des Lesers, der leuchtende Blick, die Vorstellung von Abgeschiedenheit, die entspannte K\u00f6rperhaltung, die besondere Art von Leistung, der Entdeckungsdrang \u2013 und einen Eindruck purer Freude.<\/p><\/blockquote>\n<p>Mir gefallen Bildb\u00e4nde sehr. Und einer \u00fcber lesende M\u00e4nner, Frauen und Kinder umso mehr. Ein Buch f\u00fcr lange Winterabende, an denen man sich ein Buch nach dem anderen immer wieder aus dem Regal holen kann, um darin in Seelenruhe zu bl\u00e4ttern. Die Welt da drau\u00dfen ist im Winterschlaf und macht uns kein schlechtes Gewissen, wenn wir nur ruhig dasitzen und staunen.<\/p>\n<p>&nbsp;<\/p>\n<h3>Buchdaten<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-7658 alignright\" src=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2016\/11\/McCurry_Lesen_169594.jpg\" alt=\"Lesen\" width=\"300\" height=\"224\" \/><\/p>\n<p><strong>Paul Theroux<\/strong><br \/>\n<strong>Steve McCurry<\/strong><br \/>\n<strong> Lesen<\/strong><br \/>\n<strong>Eine Leidenschaft ohne Grenzen<\/strong><\/p>\n<p>Gebunden<\/p>\n<p>ISBN: 978-3-7913-8275-3<\/p>\n<p>Prestel Verlag<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-5968\" src=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2016\/04\/Astrid-Signatur.jpeg\" alt=\"Astrid-Signatur\" width=\"206\" height=\"97\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Eine Leidenschaft ohne Grenzen Warum sind wir Buchmenschen eigentlich alle so verr\u00fcckt? Wir brauchen nicht nur B\u00fccher zum Lesen! Wir brauchen auch B\u00fccher um uns rum, wir laufen st\u00e4ndig in eine Buchhandlung, weil wir uns dort alle so wohl f\u00fchlen. Wir sehen gerne lesende Menschen, wir fotografieren gerne lesende Menschen.\u00a0<\/p>\n","protected":false},"author":1,"featured_media":7654,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,3,788],"tags":[897,387,422,433],"class_list":["post-7653","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-buecher","category-rezension","tag-foto","tag-fotografie","tag-fotos","tag-lesen"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Steven McCurry: Lesen | Leckere Kekse &amp; mehr<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/leckerekekse.de\/wordpress\/steven-mccurry-lesen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Steven McCurry: Lesen | Leckere Kekse &amp; mehr\" \/>\n<meta property=\"og:description\" content=\"Eine Leidenschaft ohne Grenzen Warum sind wir Buchmenschen eigentlich alle so verr\u00fcckt? Wir brauchen nicht nur B\u00fccher zum Lesen! Wir brauchen auch B\u00fccher um uns rum, wir laufen st\u00e4ndig in eine Buchhandlung, weil wir uns dort alle so wohl f\u00fchlen. Wir sehen gerne lesende Menschen, wir fotografieren gerne lesende Menschen.\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/leckerekekse.de\/wordpress\/steven-mccurry-lesen\/\" \/>\n<meta property=\"og:site_name\" content=\"Leckere Kekse &amp; mehr\" \/>\n<meta property=\"article:published_time\" content=\"2016-12-11T07:02:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-27T15:36:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2016\/11\/Buch-lesen-4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"427\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Astrid\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Astrid\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/steven-mccurry-lesen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/steven-mccurry-lesen\\\/\"},\"author\":{\"name\":\"Astrid\",\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/72061e7e8c1c70c8e8e542a13e5acbfe\"},\"headline\":\"Steven McCurry: Lesen\",\"datePublished\":\"2016-12-11T07:02:33+00:00\",\"dateModified\":\"2021-03-27T15:36:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/steven-mccurry-lesen\\\/\"},\"wordCount\":483,\"commentCount\":2,\"publisher\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/72061e7e8c1c70c8e8e542a13e5acbfe\"},\"image\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/steven-mccurry-lesen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/Buch-lesen-4.jpg\",\"keywords\":[\"Foto\",\"Fotografie\",\"Fotos\",\"lesen\"],\"articleSection\":{\"1\":\"B\u00fccher\",\"2\":\"Rezension\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/steven-mccurry-lesen\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/steven-mccurry-lesen\\\/\",\"url\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/steven-mccurry-lesen\\\/\",\"name\":\"Steven McCurry: Lesen | Leckere Kekse &amp; mehr\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/steven-mccurry-lesen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/steven-mccurry-lesen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/Buch-lesen-4.jpg\",\"datePublished\":\"2016-12-11T07:02:33+00:00\",\"dateModified\":\"2021-03-27T15:36:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/steven-mccurry-lesen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/steven-mccurry-lesen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/steven-mccurry-lesen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/Buch-lesen-4.jpg\",\"contentUrl\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/Buch-lesen-4.jpg\",\"width\":640,\"height\":427,\"caption\":\"lesen\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/steven-mccurry-lesen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Steven McCurry: Lesen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#website\",\"url\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/\",\"name\":\"Leckere Kekse &amp; mehr\",\"description\":\"Kekse backen, B\u00fccher lesen und mehr\",\"publisher\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/72061e7e8c1c70c8e8e542a13e5acbfe\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/72061e7e8c1c70c8e8e542a13e5acbfe\",\"name\":\"Astrid\",\"logo\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/leckerekekse.de\\\/wordpress\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Steven McCurry: Lesen | Leckere Kekse &amp; mehr","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/leckerekekse.de\/wordpress\/steven-mccurry-lesen\/","og_locale":"de_DE","og_type":"article","og_title":"Steven McCurry: Lesen | Leckere Kekse &amp; mehr","og_description":"Eine Leidenschaft ohne Grenzen Warum sind wir Buchmenschen eigentlich alle so verr\u00fcckt? Wir brauchen nicht nur B\u00fccher zum Lesen! Wir brauchen auch B\u00fccher um uns rum, wir laufen st\u00e4ndig in eine Buchhandlung, weil wir uns dort alle so wohl f\u00fchlen. Wir sehen gerne lesende Menschen, wir fotografieren gerne lesende Menschen.\u00a0","og_url":"https:\/\/leckerekekse.de\/wordpress\/steven-mccurry-lesen\/","og_site_name":"Leckere Kekse &amp; mehr","article_published_time":"2016-12-11T07:02:33+00:00","article_modified_time":"2021-03-27T15:36:23+00:00","og_image":[{"width":640,"height":427,"url":"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2016\/11\/Buch-lesen-4.jpg","type":"image\/jpeg"}],"author":"Astrid","twitter_misc":{"Verfasst von":"Astrid","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/leckerekekse.de\/wordpress\/steven-mccurry-lesen\/#article","isPartOf":{"@id":"https:\/\/leckerekekse.de\/wordpress\/steven-mccurry-lesen\/"},"author":{"name":"Astrid","@id":"https:\/\/leckerekekse.de\/wordpress\/#\/schema\/person\/72061e7e8c1c70c8e8e542a13e5acbfe"},"headline":"Steven McCurry: Lesen","datePublished":"2016-12-11T07:02:33+00:00","dateModified":"2021-03-27T15:36:23+00:00","mainEntityOfPage":{"@id":"https:\/\/leckerekekse.de\/wordpress\/steven-mccurry-lesen\/"},"wordCount":483,"commentCount":2,"publisher":{"@id":"https:\/\/leckerekekse.de\/wordpress\/#\/schema\/person\/72061e7e8c1c70c8e8e542a13e5acbfe"},"image":{"@id":"https:\/\/leckerekekse.de\/wordpress\/steven-mccurry-lesen\/#primaryimage"},"thumbnailUrl":"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2016\/11\/Buch-lesen-4.jpg","keywords":["Foto","Fotografie","Fotos","lesen"],"articleSection":{"1":"B\u00fccher","2":"Rezension"},"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/leckerekekse.de\/wordpress\/steven-mccurry-lesen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/leckerekekse.de\/wordpress\/steven-mccurry-lesen\/","url":"https:\/\/leckerekekse.de\/wordpress\/steven-mccurry-lesen\/","name":"Steven McCurry: Lesen | Leckere Kekse &amp; mehr","isPartOf":{"@id":"https:\/\/leckerekekse.de\/wordpress\/#website"},"primaryImageOfPage":{"@id":"https:\/\/leckerekekse.de\/wordpress\/steven-mccurry-lesen\/#primaryimage"},"image":{"@id":"https:\/\/leckerekekse.de\/wordpress\/steven-mccurry-lesen\/#primaryimage"},"thumbnailUrl":"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2016\/11\/Buch-lesen-4.jpg","datePublished":"2016-12-11T07:02:33+00:00","dateModified":"2021-03-27T15:36:23+00:00","breadcrumb":{"@id":"https:\/\/leckerekekse.de\/wordpress\/steven-mccurry-lesen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/leckerekekse.de\/wordpress\/steven-mccurry-lesen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/leckerekekse.de\/wordpress\/steven-mccurry-lesen\/#primaryimage","url":"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2016\/11\/Buch-lesen-4.jpg","contentUrl":"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2016\/11\/Buch-lesen-4.jpg","width":640,"height":427,"caption":"lesen"},{"@type":"BreadcrumbList","@id":"https:\/\/leckerekekse.de\/wordpress\/steven-mccurry-lesen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/leckerekekse.de\/wordpress\/"},{"@type":"ListItem","position":2,"name":"Steven McCurry: Lesen"}]},{"@type":"WebSite","@id":"https:\/\/leckerekekse.de\/wordpress\/#website","url":"https:\/\/leckerekekse.de\/wordpress\/","name":"Leckere Kekse &amp; mehr","description":"Kekse backen, B\u00fccher lesen und mehr","publisher":{"@id":"https:\/\/leckerekekse.de\/wordpress\/#\/schema\/person\/72061e7e8c1c70c8e8e542a13e5acbfe"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/leckerekekse.de\/wordpress\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/leckerekekse.de\/wordpress\/#\/schema\/person\/72061e7e8c1c70c8e8e542a13e5acbfe","name":"Astrid","logo":{"@id":"https:\/\/leckerekekse.de\/wordpress\/#\/schema\/person\/image\/"},"sameAs":["https:\/\/leckerekekse.de\/wordpress"]}]}},"_links":{"self":[{"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/posts\/7653","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/comments?post=7653"}],"version-history":[{"count":3,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/posts\/7653\/revisions"}],"predecessor-version":[{"id":16378,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/posts\/7653\/revisions\/16378"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/media\/7654"}],"wp:attachment":[{"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/media?parent=7653"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/categories?post=7653"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/tags?post=7653"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}