{"id":8794,"date":"2017-04-26T09:04:16","date_gmt":"2017-04-26T07:04:16","guid":{"rendered":"http:\/\/leckerekekse.de\/wordpress\/?p=8794"},"modified":"2017-04-23T10:06:11","modified_gmt":"2017-04-23T08:06:11","slug":"toni-morrison-gott-hilf-dem-kind-rezension","status":"publish","type":"post","link":"https:\/\/leckerekekse.de\/wordpress\/toni-morrison-gott-hilf-dem-kind-rezension\/","title":{"rendered":"Toni Morrison: Gott, hilf dem Kind, Rezension"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-8836\" src=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2017\/04\/Gott-hilf-dem-kind.jpg\" alt=\"Toni Morrsion: Gott, hilf dem Kind\" width=\"640\" height=\"462\" srcset=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2017\/04\/Gott-hilf-dem-kind.jpg 640w, https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2017\/04\/Gott-hilf-dem-kind-300x217.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<p>Die Hauptfigur von Tonis Morrisons neuem Roman ist Lula Ann Bridewell, genannt Bride. Und wie eine Braut tr\u00e4gt sie nur wei\u00df. Dies ergibt einen faszinierenden Kontrast zu ihrer sehr dunklen, schwarzblauen Haut.<\/p>\n<p>Bride ist sch\u00f6n, beliebt, alle M\u00e4nner liegen ihr zu F\u00fcssen, sie hat einen Traumjob in der Kosmetikbranche, ein tolles Auto (Jaguar) und ein sehr sch\u00f6nes Appartement in einer lebendigen Stadt. Au\u00dferdem noch Booker, ihr etwas geheimnisvoller, aber wundersch\u00f6ner Freund, mit dem sie seit einem halben Jahr zusammen ist.<\/p>\n<p>Doch eines Tages bricht alles zusammen: Booker verl\u00e4sst sie, Bride wird verpr\u00fcgelt, sie muss Urlaub nehmen, bis die Wunden verheilt sind.<\/p>\n<p>Doch Heilung erfahren nur die \u00e4u\u00dferlichen Narben. Innen ist sie die kleine Lula Ann, von niemandem geliebt, als h\u00e4sslich angesehen. Der einzige Tag, an dem ihre Mutter sie liebevoll an der Hand nimmt ist der, an dem Lula Ann vor Gericht als Zeugin f\u00fcr die Verurteilung einer Kinderg\u00e4rtnerin wegen Kindesmissbrauchs sorgt. <!--more--><\/p>\n<p>Der Roman bedient sich verschiedener Sichten.\u00a0 Da sind nat\u00fcrlich Bride und Booker. Au\u00dferdem Brooklyn, die einzige Brides einzige Freundin und Sweetness, Brides Mutter.<\/p>\n<h4>Sweetness<\/h4>\n<p>Diese Stimme der Mutter hatte f\u00fcr mich die gr\u00f6\u00dfte Eindringlichkeit. Mit ihr beginnt und endet der Roman. Somit beginnt und endet er auch damit jede Verantwortung f\u00fcr das Leben der eigenen Tochter abzulehnen. Der erste Satz des Buches lautet dann auch direkt:<\/p>\n<blockquote>\n<p style=\"text-align: center;\">Ich kann nichts daf\u00fcr.<\/p>\n<\/blockquote>\n<p>Der letzte:<\/p>\n<blockquote>\n<p style=\"text-align: center;\">Viel Gl\u00fcck, und Gott hilf dem Kind.<\/p>\n<\/blockquote>\n<p>Die Mutter lehnt jede Verantwortung f\u00fcr ihr eigenes Kind ab und \u00fcbertr\u00e4gt diese an eine h\u00f6here Instanz. Die harte, lieblose Erziehung rechtfertigt die Mutter damit, dass sie ihre Tochter so gesch\u00fctzt h\u00e4tte.<\/p>\n<p>\u201eSweetness\u201c: so muss die kleine Lula Ann ihre Mutter nennen, denn diese m\u00f6chte nicht daran erinnert werden, dass dieses Kind, mit der sehr dunklen Haut, ihr eigenes ist. Der Vater macht sich sofort aus dem Staub, \u00fcberzeugt, dass Lula Ann nicht von ihm stammt. Nicht, dass die Eltern Wei\u00dfe gewesen w\u00e4ren: sie waren nur so viel heller. Wie kann eine Mischung dann so dunkel ausfallen.<\/p>\n<h4>Rassismus<\/h4>\n<p>So ist eines der Themen dieses Buches der Rassismus innerhalb der Afroamerikanischen \u201eGemeinschaft\u201c. Es gilt: je heller, je besser. Somit zum Selbstverst\u00e4ndnis von \u201eSweetness\u201c. Und dies erf\u00e4hrt Lula Ann nicht nur durch die Eltern, sondern auch durch ihre restliche Umgebung, wie zum Beispiel ihre Mitsch\u00fcler. So bleibt sie immer einsam.<\/p>\n<p>Morrison legt Booker folgende Worte \u00fcber Rassismus in den Mund:<\/p>\n<blockquote><p>Wissenschaftlich betrachtet gibt es so was wie Rasse gar nicht, Bride, und ohne Rasse ist Rassismus nichts anderes als eine Wahl, die jemand trifft. Die nat\u00fcrlich vorgelebt wird, von denen, die es n\u00f6tig haben, aber es bleibt eine Wahl. Menschen, die diese Wahl treffen, w\u00e4ren das reine Nichts ohne sie.<\/p><\/blockquote>\n<h4><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-8837\" src=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2017\/04\/Gott-hilf-dem-kind-Toni-Morrison.jpg\" alt=\"Toni Morrsion: Gott, hilf dem Kind\" width=\"640\" height=\"320\" srcset=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2017\/04\/Gott-hilf-dem-kind-Toni-Morrison.jpg 640w, https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2017\/04\/Gott-hilf-dem-kind-Toni-Morrison-300x150.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/h4>\n<h4>Sch\u00f6nheit<\/h4>\n<blockquote><p>Ihre Farbe ist ein Kreuz, das sie immer zu tragen haben wird.<\/p><\/blockquote>\n<p>So denkt Sweetness \u00fcber ihre Tochter. Doch es kommt anders:<\/p>\n<p>Bride gilt als Sch\u00f6nheit. Sie l\u00e4sst sich professionell beraten, tr\u00e4gt nur noch wei\u00dfe Kleidung, die ihre dunkle Haut betont. Pl\u00f6tzlich ist sie wer. Kleider machen Leute: hier macht das unschuldige Wei\u00df selbstbewusst, auff\u00e4llig und somit sch\u00f6n. Die von der Mutter und der Umgebung in der Kindheit eingeimpften Selbstzweifel sind weg:<\/p>\n<blockquote><p>Die M\u00e4nner flogen auf mich, und ich lie\u00df sie landen. Eine ganze Weile jedenfalls, bis mein Liebesleben zu einer Art Cola Light wurde &#8211; t\u00e4uschend s\u00fc\u00df, aber ohne N\u00e4hrwert.<\/p><\/blockquote>\n<p>Wie fr\u00fcher, als sie noch das h\u00e4ssliche Entlein war, wird Bride auf ihr \u00c4u\u00dferes reduziert. Keiner interessiert sich f\u00fcr ihre Gedanken, Gef\u00fchle Probleme. Booker ist der erste, der ihr zuh\u00f6rt.<\/p>\n<h4>Metamorphose<\/h4>\n<p>Doch als sie von Booker verlassen wird, ver\u00e4ndert sich ihr K\u00f6rper. Als ob er ihr etwas gestohlen h\u00e4tte. Aus dem Schwan wird wieder ein K\u00fcken:<\/p>\n<p>\u201eMit flacher Brust, ohne Achsel- und Schamhaar, ohne Ohrl\u00f6cher oder stabiles Gewicht versuchte sie, und zwar vergeblich, das zu vergessen, was sie f\u00fcr ihre verr\u00fcckte R\u00fcckverwandlung in ein ver\u00e4ngstigtes kleines schwarzes M\u00e4dchen hielt.\u201c<\/p>\n<p>Wird sie ohne die Betrachtung durch Booker unsichtbar? Entzogene Liebe scheint noch schlimmer als das Fehlen der Mutterliebe zu sein.<\/p>\n<h4>Geschriebene Musik<\/h4>\n<p>Booker schreibt auch, Hingeworfene Skizzen ohne Punkt und Komma. Ein paar dieser Texte sind im Buch enthalten. In jedem dieser Texte kommt ein Musikinstrument vor. Musik ist ein weiteres Thema im Buch. Immer wieder wird gesungen, Platten gespielt, Booker spielt trompete. Musik ist hier immer ein Mittel Gef\u00fchle auszudr\u00fccken oder zu verarbeiten. Oft wird Jazz Musik erw\u00e4hnt, gespielt, beschreiben. So spannt Morrison einen Bogen zu fr\u00fcheren Werken, wie zum Beispiel Jazz.<\/p>\n<h4>Kindesmissbrauch<\/h4>\n<p>Ein Thema, das in viele Varianten im Buch auftaucht. Der Prozess, in dem Lula Ann als Kind aussagte, eine Situation, in der sie zur Beobachterin wurde, Bookers Bruder von einem P\u00e4derasten umgebracht, ein anderes M\u00e4dchen von der Mutter zur Prostitution gezwungen.<\/p>\n<p>Warum ist der Kindesmissbrauch im Buch allgegenw\u00e4rtig? Gibt es keine unbeschwerten Kindheiten? Warum wird gerade dieses Motiv so vielf\u00e4ltig in diesem Buch thematisiert? Ich kann das nicht wirklich einordnen.\u00a0 Dazu w\u00fcrde ich gerne die Autorin befragen.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-8835\" src=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2017\/04\/Toni-morrison-gott-hilf-dem-kind.jpg\" alt=\"Toni Morrsion: Gott, hilf dem Kind\" width=\"640\" height=\"320\" srcset=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2017\/04\/Toni-morrison-gott-hilf-dem-kind.jpg 640w, https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2017\/04\/Toni-morrison-gott-hilf-dem-kind-300x150.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<h4>Generationenkonflikt<\/h4>\n<p>Lula Ann hat Probleme mit ihrer Mutter, Booker hat sich von den Eltern losgesagt, seine geliebte Tante hat keinen Kontakt zu ihren unz\u00e4hligen Kindern. Die Welt ist im Umbruch, lese ich daraus.<\/p>\n<p>Jedes Kind ist Grund zur Hoffnung, das die Welt eine bessere werden wird.<\/p>\n<p>Eine passende Passage liest sich wie ein Gebet:<\/p>\n<p>\u201eEin Kind. Neues Leben. Immun gegen alles B\u00f6se, jede Krankheit, beh\u00fctet vor Entf\u00fchrung, Schl\u00e4gen, sexueller Gewalt, Rassismus, Dem\u00fctigung, Verletzung, Selbstzweifel, Verwahrlosung. Niemals irrend, voller G\u00fcte. Ohne Zorn.\u201c<\/p>\n<p>Dazu passt der (w\u00f6rtlich \u00fcbersetzte) Romantitel: \u201eGott, hilf dem Kind.\u201c Sollte f\u00fcr jedes Kind gelten, egal welche Schattierung die Haut hat.<\/p>\n<p>Noch besser ist: wir Eltern \u00fcbernehmen Verantwortung f\u00fcr unsere Kinder. F\u00fcr eine liebevolle Erziehung, die wichtige Werte vorlebt und weitergibt. In diesem Buch und in der ganzen Welt, zu jeder Zeit.<\/p>\n<h3>Fazit<\/h3>\n<p>So eine lange Rezension f\u00fcr ein doch eher d\u00fcnnes Buch. Dran merke ich, wie stark es mich beeindruckt hat.<\/p>\n<p>Die Literaturnobelpreistr\u00e4gerin Toni Morrison hat einen kurzen Roman mit viel Inhalt und Diskussionspotential vorgelegt. Ich habe ihn atemlos verschlungen und werde mit der Interpretation noch l\u00e4nger besch\u00e4ftigt sein.\u00a0 Der Stil ist meisterhaft. Ich staune, dass eine \u00e4ltere Dame (falls ich das so schreiben darf) ein so jung wirkendes Buch verfasst hat.<\/p>\n<h5><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-5977\" src=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2016\/04\/Signatur-002-300x219.jpg\" alt=\"\" width=\"300\" height=\"219\" srcset=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2016\/04\/Signatur-002-300x219.jpg 300w, https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2016\/04\/Signatur-002.jpg 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Infos zum Buch<\/h5>\n<table width=\"640\">\n<tbody>\n<tr>\n<td width=\"320\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-8684\" src=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2017\/04\/gott-hilf-dem-kind-toni-morrison-184x300.jpg\" alt=\"Toni Morrison: Gott, hilf dem Kind\" width=\"184\" height=\"300\" srcset=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2017\/04\/gott-hilf-dem-kind-toni-morrison-184x300.jpg 184w, https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2017\/04\/gott-hilf-dem-kind-toni-morrison.jpg 392w\" sizes=\"auto, (max-width: 184px) 100vw, 184px\" \/><\/td>\n<td width=\"320\">\n<p class=\"small\"><a href=\"https:\/\/www.rowohlt.de\/hardcover\/toni-morrison-gott-hilf-dem-kind.html\" target=\"_blank\" rel=\"noopener noreferrer\">Gott, hilf dem Kind<\/a><\/p>\n<p>Toni Morrison<\/p>\n<p>\u00dcbersetzt von Thomas Piltz<\/p>\n<p>Rowohlt Verlag<\/p>\n<p class=\"small\">208 Seiten, gebunden<\/p>\n<p>ISBN: 978-3-498-04531-9<\/p>\n<p class=\"small\">19,95 \u20ac [D], als Hardcover-Ausgabe<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>Die Hauptfigur von Tonis Morrisons neuem Roman ist Lula Ann Bridewell, genannt Bride. Und wie eine Braut tr\u00e4gt sie nur wei\u00df. Dies ergibt einen faszinierenden Kontrast zu ihrer sehr dunklen, schwarzblauen Haut. Bride ist sch\u00f6n, beliebt, alle M\u00e4nner liegen ihr zu F\u00fcssen, sie hat einen Traumjob in der Kosmetikbranche, ein tolles Auto (Jaguar) und ein [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":8836,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,3,788],"tags":[130,217,56,127,76],"class_list":["post-8794","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-buecher","category-rezension","tag-liebe","tag-missbrauch","tag-musik","tag-rassismus","tag-usa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Toni Morrison: &quot;Gott, hilf dem Kind&quot;, Rezension des Romans der Literaturnobelpreistr\u00e4gerin<\/title>\n<meta name=\"description\" content=\"Rezension des neuen Romans von Toni Morrison &quot;Gott, hilf dem Kind&quot;. Ein Roman \u00fcber die Situation von Afroamerikanern in den USA.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/leckerekekse.de\/wordpress\/toni-morrison-gott-hilf-dem-kind-rezension\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Toni Morrison: &quot;Gott, hilf dem Kind&quot;, Rezension des Romans der Literaturnobelpreistr\u00e4gerin\" \/>\n<meta property=\"og:description\" content=\"Rezension des neuen Romans von Toni Morrison &quot;Gott, hilf dem Kind&quot;. Ein Roman \u00fcber die Situation von Afroamerikanern in den USA.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/leckerekekse.de\/wordpress\/toni-morrison-gott-hilf-dem-kind-rezension\/\" \/>\n<meta property=\"og:site_name\" content=\"Leckere Kekse &amp; mehr\" \/>\n<meta property=\"article:published_time\" content=\"2017-04-26T07:04:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2017\/04\/Gott-hilf-dem-kind.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"462\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Buchlieberin\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Buchlieberin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"6\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/toni-morrison-gott-hilf-dem-kind-rezension\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/toni-morrison-gott-hilf-dem-kind-rezension\\\/\"},\"author\":{\"name\":\"Buchlieberin\",\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/2374d41b5cda28a27f6924e58f3afcc2\"},\"headline\":\"Toni Morrison: Gott, hilf dem Kind, Rezension\",\"datePublished\":\"2017-04-26T07:04:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/toni-morrison-gott-hilf-dem-kind-rezension\\\/\"},\"wordCount\":1123,\"commentCount\":14,\"publisher\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/72061e7e8c1c70c8e8e542a13e5acbfe\"},\"image\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/toni-morrison-gott-hilf-dem-kind-rezension\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/Gott-hilf-dem-kind.jpg\",\"keywords\":[\"Liebe\",\"Missbrauch\",\"Musik\",\"Rassismus\",\"USA\"],\"articleSection\":{\"1\":\"B\u00fccher\",\"2\":\"Rezension\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/toni-morrison-gott-hilf-dem-kind-rezension\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/toni-morrison-gott-hilf-dem-kind-rezension\\\/\",\"url\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/toni-morrison-gott-hilf-dem-kind-rezension\\\/\",\"name\":\"Toni Morrison: \\\"Gott, hilf dem Kind\\\", Rezension des Romans der Literaturnobelpreistr\u00e4gerin\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/toni-morrison-gott-hilf-dem-kind-rezension\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/toni-morrison-gott-hilf-dem-kind-rezension\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/Gott-hilf-dem-kind.jpg\",\"datePublished\":\"2017-04-26T07:04:16+00:00\",\"description\":\"Rezension des neuen Romans von Toni Morrison \\\"Gott, hilf dem Kind\\\". Ein Roman \u00fcber die Situation von Afroamerikanern in den USA.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/toni-morrison-gott-hilf-dem-kind-rezension\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/toni-morrison-gott-hilf-dem-kind-rezension\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/toni-morrison-gott-hilf-dem-kind-rezension\\\/#primaryimage\",\"url\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/Gott-hilf-dem-kind.jpg\",\"contentUrl\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/Gott-hilf-dem-kind.jpg\",\"width\":640,\"height\":462,\"caption\":\"Toni Morrsion: Gott, hilf dem Kind\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/toni-morrison-gott-hilf-dem-kind-rezension\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Toni Morrison: Gott, hilf dem Kind, Rezension\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#website\",\"url\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/\",\"name\":\"Leckere Kekse &amp; mehr\",\"description\":\"Kekse backen, B\u00fccher lesen und mehr\",\"publisher\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/72061e7e8c1c70c8e8e542a13e5acbfe\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/72061e7e8c1c70c8e8e542a13e5acbfe\",\"name\":\"Astrid\",\"logo\":{\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/leckerekekse.de\\\/wordpress\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/leckerekekse.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/2374d41b5cda28a27f6924e58f3afcc2\",\"name\":\"Buchlieberin\",\"sameAs\":[\"https:\\\/\\\/leckerekekse.de\\\/wordpress\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Toni Morrison: \"Gott, hilf dem Kind\", Rezension des Romans der Literaturnobelpreistr\u00e4gerin","description":"Rezension des neuen Romans von Toni Morrison \"Gott, hilf dem Kind\". Ein Roman \u00fcber die Situation von Afroamerikanern in den USA.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/leckerekekse.de\/wordpress\/toni-morrison-gott-hilf-dem-kind-rezension\/","og_locale":"de_DE","og_type":"article","og_title":"Toni Morrison: \"Gott, hilf dem Kind\", Rezension des Romans der Literaturnobelpreistr\u00e4gerin","og_description":"Rezension des neuen Romans von Toni Morrison \"Gott, hilf dem Kind\". Ein Roman \u00fcber die Situation von Afroamerikanern in den USA.","og_url":"https:\/\/leckerekekse.de\/wordpress\/toni-morrison-gott-hilf-dem-kind-rezension\/","og_site_name":"Leckere Kekse &amp; mehr","article_published_time":"2017-04-26T07:04:16+00:00","og_image":[{"width":640,"height":462,"url":"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2017\/04\/Gott-hilf-dem-kind.jpg","type":"image\/jpeg"}],"author":"Buchlieberin","twitter_misc":{"Verfasst von":"Buchlieberin","Gesch\u00e4tzte Lesezeit":"6\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/leckerekekse.de\/wordpress\/toni-morrison-gott-hilf-dem-kind-rezension\/#article","isPartOf":{"@id":"https:\/\/leckerekekse.de\/wordpress\/toni-morrison-gott-hilf-dem-kind-rezension\/"},"author":{"name":"Buchlieberin","@id":"https:\/\/leckerekekse.de\/wordpress\/#\/schema\/person\/2374d41b5cda28a27f6924e58f3afcc2"},"headline":"Toni Morrison: Gott, hilf dem Kind, Rezension","datePublished":"2017-04-26T07:04:16+00:00","mainEntityOfPage":{"@id":"https:\/\/leckerekekse.de\/wordpress\/toni-morrison-gott-hilf-dem-kind-rezension\/"},"wordCount":1123,"commentCount":14,"publisher":{"@id":"https:\/\/leckerekekse.de\/wordpress\/#\/schema\/person\/72061e7e8c1c70c8e8e542a13e5acbfe"},"image":{"@id":"https:\/\/leckerekekse.de\/wordpress\/toni-morrison-gott-hilf-dem-kind-rezension\/#primaryimage"},"thumbnailUrl":"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2017\/04\/Gott-hilf-dem-kind.jpg","keywords":["Liebe","Missbrauch","Musik","Rassismus","USA"],"articleSection":{"1":"B\u00fccher","2":"Rezension"},"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/leckerekekse.de\/wordpress\/toni-morrison-gott-hilf-dem-kind-rezension\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/leckerekekse.de\/wordpress\/toni-morrison-gott-hilf-dem-kind-rezension\/","url":"https:\/\/leckerekekse.de\/wordpress\/toni-morrison-gott-hilf-dem-kind-rezension\/","name":"Toni Morrison: \"Gott, hilf dem Kind\", Rezension des Romans der Literaturnobelpreistr\u00e4gerin","isPartOf":{"@id":"https:\/\/leckerekekse.de\/wordpress\/#website"},"primaryImageOfPage":{"@id":"https:\/\/leckerekekse.de\/wordpress\/toni-morrison-gott-hilf-dem-kind-rezension\/#primaryimage"},"image":{"@id":"https:\/\/leckerekekse.de\/wordpress\/toni-morrison-gott-hilf-dem-kind-rezension\/#primaryimage"},"thumbnailUrl":"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2017\/04\/Gott-hilf-dem-kind.jpg","datePublished":"2017-04-26T07:04:16+00:00","description":"Rezension des neuen Romans von Toni Morrison \"Gott, hilf dem Kind\". Ein Roman \u00fcber die Situation von Afroamerikanern in den USA.","breadcrumb":{"@id":"https:\/\/leckerekekse.de\/wordpress\/toni-morrison-gott-hilf-dem-kind-rezension\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/leckerekekse.de\/wordpress\/toni-morrison-gott-hilf-dem-kind-rezension\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/leckerekekse.de\/wordpress\/toni-morrison-gott-hilf-dem-kind-rezension\/#primaryimage","url":"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2017\/04\/Gott-hilf-dem-kind.jpg","contentUrl":"https:\/\/leckerekekse.de\/wordpress\/wp-content\/uploads\/2017\/04\/Gott-hilf-dem-kind.jpg","width":640,"height":462,"caption":"Toni Morrsion: Gott, hilf dem Kind"},{"@type":"BreadcrumbList","@id":"https:\/\/leckerekekse.de\/wordpress\/toni-morrison-gott-hilf-dem-kind-rezension\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/leckerekekse.de\/wordpress\/"},{"@type":"ListItem","position":2,"name":"Toni Morrison: Gott, hilf dem Kind, Rezension"}]},{"@type":"WebSite","@id":"https:\/\/leckerekekse.de\/wordpress\/#website","url":"https:\/\/leckerekekse.de\/wordpress\/","name":"Leckere Kekse &amp; mehr","description":"Kekse backen, B\u00fccher lesen und mehr","publisher":{"@id":"https:\/\/leckerekekse.de\/wordpress\/#\/schema\/person\/72061e7e8c1c70c8e8e542a13e5acbfe"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/leckerekekse.de\/wordpress\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/leckerekekse.de\/wordpress\/#\/schema\/person\/72061e7e8c1c70c8e8e542a13e5acbfe","name":"Astrid","logo":{"@id":"https:\/\/leckerekekse.de\/wordpress\/#\/schema\/person\/image\/"},"sameAs":["https:\/\/leckerekekse.de\/wordpress"]},{"@type":"Person","@id":"https:\/\/leckerekekse.de\/wordpress\/#\/schema\/person\/2374d41b5cda28a27f6924e58f3afcc2","name":"Buchlieberin","sameAs":["https:\/\/leckerekekse.de\/wordpress"]}]}},"_links":{"self":[{"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/posts\/8794","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/comments?post=8794"}],"version-history":[{"count":3,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/posts\/8794\/revisions"}],"predecessor-version":[{"id":8838,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/posts\/8794\/revisions\/8838"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/media\/8836"}],"wp:attachment":[{"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/media?parent=8794"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/categories?post=8794"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/leckerekekse.de\/wordpress\/wp-json\/wp\/v2\/tags?post=8794"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}